{"id":48172,"date":"2022-06-10T00:24:46","date_gmt":"2022-06-09T21:24:46","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=48172"},"modified":"2025-05-29T10:28:15","modified_gmt":"2025-05-29T07:28:15","slug":"was-sind-die-schaetze-der-finsternisjesaja-453","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/","title":{"rendered":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)"},"content":{"rendered":"\n\n\n<p><strong>Einleitung:<\/strong><br \/>In <em>Jesaja 45,3<\/em> spricht Gott durch den Propheten Jesaja zum persischen K\u00f6nig Kyros:<\/p>\n<blockquote>\n<p>\u201eIch will dir geben die Sch\u00e4tze, die im Finstern verborgen liegen, und die verborgenen Reicht\u00fcmer, damit du erkennst, dass ich der HERR bin, der dich bei deinem Namen ruft, der Gott Israels.\u201c<br \/><em>(Jesaja 45,3 \u2013 Lutherbibel 2017)<\/em><\/p>\n<\/blockquote>\n<p>Diese Verhei\u00dfung galt urspr\u00fcnglich einem heidnischen K\u00f6nig\u00a0 Kyros \u2013, den Gott dazu berufen hatte, Israel aus der babylonischen Gefangenschaft zu befreien. Doch wie viele Aussagen des Alten Testaments enth\u00e4lt auch dieser Vers eine geistliche Wahrheit, die bis heute f\u00fcr Gl\u00e4ubige gilt: Gott ist in der Lage, verborgene Segnungen, Chancen und Menschen ans Licht zu bringen, die bislang versteckt, aufgehalten oder vom Feind gefangen gehalten wurden.<\/p>\n<hr \/>\n<p><strong>Was bedeutet \u201eSch\u00e4tze der Finsternis\u201c?<\/strong><br \/>Im biblischen Sinn stehen die \u201eSch\u00e4tze der Finsternis\u201c f\u00fcr:<\/p>\n<ul>\n<li>\n<p>Geistliche, physische oder materielle Ressourcen, die verborgen sind.<\/p>\n<\/li>\n<li>\n<p>Segnungen, die durch geistliche Widerst\u00e4nde verz\u00f6gert wurden.<\/p>\n<\/li>\n<li>\n<p>Verborgene Weisheit und g\u00f6ttliche Strategien f\u00fcr Durchbr\u00fcche.<\/p>\n<\/li>\n<li>\n<p>Wiederherstellung dessen, was der Feind geraubt hat <em>(vgl. Joel 2,25\u201326)<\/em>.<\/p>\n<\/li>\n<\/ul>\n<p>Es geht hier nicht nur um materiellen Gewinn, sondern um Befreiung, neue M\u00f6glichkeiten, Beziehungen, Dienste und g\u00f6ttliche Erkenntnis.<\/p>\n<p><em>Jesaja 45,3<\/em> zeigt symbolisch, wie Gott Dinge, die im Dunkeln liegen, ans Licht bringt\u00a0 oft auf unerwartete Weise. So wie Kyros Zugang zu Babylons versteckten Sch\u00e4tzen erhielt, als Zeichen von Gottes Souver\u00e4nit\u00e4t, so kann Gott auch uns verborgene Segnungen offenbaren und wiederherstellen.<\/p>\n<hr \/>\n<p><strong>Biblisches Beispiel: Die Belagerung und die Beute (2. K\u00f6nige 7)<\/strong><br \/>In <em>2. K\u00f6nige 6\u20137<\/em> wird Israel von den Aram\u00e4ern belagert. Die Hungersnot war so schlimm, dass Menschen Eselsk\u00f6pfe und Taubenmist a\u00dfen (<em>2. K\u00f6nige 6,25<\/em>). Die Stadt war v\u00f6llig vom Nachschub abgeschnitten.<\/p>\n<p>Doch in Kapitel 7 greift Gott \u00fcbernat\u00fcrlich ein: Er l\u00e4sst die Aram\u00e4er das Ger\u00e4usch eines gro\u00dfen Heeres h\u00f6ren (V.6), woraufhin sie in Panik fliehen und ihre Vorr\u00e4te zur\u00fccklassen:<\/p>\n<blockquote>\n<p>\u201eDenn der HERR hatte das Heer der Aram\u00e4er h\u00f6ren lassen ein Ger\u00e4usch von Rossen und Wagen und ein gro\u00dfes Heer, sodass sie zueinander sprachen: Siehe, der K\u00f6nig von Israel hat die K\u00f6nige der Hetiter und die K\u00f6nige der \u00c4gypter gegen uns gedungen, dass sie \u00fcber uns kommen sollen.\u201c<br \/><em>(2. K\u00f6nige 7,6 \u2013 Lutherbibel 2017)<\/em><\/p>\n<\/blockquote>\n<p>Vier auss\u00e4tzige M\u00e4nner entdecken das verlassene Lager, nehmen von der Beute \u2013 und schlie\u00dflich wird die ganze Stadt gerettet.<\/p>\n<p>Dieses Wunder ist ein prophetisches Bild daf\u00fcr, wie Gott eingreifen kann, sodass unsere Feinde loslassen m\u00fcssen, was sie unrechtm\u00e4\u00dfig halten\u00a0 und wie Gott auf einmal T\u00fcren \u00f6ffnen kann. Die Sch\u00e4tze, die im Verborgenen lagen, wurden sichtbar und verf\u00fcgbar f\u00fcr Gottes Volk.<\/p>\n<hr \/>\n<p><strong>Anwendung f\u00fcr Gl\u00e4ubige heute<\/strong><br \/>Solche \u201eSch\u00e4tze der Finsternis\u201c k\u00f6nnen in deinem Leben sein:<\/p>\n<ul>\n<li>\n<p>Eine geistliche Berufung oder Gabe, die durch Angst oder Druck unterdr\u00fcckt wurde.<\/p>\n<\/li>\n<li>\n<p>Ein Familienmitglied, das in S\u00fcnde oder T\u00e4uschung gefangen ist.<\/p>\n<\/li>\n<li>\n<p>Finanzielle Versorgung, Heilung oder Wiederherstellung, die sich verz\u00f6gert hat.<\/p>\n<\/li>\n<li>\n<p>Geistliche Erweckung oder Frucht im Dienst, die lange unerreichbar schien.<\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<p><strong>Geistlicher Kampf und unsere Rolle<\/strong><br \/>Um das Verborgene wiederzuerlangen, m\u00fcssen wir geistlich k\u00e4mpfen \u2013 nicht mit irdischen Waffen, sondern mit den Waffen Gottes:<\/p>\n<blockquote>\n<p>\u201eDenn die Waffen unseres Kampfes sind nicht fleischlich, sondern m\u00e4chtig im Dienst Gottes, Festungen zu zerst\u00f6ren. Wir zerst\u00f6ren damit Gedanken und alles Hohe, das sich erhebt gegen die Erkenntnis Gottes, und nehmen gefangen alles Denken in den Gehorsam gegen Christus.\u201c<br \/><em>(2. Korinther 10,4\u20135 \u2013 Lutherbibel 2017)<\/em><\/p>\n<\/blockquote>\n<p>Vieles, was verborgen oder blockiert ist, unterliegt geistlichem Widerstand \u2013 wie im Fall von Daniel (<em>Daniel 10<\/em>), dessen Gebet durch d\u00e4monische M\u00e4chte verz\u00f6gert wurde.<\/p>\n<hr \/>\n<p><strong>Die Waffenr\u00fcstung Gottes (Epheser 6,10\u201318)<\/strong><br \/>Um in dieser Auseinandersetzung zu bestehen, brauchen wir die vollst\u00e4ndige Waffenr\u00fcstung Gottes:<\/p>\n<ul>\n<li>\n<p><strong>G\u00fcrtel der Wahrheit<\/strong> \u2013 Gottes Wort kennen und danach leben.<\/p>\n<\/li>\n<li>\n<p><strong>Brustpanzer der Gerechtigkeit<\/strong> \u2013 Durch Christus im rechten Verh\u00e4ltnis zu Gott stehen.<\/p>\n<\/li>\n<li>\n<p><strong>Schuhe der Bereitschaft f\u00fcr das Evangelium des Friedens<\/strong> \u2013 Die gute Nachricht leben und verk\u00fcnden.<\/p>\n<\/li>\n<li>\n<p><strong>Schild des Glaubens<\/strong> \u2013 Vertrauen, das die Angriffe des Feindes ausl\u00f6scht.<\/p>\n<\/li>\n<li>\n<p><strong>Helm des Heils<\/strong> \u2013 Gewissheit des Heils und Schutz f\u00fcr unsere Gedanken.<\/p>\n<\/li>\n<li>\n<p><strong>Schwert des Geistes<\/strong> \u2013 Das Wort Gottes, gesprochen mit Autorit\u00e4t.<\/p>\n<\/li>\n<li>\n<p><strong>Gebet<\/strong> \u2013 Die Kraftquelle, die alles in Bewegung setzt.<\/p>\n<\/li>\n<\/ul>\n<blockquote>\n<p>\u201eZieht an die Waffenr\u00fcstung Gottes, damit ihr bestehen k\u00f6nnt gegen die listigen Anschl\u00e4ge des Teufels.\u201c<br \/><em>(Epheser 6,11 \u2013 Lutherbibel 2017)<\/em><\/p>\n<\/blockquote>\n<hr \/>\n<p><strong>Die verborgenen Sch\u00e4tze ergreifen<\/strong><br \/>Gott hat Sch\u00e4tze und Reicht\u00fcmer im Verborgenen vorbereitet\u00a0 nicht, um sie uns vorzuenthalten, sondern um sie zur rechten Zeit offenbaren zu k\u00f6nnen, wenn wir treu danach streben.<\/p>\n<p>So wie Israel die Beute der Aram\u00e4er erhielt, sind auch wir berufen, das zu ergreifen, was geistlich unser ist\u00a0 durch Glauben, Gehorsam, Gebet und Ausdauer.<\/p>\n<blockquote>\n<p>\u201eIch will euch die Jahre erstatten, die die Heuschrecken gefressen haben&#8230; Und ihr sollt genug zu essen haben und satt werden und den Namen des HERRN, eures Gottes, loben.\u201c<br \/><em>(Joel 2,25\u201326 \u2013 Lutherbibel 2017)<\/em><\/p>\n<\/blockquote>\n<p>M\u00f6ge unser Herz mutig und entschlossen sein, all das zu ergreifen, was Gott f\u00fcr uns vorbereitet hat\u00a0 im Vertrauen darauf, dass das, was heute noch verborgen ist, morgen offenbar werden kann, durch Seine Kraft und zu Seiner Ehre.<\/p>\n<p><strong>Maranatha \u2013 Unser Herr kommt!<\/strong><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)' data-link='https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Einleitung:In Jesaja 45,3 spricht Gott durch den Propheten Jesaja zum persischen K\u00f6nig Kyros: \u201eIch will dir geben die Sch\u00e4tze, die im Finstern verborgen liegen, und die verborgenen Reicht\u00fcmer, damit du erkennst, dass ich der HERR bin, der dich bei deinem Namen ruft, der Gott Israels.\u201c(Jesaja 45,3 \u2013 Lutherbibel 2017) Diese Verhei\u00dfung galt urspr\u00fcnglich einem heidnischen [&hellip;]<\/p>\n","protected":false},"author":1198,"featured_media":48174,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-48172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pCE23PoPta\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/\">Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/embed\/#?secret=pCE23PoPta\" width=\"500\" height=\"350\" title=\"&#8222;Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"pCE23PoPta\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Einleitung:In Jesaja 45,3 spricht Gott durch den Propheten Jesaja zum persischen K\u00f6nig Kyros: \u201eIch will dir geben die Sch\u00e4tze, die im Finstern verborgen liegen, und die verborgenen Reicht\u00fcmer, damit du erkennst, dass ich der HERR bin, der dich bei deinem Namen ruft, der Gott Israels.\u201c(Jesaja 45,3 \u2013 Lutherbibel 2017) Diese Verhei\u00dfung galt urspr\u00fcnglich einem heidnischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T21:24:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T07:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rehema Jonathan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rehema Jonathan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/\"},\"author\":{\"name\":\"Rehema Jonathan\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\"},\"headline\":\"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)\",\"datePublished\":\"2022-06-09T21:24:46+00:00\",\"dateModified\":\"2025-05-29T07:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/\"},\"wordCount\":858,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/images-46.jpeg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/\",\"name\":\"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/images-46.jpeg\",\"datePublished\":\"2022-06-09T21:24:46+00:00\",\"dateModified\":\"2025-05-29T07:28:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/images-46.jpeg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/images-46.jpeg\",\"width\":701,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/06\\\/10\\\/was-sind-die-schaetze-der-finsternisjesaja-453\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\",\"name\":\"Rehema Jonathan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"caption\":\"Rehema Jonathan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/","og_locale":"de_DE","og_type":"article","og_title":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title","og_description":"Einleitung:In Jesaja 45,3 spricht Gott durch den Propheten Jesaja zum persischen K\u00f6nig Kyros: \u201eIch will dir geben die Sch\u00e4tze, die im Finstern verborgen liegen, und die verborgenen Reicht\u00fcmer, damit du erkennst, dass ich der HERR bin, der dich bei deinem Namen ruft, der Gott Israels.\u201c(Jesaja 45,3 \u2013 Lutherbibel 2017) Diese Verhei\u00dfung galt urspr\u00fcnglich einem heidnischen [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2022-06-09T21:24:46+00:00","article_modified_time":"2025-05-29T07:28:15+00:00","og_image":[{"width":701,"height":438,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","type":"image\/jpeg"}],"author":"Rehema Jonathan","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rehema Jonathan","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/"},"author":{"name":"Rehema Jonathan","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c"},"headline":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)","datePublished":"2022-06-09T21:24:46+00:00","dateModified":"2025-05-29T07:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/"},"wordCount":858,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/","url":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/","name":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3) &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","datePublished":"2022-06-09T21:24:46+00:00","dateModified":"2025-05-29T07:28:15+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/06\/images-46.jpeg","width":701,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/06\/10\/was-sind-die-schaetze-der-finsternisjesaja-453\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"Was sind die Sch\u00e4tze der Finsternis?(Jesaja 45,3)"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c","name":"Rehema Jonathan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","caption":"Rehema Jonathan"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/48172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=48172"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/48172\/revisions"}],"predecessor-version":[{"id":48175,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/48172\/revisions\/48175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/48174"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=48172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=48172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=48172"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=48172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}