{"id":49125,"date":"2021-06-17T10:26:47","date_gmt":"2021-06-17T07:26:47","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=49125"},"modified":"2025-06-04T00:49:12","modified_gmt":"2025-06-03T21:49:12","slug":"die-verheissung-des-heiligen-geistes-fuer-unsere-zeit","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/","title":{"rendered":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT"},"content":{"rendered":"<p>Das Wirken des Heiligen Geistes in der heutigen Zeit zu verstehen, ist f\u00fcr viele Christen ebenso herausfordernd, wie es f\u00fcr die Juden zur Zeit Jesu war, den vollen Umfang seines Dienstes zu begreifen. Die Juden erwarteten den Messias vor allem als politischen K\u00f6nig und konzentrierten sich auf Stellen wie:<\/p>\n<blockquote><p><strong>Jesaja 9,5 (LUT 2017):<\/strong><br \/>\n<em>\u201eDenn uns ist ein Kind geboren, ein Sohn ist uns gegeben, und die Herrschaft ruht auf seiner Schulter\u2026\u201c<\/em><\/p><\/blockquote>\n<p>Dabei \u00fcbersahen sie andere entscheidende Prophetien. Als Jesus als leidender Knecht kam \u2013 das Lamm Gottes, das die S\u00fcnde der Welt wegnimmt (vgl. Jesaja 53) \u2013 erkannten sie seine tiefere Bestimmung nicht und verwarfen ihn als Messias (vgl. Johannes 1,11).<\/p>\n<p>Wir Gl\u00e4ubigen verstehen heute, dass der Messias letztlich in Herrlichkeit herrschen wird wie David (vgl. 2. Samuel 7,12\u201316) und Erl\u00f6sung von geistlichen Feinden bringt.<\/p>\n<p>In \u00e4hnlicher Weise wird der Heilige Geist von vielen Christen heute fast ausschlie\u00dflich mit dem Reden in Zungen (Glossolalie) verbunden, w\u00e4hrend andere Aspekte seines Wirkens in der Gemeinde oft \u00fcbersehen werden. Der Heilige Geist ist jedoch nicht auf eine einzige Manifestation beschr\u00e4nkt. Gerade in der Endzeit wirkt Er auf vielf\u00e4ltige Weise in der Gemeinde.<\/p>\n<p>Heute wollen wir das umfassende Wirken des Heiligen Geistes betrachten, insbesondere sein Handeln in der letzten Phase der Gemeindezeit.<\/p>\n<hr \/>\n<h3><strong>Die sieben Geister Gottes<\/strong><\/h3>\n<blockquote><p><strong>Offenbarung 1,4 (E\u00dc):<\/strong><br \/>\n<em>\u201eGnade sei mit euch und Friede von dem, der ist und der war und der kommt, und von den sieben Geistern, die vor seinem Thron sind\u2026\u201c<\/em><\/p><\/blockquote>\n<p>Die \u201esieben Geister\u201c werden oft missverstanden. Gott ist Geist (Johannes 4,24) und hat einen Heiligen Geist. Doch diese Stelle steht symbolisch f\u00fcr die siebenfachen Aspekte oder Dienste des Heiligen Geistes \u2013 die F\u00fclle seines Wirkens (vgl. Jesaja 11,2), wo vom Geist des HERRN gesprochen wird, mit den Eigenschaften: Weisheit, Einsicht, Rat, St\u00e4rke, Erkenntnis, Furcht des HERRN und Freude an der Gottesfurcht.<\/p>\n<p>Diese sieben Geister korrespondieren mit den sieben Gemeinden in Offenbarung Kapitel 2 und 3 und stehen zugleich f\u00fcr sieben Epochen der Kirchengeschichte. Biblisch gesehen befinden wir uns heute in der siebten und letzten Gemeindezeit: <strong>Laodizea<\/strong> (Offenbarung 3,14\u201322), die etwa im Jahr 1906 begann \u2013 zeitgleich mit den Pfingst- und Charismatischen Bewegungen.<\/p>\n<p>Der siebte Geist steht f\u00fcr die letzte Ausgie\u00dfung des Heiligen Geistes vor der Wiederkunft Christi.<\/p>\n<hr \/>\n<h3><strong>Der Erste und der Letzte: Bedeutung und Kraft<\/strong><\/h3>\n<p>In der Bibel haben der Anfang und das Ende eines Prozesses oft besondere Bedeutung \u2013 sei es das Fundament und der Abschluss eines Bauwerks oder der Anfang und das Ziel eines Laufs (vgl. Hebr\u00e4er 12,1\u20132). Auch das Wirken des Heiligen Geistes war an Pfingsten m\u00e4chtig (erste Gemeinde) und wird es in der Zeit Laodizeas wieder sein \u2013 jedoch auf einzigartige und intensivierte Weise.<\/p>\n<p>Die erste Gemeinde erlebte gro\u00dfe Zeichen und Wunder (Apostelgeschichte 2,1\u20134; 19,11\u201312). Doch nach dem apostolischen Zeitalter gingen viele dieser Gaben zur\u00fcck, da der Geist Gottes anders in den Epochen wirkte (vgl. 1. Korinther 13,8\u201310). In der Kirchengeschichte traten viele Gaben scheinbar in den Hintergrund.<\/p>\n<hr \/>\n<h3><strong>Die Wiederherstellung der Gaben<\/strong><\/h3>\n<p>In Laodizea \u2013 beginnend um 1906 \u2013 sehen wir eine Wiederherstellung apostolischer Gaben und Vollmacht: Prophetie, Heilung, Zungenrede und Wunder. Dies markiert das erneute Wirken des siebenf\u00e4ltigen Geistes und bereitet die Gemeinde auf die letzte Phase seines Wirkens vor (vgl. Epheser 4,11\u201313).<\/p>\n<p>Gleichzeitig bringt diese Erweckung auch Verwirrung, falsche Propheten und den Missbrauch geistlicher Gaben zum eigenen Vorteil mit sich (vgl. 2. Petrus 2,1\u20133). Deshalb ist Unterscheidung gefragt.<\/p>\n<hr \/>\n<h3><strong>Die besondere Ausgie\u00dfung auf treue Knechte<\/strong><\/h3>\n<p>Ein entscheidender Unterschied findet sich in:<\/p>\n<blockquote><p><strong>Joel 3,1\u20133 (LUT 2017; entspricht Joel 2,28\u201330 in englischer Z\u00e4hlung):<\/strong><br \/>\n<em>\u201eUnd danach will ich meinen Geist ausgie\u00dfen \u00fcber alles Fleisch; und eure S\u00f6hne und T\u00f6chter sollen weissagen, eure Alten sollen Tr\u00e4ume haben, und eure jungen M\u00e4nner sollen Gesichte sehen. Auch will ich zur selben Zeit \u00fcber Knechte und M\u00e4gde meinen Geist ausgie\u00dfen. Und ich will Wunderzeichen geben am Himmel und auf Erden: Blut, Feuer und Rauchdampf.\u201c<\/em><\/p><\/blockquote>\n<p>Gott verhei\u00dft hier eine allgemeine Ausgie\u00dfung des Geistes auf alle Gl\u00e4ubigen \u2013 mit Prophetie, Tr\u00e4umen und Visionen. Diese Ausgie\u00dfung gilt allen, die glauben.<\/p>\n<p>Doch es wird auch eine <strong>besondere, \u00fcbernat\u00fcrliche Ausgie\u00dfung<\/strong> auf <strong>treue Knechte und M\u00e4gde<\/strong> geben \u2013 M\u00e4nner und Frauen, die durch Wunder und Zeichen die Welt auf das Kommen des Herrn vorbereiten. Diese zweite Ausgie\u00dfung ist durch beispiellose Erscheinungen gekennzeichnet, wie sie zuletzt zu Zeiten von Mose und Elia auftraten (vgl. 2. Mose 7\u201311; 2. K\u00f6nige 2).<\/p>\n<hr \/>\n<h3><strong>Der Zweck dieser Zeichen<\/strong><\/h3>\n<p>Diese Zeichen dienen <strong>nicht<\/strong> dem Ruhm oder Gewinn, wie es bei falschen Propheten oft der Fall ist (vgl. Matth\u00e4us 7,15\u201320; 2. Korinther 11,13\u201315), sondern sie sollen:<\/p>\n<ul>\n<li>Die Gegenwart Gottes mit seinen treuen Dienern best\u00e4tigen<\/li>\n<li>Den wahren \u00dcberrest der Gl\u00e4ubigen aus Verwirrung und Irrlehre zur\u00fcckrufen<\/li>\n<li>Den Weg f\u00fcr die baldige Wiederkunft Christi bereiten<\/li>\n<\/ul>\n<p><strong>Bist du gerettet? Bist du einer von Gottes treuen Dienern, bereit, diese besondere Ausgie\u00dfung zu empfangen?<\/strong><\/p>\n<p>Die Zeit ist nahe. Diene dem Herrn heute in Treue, damit du, wenn diese letzte Ausgie\u00dfung kommt und du noch lebst, Teil dieses m\u00e4chtigen Wirkens bist. Wir sind berufen, Gott mit den Gaben zu dienen, die er uns gegeben hat (vgl. 1. Petrus 4,10\u201311).<\/p>\n<p><strong>Lasst uns den Heiligen Geist ernstlich suchen und unser Leben seinem Plan unterordnen \u2013 damit Gottes Wille auf Erden geschehe.<\/strong><\/p>\n<p><strong>Shalom.<\/strong><\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT' data-link='https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Das Wirken des Heiligen Geistes in der heutigen Zeit zu verstehen, ist f\u00fcr viele Christen ebenso herausfordernd, wie es f\u00fcr die Juden zur Zeit Jesu war, <\/p>\n","protected":false},"author":1198,"featured_media":49126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-49125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"yeaCO6b80g\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/\">DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/embed\/#?secret=yeaCO6b80g\" width=\"500\" height=\"350\" title=\"&#8222;DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"yeaCO6b80g\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Das Wirken des Heiligen Geistes in der heutigen Zeit zu verstehen, ist f\u00fcr viele Christen ebenso herausfordernd, wie es f\u00fcr die Juden zur Zeit Jesu war,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T07:26:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T21:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rehema Jonathan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rehema Jonathan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/\"},\"author\":{\"name\":\"Rehema Jonathan\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\"},\"headline\":\"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT\",\"datePublished\":\"2021-06-17T07:26:47+00:00\",\"dateModified\":\"2025-06-03T21:49:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/\"},\"wordCount\":862,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/menorah.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/\",\"name\":\"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/menorah.jpg\",\"datePublished\":\"2021-06-17T07:26:47+00:00\",\"dateModified\":\"2025-06-03T21:49:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/menorah.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/menorah.jpg\",\"width\":299,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/06\\\/17\\\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\",\"name\":\"Rehema Jonathan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"caption\":\"Rehema Jonathan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/","og_locale":"de_DE","og_type":"article","og_title":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title","og_description":"Das Wirken des Heiligen Geistes in der heutigen Zeit zu verstehen, ist f\u00fcr viele Christen ebenso herausfordernd, wie es f\u00fcr die Juden zur Zeit Jesu war,","og_url":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2021-06-17T07:26:47+00:00","article_modified_time":"2025-06-03T21:49:12+00:00","og_image":[{"width":299,"height":168,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","type":"image\/jpeg"}],"author":"Rehema Jonathan","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rehema Jonathan","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/"},"author":{"name":"Rehema Jonathan","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c"},"headline":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT","datePublished":"2021-06-17T07:26:47+00:00","dateModified":"2025-06-03T21:49:12+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/"},"wordCount":862,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/","url":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/","name":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","datePublished":"2021-06-17T07:26:47+00:00","dateModified":"2025-06-03T21:49:12+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/06\/menorah.jpg","width":299,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/06\/17\/die-verheissung-des-heiligen-geistes-fuer-unsere-zeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"DIE VERHEISSUNG DES HEILIGEN GEISTES F\u00dcR UNSERE ZEIT"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c","name":"Rehema Jonathan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","caption":"Rehema Jonathan"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/49125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=49125"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/49125\/revisions"}],"predecessor-version":[{"id":49127,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/49125\/revisions\/49127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/49126"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=49125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=49125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=49125"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=49125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}