{"id":51026,"date":"2022-08-15T13:04:48","date_gmt":"2022-08-15T10:04:48","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=51026"},"modified":"2025-06-19T23:43:24","modified_gmt":"2025-06-19T20:43:24","slug":"verstehen-von-bundnissen-in-der-bibel-ein-theologischer-ueberblick","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2022\/08\/15\/verstehen-von-bundnissen-in-der-bibel-ein-theologischer-ueberblick\/","title":{"rendered":"Verstehen von Bundnissen in der Bibel: Ein theologischer \u00dcberblick"},"content":{"rendered":"<div class=\"flex basis-auto flex-col -mb-(--composer-overlap-px) [--composer-overlap-px:24px] grow overflow-hidden\">\n<div class=\"relative h-full\">\n<div class=\"flex h-full flex-col overflow-y-auto [scrollbar-gutter:stable_both-edges] @[84rem]\/thread:pt-(--header-height)\">\n<div class=\"@thread-xl\/thread:pt-header-height mt-1.5 flex flex-col text-sm keyboard-open:pb-[calc(var(--composer-height,100px)+var(--screen-keyboard-height,0))] pb-25\">\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"18c61982-0aee-4c1a-b5d5-8d8cd81ad66d\" data-message-model-slug=\"gpt-4-1-mini\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark\">\n<p data-start=\"138\" data-end=\"208\">\n<p data-start=\"210\" data-end=\"680\"><strong data-start=\"210\" data-end=\"231\">Was ist ein Bund?<\/strong><br data-start=\"231\" data-end=\"234\" \/>Ein Bund ist eine feierliche, verbindliche Vereinbarung zwischen zwei Parteien. In der biblischen Theologie stehen Bundnisse im Zentrum von Gottes Beziehung zu den Menschen. Sie k\u00f6nnen bedingt sein (abh\u00e4ngig von menschlicher Antwort) oder unbedingte Zusagen, die allein von Gottes Versprechen getragen werden. Die Bibel offenbart sieben Hauptarten von Bundnissen, die sowohl die g\u00f6ttliche Initiative als auch die menschliche Verantwortung zeigen.<\/p>\n<hr data-start=\"682\" data-end=\"685\" \/>\n<h3 data-start=\"687\" data-end=\"727\">1. Bund zwischen Mensch und Mensch<\/h3>\n<p data-start=\"728\" data-end=\"927\">Diese Art von Bund ist eine gegenseitige Vereinbarung zwischen Personen. Sie kann Versprechen, Eide oder Verpflichtungen umfassen, die von beiden Seiten gehalten werden, manchmal mit Gott als Zeugen.<\/p>\n<p data-start=\"929\" data-end=\"973\">Beispiel: Jakob und Laban (1. Mose 31,43\u201350)<\/p>\n<blockquote data-start=\"975\" data-end=\"1129\">\n<p data-start=\"977\" data-end=\"1129\">\u201eKomm, lass uns einen Bund schlie\u00dfen, du und ich, und er sei zwischen uns Zeuge.\u201c Da nahm Jakob einen Stein und setzte ihn auf als eine S\u00e4ule. (V.44-45)<\/p>\n<\/blockquote>\n<p data-start=\"1131\" data-end=\"1305\">Dieser Bund war eine Familienvereinbarung \u00fcber Ehe und Eigentum. Ein weiteres wichtiges Beispiel ist die Ehe, die biblisch gesehen ein Bund vor Gott ist (vgl. Maleachi 2,14).<\/p>\n<p data-start=\"1307\" data-end=\"1585\"><strong data-start=\"1307\" data-end=\"1333\">Theologischer Hinweis:<\/strong><br data-start=\"1333\" data-end=\"1336\" \/>Zwischenmenschliche Bundnisse spiegeln oft g\u00f6ttliche Prinzipien wie Verpflichtung, Treue und Verantwortlichkeit wider. Das Brechen solcher Bundnisse, besonders der Ehe, gilt als S\u00fcnde und kann g\u00f6ttliche Konsequenzen nach sich ziehen (Matth\u00e4us 19,6).<\/p>\n<hr data-start=\"1587\" data-end=\"1590\" \/>\n<h3 data-start=\"1592\" data-end=\"1632\">2. Bund zwischen Mensch und Objekt<\/h3>\n<p data-start=\"1633\" data-end=\"1813\">Dies sind symbolische oder pers\u00f6nliche Verpflichtungen, die den menschlichen Willen betreffen. Hier bindet sich eine Person an einen Verhaltenskodex oder eine geistliche Disziplin.<\/p>\n<p data-start=\"1815\" data-end=\"1857\">Beispiel: Hiob und seine Augen (Hiob 31,1)<\/p>\n<blockquote data-start=\"1859\" data-end=\"1955\">\n<p data-start=\"1861\" data-end=\"1955\">\u201eIch habe mit meinen Augen einen Bund geschlossen; wie k\u00f6nnte ich dann eine Jungfrau ansehen?\u201c<\/p>\n<\/blockquote>\n<p data-start=\"1957\" data-end=\"2217\"><strong data-start=\"1957\" data-end=\"1983\">Theologischer Hinweis:<\/strong><br data-start=\"1983\" data-end=\"1986\" \/>Dies steht f\u00fcr pers\u00f6nliche Heiligung und einen Bund der Reinheit. Es verbindet sich mit den neutestamentlichen Aufforderungen, den K\u00f6rper zu disziplinieren (1. Korinther 9,27) und ihn als lebendiges Opfer darzubringen (R\u00f6mer 12,1).<\/p>\n<hr data-start=\"2219\" data-end=\"2222\" \/>\n<h3 data-start=\"2224\" data-end=\"2263\">3. Bund zwischen Mensch und Satan<\/h3>\n<p data-start=\"2264\" data-end=\"2428\">Ein geistlicher Bund, der wissentlich oder unwissentlich mit d\u00e4monischen M\u00e4chten geschlossen wird. Solche Vereinbarungen sind G\u00f6tzendienst und vor Gott abscheulich.<\/p>\n<p data-start=\"2430\" data-end=\"2487\">Beispiel: Verbot des heidnischen Kults (2. Mose 23,32\u201333)<\/p>\n<blockquote data-start=\"2489\" data-end=\"2648\">\n<p data-start=\"2491\" data-end=\"2648\">\u201eDu sollst keinen Bund mit ihnen und ihren G\u00f6ttern schlie\u00dfen. Sie sollen nicht in deinem Land wohnen, damit sie dich nicht zur S\u00fcnde gegen mich verleiten&#8230;\u201c<\/p>\n<\/blockquote>\n<p data-start=\"2650\" data-end=\"2934\"><strong data-start=\"2650\" data-end=\"2676\">Theologischer Hinweis:<\/strong><br data-start=\"2676\" data-end=\"2679\" \/>Solche Bundnisse f\u00fchren zur geistlichen Knechtschaft. Sie k\u00f6nnen aus G\u00f6tzendienst, okkulten Praktiken oder generationen\u00fcbergreifenden Traditionen stammen (5. Mose 18,10\u201312). Die Befreiung durch Christus ist notwendig, um sie zu brechen (Kolosser 1,13\u201314).<\/p>\n<hr data-start=\"2936\" data-end=\"2939\" \/>\n<h3 data-start=\"2941\" data-end=\"2979\">4. Bund zwischen Mensch und Gott<\/h3>\n<p data-start=\"2980\" data-end=\"3122\">Dies ist ein menschlich initiierter Bund als Antwort auf Gottes Gnade oder Gebot. Oft wird er durch Umkehr, Gehorsam oder Hingabe geschlossen.<\/p>\n<p data-start=\"3124\" data-end=\"3175\">Beispiel: Israels Erneuerung des Bundes (Esra 10,3)<\/p>\n<blockquote data-start=\"3177\" data-end=\"3302\">\n<p data-start=\"3179\" data-end=\"3302\">\u201eLasst uns einen Bund mit unserem Gott schlie\u00dfen, alle diese Frauen und ihre Kinder wegzutun, nach dem Rat meines Herrn&#8230;\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3304\" data-end=\"3501\"><strong data-start=\"3304\" data-end=\"3330\">Theologischer Hinweis:<\/strong><br data-start=\"3330\" data-end=\"3333\" \/>Obwohl menschlich begonnen, m\u00fcssen solche Bundnisse mit Gottes Willen und Wort \u00fcbereinstimmen. Sie zeigen Teshuvah, echte Umkehr und Hingabe zur Heiligung (R\u00f6mer 12,2).<\/p>\n<hr data-start=\"3503\" data-end=\"3506\" \/>\n<h3 data-start=\"3508\" data-end=\"3546\">5. Bund zwischen Gott und Mensch<\/h3>\n<p data-start=\"3547\" data-end=\"3712\">Dies ist ein g\u00f6ttlicher Bund, der von Gott initiiert und aufrechterhalten wird. Oft unbedingte Zusagen, die Gottes souver\u00e4nen Willen und Erl\u00f6sungsplan widerspiegeln.<\/p>\n<p data-start=\"3714\" data-end=\"3757\">Beispiel: Der Abrahamsbund (1. Mose 17,1\u20139)<\/p>\n<blockquote data-start=\"3759\" data-end=\"3919\">\n<p data-start=\"3761\" data-end=\"3919\">\u201eIch will meinen Bund errichten zwischen mir und dir und deinen Nachkommen nach dir&#8230; ich will dein Gott sein und der Gott deiner Nachkommen nach dir.\u201c (V.7)<\/p>\n<\/blockquote>\n<p data-start=\"3921\" data-end=\"4139\"><strong data-start=\"3921\" data-end=\"3947\">Theologischer Hinweis:<\/strong><br data-start=\"3947\" data-end=\"3950\" \/>Dieser Bund ist grundlegend f\u00fcr die biblische Geschichte. Er f\u00fchrt die Begriffe von Erw\u00e4hlung, Erbe und Rechtfertigung durch Glauben ein (Galater 3,6\u20139) und weist auf das Evangelium voraus.<\/p>\n<hr data-start=\"4141\" data-end=\"4144\" \/>\n<h3 data-start=\"4146\" data-end=\"4191\">6. Bund zwischen Gott und der Sch\u00f6pfung<\/h3>\n<p data-start=\"4192\" data-end=\"4384\">Gott hat auch Bundnisse mit seiner Sch\u00f6pfung geschlossen, sowohl mit Lebendigem als auch mit Unbelebtem. Sie zeigen seine Autorit\u00e4t als Sch\u00f6pfer und seine Barmherzigkeit gegen\u00fcber allem Leben.<\/p>\n<p data-start=\"4386\" data-end=\"4428\">Beispiel: Noahischer Bund (1. Mose 9,9\u201317)<\/p>\n<blockquote data-start=\"4430\" data-end=\"4623\">\n<p data-start=\"4432\" data-end=\"4623\">\u201eIch richte meinen Bund auf mit euch&#8230; nie wieder soll alles Fleisch durchs Wasser der Sintflut umkommen&#8230;<br data-start=\"4540\" data-end=\"4543\" \/>Ich habe meinen Bogen in die Wolken gesetzt als Zeichen des Bundes.\u201c (V.11\u201313)<\/p>\n<\/blockquote>\n<p data-start=\"4625\" data-end=\"4847\"><strong data-start=\"4625\" data-end=\"4651\">Theologischer Hinweis:<\/strong><br data-start=\"4651\" data-end=\"4654\" \/>Dieser universelle Bund zeigt Gottes allgemeine Gnade und seine G\u00fcte allen Kreaturen gegen\u00fcber (Matth\u00e4us 5,45). Der Regenbogen ist ein sakramentales Zeichen von Gottes Barmherzigkeit und Treue.<\/p>\n<hr data-start=\"4849\" data-end=\"4852\" \/>\n<h3 data-start=\"4854\" data-end=\"4913\">7. Bund zwischen Gott und seinem Sohn (Der Neue Bund)<\/h3>\n<p data-start=\"4914\" data-end=\"5086\">Dies ist der m\u00e4chtigste und letzte Bund, geschlossen zwischen Gott, dem Vater, und Gott, dem Sohn, erf\u00fcllt durch Jesu Tod und Auferstehung. Er ist in seinem Blut besiegelt.<\/p>\n<p data-start=\"5088\" data-end=\"5099\">Lukas 22,20<\/p>\n<blockquote data-start=\"5101\" data-end=\"5180\">\n<p data-start=\"5103\" data-end=\"5180\">\u201eDieser Kelch ist der neue Bund in meinem Blut, das f\u00fcr euch vergossen wird.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"5182\" data-end=\"5195\">Hebr\u00e4er 12,24<\/p>\n<blockquote data-start=\"5197\" data-end=\"5315\">\n<p data-start=\"5199\" data-end=\"5315\">\u201e&#8230;zu Jesus, dem Mittler eines neuen Bundes, und zu dem Blut der Besprengung, das besser redet als das Blut Abels.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"5317\" data-end=\"5558\"><strong data-start=\"5317\" data-end=\"5343\">Theologischer Hinweis:<\/strong><br data-start=\"5343\" data-end=\"5346\" \/>Dieser Bund ist ewig (Hebr\u00e4er 13,20) und bietet Heilung aus Gnade durch Glauben (Epheser 2,8\u20139). Er ersetzt den alten mosaischen Bund und erf\u00fcllt die Verhei\u00dfung eines neuen Herzens und Geistes (Jeremia 31,31\u201334).<\/p>\n<p data-start=\"5560\" data-end=\"5692\">Er hat auch die Kraft, jeden d\u00e4monischen oder s\u00fcndhaften Bund zu brechen und Menschen zu befreien (Johannes 8,36; Kolosser 2,14\u201315).<\/p>\n<hr data-start=\"5694\" data-end=\"5697\" \/>\n<p data-start=\"5699\" data-end=\"5918\"><strong data-start=\"5699\" data-end=\"5748\">Fazit: Bist du in den Neuen Bund eingetreten?<\/strong><br data-start=\"5748\" data-end=\"5751\" \/>Durch das Blut Jesu bietet Gott ewiges Leben, Vergebung und eine wiederhergestellte Beziehung zu sich selbst. Die T\u00fcr der Gnade steht noch offen, aber nicht f\u00fcr immer.<\/p>\n<ol start=\"2\" data-start=\"5920\" data-end=\"5933\">\n<li data-start=\"5920\" data-end=\"5933\">\n<p data-start=\"5923\" data-end=\"5933\">Petrus 3,7<\/p>\n<\/li>\n<\/ol>\n<blockquote data-start=\"5935\" data-end=\"6036\">\n<p data-start=\"5937\" data-end=\"6036\">\u201eDurch dasselbe Wort werden Himmel und Erde aufbewahrt f\u00fcr das Feuer zum Gericht am letzten Tag&#8230;\u201c<\/p>\n<\/blockquote>\n<p data-start=\"6038\" data-end=\"6216\"><strong data-start=\"6038\" data-end=\"6049\">Aufruf:<\/strong><br data-start=\"6049\" data-end=\"6052\" \/>Wenn du noch nicht durch den Glauben an Jesus Christus in den Neuen Bund eingetreten bist, z\u00f6gere nicht l\u00e4nger. Sein Blut spricht Barmherzigkeit, Erl\u00f6sung und Sieg.<\/p>\n<p data-start=\"6218\" data-end=\"6238\">Der Herr segne dich.<\/p>\n<hr data-start=\"6240\" data-end=\"6243\" \/>\n<p data-start=\"6245\" data-end=\"6349\" data-is-last-node=\"\" data-is-only-node=\"\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"flex min-h-[46px] justify-start\">\n<div class=\"touch:-me-2 touch:-ms-3.5 -ms-2.5 -me-1 flex flex-wrap items-center gap-y-4 p-1 select-none touch:w-[calc(100%+--spacing(3.5))] -mt-1 w-[calc(100%+--spacing(2.5))] duration-[1.5s] focus-within:transition-none hover:transition-none pointer-events-none [mask-image:linear-gradient(to_right,black_33%,transparent_66%)] [mask-size:300%_100%] [mask-position:100%_0%] motion-safe:transition-[mask-position] group-hover\/turn-messages:pointer-events-auto group-hover\/turn-messages:[mask-position:0_0] group-focus-within\/turn-messages:pointer-events-auto group-focus-within\/turn-messages:[mask-position:0_0] has-data-[state=open]:pointer-events-auto has-data-[state=open]:[mask-position:0_0]\"><button class=\"text-token-text-secondary hover:bg-token-bg-secondary rounded-lg\" aria-label=\"Copy\" aria-selected=\"false\" data-testid=\"copy-turn-action-button\" data-state=\"closed\"><\/button><button class=\"text-token-text-secondary hover:bg-token-bg-secondary rounded-lg\" aria-label=\"Good response\" aria-selected=\"false\" data-testid=\"good-response-turn-action-button\" data-state=\"closed\"><\/button><button class=\"text-token-text-secondary hover:bg-token-bg-secondary rounded-lg\" aria-label=\"Bad response\" aria-selected=\"false\" data-testid=\"bad-response-turn-action-button\" data-state=\"closed\"><\/button><button class=\"text-token-text-secondary hover:bg-token-bg-secondary rounded-lg\" aria-label=\"Read aloud\" aria-selected=\"false\" data-testid=\"voice-play-turn-action-button\" data-state=\"closed\"><\/button><button class=\"text-token-text-secondary hover:bg-token-bg-secondary rounded-lg\" aria-label=\"Share\" aria-selected=\"false\" data-state=\"closed\"><br \/>\n<\/button><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"thread-bottom-container\" class=\"isolate z-3 w-full basis-auto has-data-has-thread-error:pt-2 has-data-has-thread-error:[box-shadow:var(--sharp-edge-bottom-shadow)] md:border-transparent md:pt-0 dark:border-white\/20 md:dark:border-transparent flex flex-col\">\n<div id=\"thread-bottom\">\n<div class=\"text-base mx-auto [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6\">\n<div class=\"max-xs:[--force-hide-label:none] relative z-1 flex h-full max-w-full flex-1 flex-col\" aria-haspopup=\"dialog\" aria-expanded=\"false\" aria-controls=\"radix-\u00abR695ij59jm595j5\u00bb\" data-state=\"closed\">\n<form class=\"w-full [view-transition-name:var(--vt-composer)]\" data-type=\"unified-composer\">\n<div class=\"keyboard-open:fixed keyboard-open:bottom-[var(--screen-keyboard-height,0)] keyboard-open:start-3 keyboard-open:end-3 keyboard-open:z-50 keyboard-open:w-auto! keyboard-open:-translate-y-2 bg-token-bg-primary flex w-full cursor-text flex-col items-center justify-center overflow-clip bg-clip-padding contain-inline-size dark:bg-[#303030] shadow-short rounded-[28px]\">\n<div class=\"relative flex w-full items-end px-2.5 py-2.5\">\n<div class=\"relative flex w-full flex-auto flex-col\">\n<div class=\"relative mx-2.5 grid grid-cols-[auto_minmax(0,1fr)]\">\n<div class=\"relative flex-auto bg-transparent pt-1.5\">\n<div class=\"flex flex-col justify-start\">\n<div class=\"flex min-h-12 items-start\">\n<div class=\"max-w-full min-w-0 flex-1\">\n<div class=\"_prosemirror-parent_kfgfu_2 text-token-text-primary max-h-[25dvh] max-h-52 -mx-3 px-3 overflow-auto [scrollbar-width:thin] default-browser vertical-scroll-fade-mask min-h-12 pe-3\">\n<div id=\"prompt-textarea\" class=\"ProseMirror\" contenteditable=\"true\" translate=\"no\" data-virtualkeyboard=\"true\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"justify-content-end relative ms-2 flex w-full flex-auto flex-col\">\n<div class=\"flex-auto\"><\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div class=\"bg-primary-surface-primary absolute start-2.5 end-0 bottom-2.5 z-2 flex items-center\">\n<div class=\"w-full\">\n<div class=\"flex items-center\" data-testid=\"composer-footer-actions\">\n<div data-testid=\"composer-action-file-upload\">\n<div class=\"relative\">\n<div class=\"flex flex-col\"><input class=\"hidden\" tabindex=\"-1\" multiple=\"multiple\" type=\"file\" \/><button id=\"upload-file-btn\" class=\"composer-btn\" disabled=\"disabled\" type=\"button\" aria-haspopup=\"menu\" aria-expanded=\"false\" data-state=\"closed\" data-disabled=\"\" aria-label=\"Add files is unavailable\"><\/button><\/p>\n<div class=\"w-fit\" aria-haspopup=\"dialog\" aria-expanded=\"false\" aria-controls=\"radix-\u00abR24mar695ij59jm595j5\u00bb\" data-state=\"closed\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Verstehen von Bundnissen in der Bibel: Ein theologischer \u00dcberblick' data-link='https:\/\/wingulamashahidi.org\/de\/2022\/08\/15\/verstehen-von-bundnissen-in-der-bibel-ein-theologischer-ueberblick\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Was ist ein Bund?Ein Bund ist eine feierliche, verbindliche Vereinbarung zwischen zwei Parteien. In der biblischen Theologie stehen Bundnisse im Zentrum vo<\/p>\n","protected":false},"author":1212,"featured_media":51027,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-51026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/08\/hand-819279.webp","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/08\/hand-819279.webp","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"3d0eKm74Wa\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2022\/08\/15\/verstehen-von-bundnissen-in-der-bibel-ein-theologischer-ueberblick\/\">Verstehen von Bundnissen in der Bibel: Ein theologischer \u00dcberblick<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2022\/08\/15\/verstehen-von-bundnissen-in-der-bibel-ein-theologischer-ueberblick\/embed\/#?secret=3d0eKm74Wa\" width=\"500\" height=\"350\" title=\"&#8222;Verstehen von Bundnissen in der Bibel: Ein theologischer \u00dcberblick&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"3d0eKm74Wa\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/51026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1212"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=51026"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/51026\/revisions"}],"predecessor-version":[{"id":51028,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/51026\/revisions\/51028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/51027"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=51026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=51026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=51026"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=51026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}