{"id":52101,"date":"2021-04-23T11:50:46","date_gmt":"2021-04-23T08:50:46","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=52101"},"modified":"2025-07-04T17:45:50","modified_gmt":"2025-07-04T14:45:50","slug":"koikoi-am-himmel-kennt-seine-vorgegebenen-zeiten","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2021\/04\/23\/koikoi-am-himmel-kennt-seine-vorgegebenen-zeiten\/","title":{"rendered":"KOIKOI AM HIMMEL KENNT SEINE VORGEGEBENEN ZEITEN"},"content":{"rendered":"<div class=\"flex basis-auto flex-col -mb-(--composer-overlap-px) [--composer-overlap-px:55px] grow overflow-hidden\">\n<div class=\"relative h-full\">\n<div class=\"flex h-full flex-col overflow-y-auto [scrollbar-gutter:stable_both-edges] @[84rem]\/thread:pt-(--header-height)\">\n<div class=\"@thread-xl\/thread:pt-header-height flex flex-col text-sm keyboard-open:pb-[calc(var(--composer-height,100px)+var(--screen-keyboard-height,0))] pb-25\">\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"b61b77e1-0c6d-4538-b3b7-c9fb82eba49e\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark\">\n<h2 data-start=\"153\" data-end=\"204\"><\/h2>\n<p data-start=\"206\" data-end=\"224\"><strong data-start=\"206\" data-end=\"222\">Jeremia 8,7:<\/strong><\/p>\n<blockquote data-start=\"225\" data-end=\"409\">\n<p data-start=\"227\" data-end=\"409\">\u201eSogar der Storch am Himmel kennt seine bestimmten Zeiten, Turteltaube, Schwalbe und Kranich halten die Zeit ihres Wiederkommens ein; aber mein Volk kennt nicht das Recht des HERRN.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"411\" data-end=\"671\">Der Storch, die Schwalbe und der Kranich \u2013 das sind erstaunliche V\u00f6gel. Sie besitzen die F\u00e4higkeit, die Jahreszeiten der Erde zu erkennen. Diese F\u00e4higkeit hilft ihnen, sicher und unbeschadet auf dieser Welt zu leben, ohne unn\u00f6tigen Gefahren ausgesetzt zu sein.<\/p>\n<p data-start=\"673\" data-end=\"1022\">Wenn der Winter naht, verlassen sie instinktiv ihre gewohnten Lebensr\u00e4ume und begeben sich auf eine weite Reise \u2013 oft \u00fcber tausende Kilometer \u2013 bis in w\u00e4rmere Gegenden wie Afrika oder andere tropische Regionen. Dort verweilen sie, bis die eisigen Temperaturen des Nordens vor\u00fcber sind, und kehren dann wieder in ihre angestammten Brutgebiete zur\u00fcck.<\/p>\n<p data-start=\"1024\" data-end=\"1473\">Wir sprechen hier nicht von irgendeinem k\u00fchlen Wetter, sondern von den bitterkalten Wintern Europas \u2013 von Temperaturen, bei denen selbst Menschen, die nur wenige Stunden im Freien verbringen, Gefahr laufen zu erfrieren \u2013 ganz gleich, wie viele Schichten sie tragen. Dort lebt man im Winter vorwiegend in gut isolierten H\u00e4usern; gew\u00f6hnliche Bauweisen wie bei uns in Afrika w\u00fcrden dort nicht ausreichen. Unsere Regionen kennen eine solche K\u00e4lte nicht.<\/p>\n<p data-start=\"1475\" data-end=\"1682\">Diese V\u00f6gel wissen, dass sie in solch harschen Bedingungen nicht \u00fcberleben k\u00f6nnen \u2013 selbst ihre Nester w\u00fcrden erfrieren. Also ziehen sie sich rechtzeitig zur\u00fcck, bis die Zeit g\u00fcnstig ist, um zur\u00fcckzukehren.<\/p>\n<p data-start=\"1684\" data-end=\"1819\">Gott gebraucht dieses Beispiel von scheinbar verstandlosen Tieren, um uns Menschen zur Vernunft zu bringen. Er fragt uns gewisserma\u00dfen:<\/p>\n<blockquote data-start=\"1821\" data-end=\"1949\">\n<p data-start=\"1823\" data-end=\"1949\"><strong data-start=\"1823\" data-end=\"1935\">\u201eSogar der Storch am Himmel kennt seine bestimmten Zeiten&#8230; aber mein Volk kennt nicht das Recht des HERRN\u201c<\/strong> (Jeremia 8,7)<\/p>\n<\/blockquote>\n<p data-start=\"1951\" data-end=\"2221\">Mit anderen Worten: Wir erkennen nicht den Unterschied zwischen der Zeit der Gnade und der Zeit des Gerichts. Wir leben dahin, als g\u00e4be es keine Ver\u00e4nderung. Wir denken, die Gnadenzeit des Heils werde ewig dauern, dass das Evangelium immer frei verk\u00fcndet wird wie heute.<\/p>\n<p data-start=\"2223\" data-end=\"2521\">Doch, mein lieber Bruder, meine liebe Schwester \u2013 wisse: Diese Gnadenzeit geht bald zu Ende. Eine gro\u00dfe Drangsal, wie sie die Welt noch nie gesehen hat, steht bevor (vgl. Matth\u00e4us 24,21). Alle Zeichen weisen darauf hin, dass wir diese Ereignisse wom\u00f6glich noch in unserer Generation erleben werden.<\/p>\n<p data-start=\"2523\" data-end=\"2841\">Die letzte Phase der Gnadenzeit ist angebrochen. Die Welt h\u00e4tte schon l\u00e4ngst ihr Ende finden sollen, aber weil noch ein schwacher Abendschein der Wahrheit leuchtet, h\u00e4lt Gott sie zur\u00fcck. Jesus verk\u00fcndigt heute nicht mehr prim\u00e4r ein Evangelium der Einladung, sondern eines der Best\u00e4tigung \u2013 zur Pr\u00fcfung deines Glaubens.<\/p>\n<blockquote data-start=\"2843\" data-end=\"3251\">\n<p data-start=\"2845\" data-end=\"3251\"><strong data-start=\"2845\" data-end=\"2870\">Offenbarung 22,10\u201312:<\/strong><br data-start=\"2870\" data-end=\"2873\" \/>\u201eUnd er sprach zu mir: Versiegle die Worte der Weissagung dieses Buches nicht; denn die Zeit ist nahe.<br data-start=\"2977\" data-end=\"2980\" \/>Wer Unrecht tut, der tue weiterhin Unrecht, und wer unrein ist, der sei weiterhin unrein; und der Gerechte \u00fcbe weiterhin Gerechtigkeit, und der Heilige heilige sich weiterhin!<br data-start=\"3157\" data-end=\"3160\" \/>Siehe, ich komme bald und mein Lohn mit mir, einem jeden zu geben, wie seine Werke sind.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3253\" data-end=\"3640\">Warum erkennen wir die Zeichen der Endzeit nicht, obwohl wir f\u00e4hig sind, Regenzeiten und D\u00fcrre vorherzusehen? Warum bereiten wir unsere Felder auf die Regenzeit vor, weichen aber den g\u00f6ttlichen Warnungen nicht aus? Was lehrt dich die Corona-Pandemie? Was sagen dir die immer h\u00e4ufiger werdenden Wirbelst\u00fcrme? Was bedeuten die pl\u00f6tzlich aufgetauchten Massen falscher Propheten in der Welt?<\/p>\n<p data-start=\"3642\" data-end=\"3721\">Sie sind klare Vorzeichen \u2013 Zeichen, dass die Entr\u00fcckung der Gemeinde nahe ist.<\/p>\n<p data-start=\"3723\" data-end=\"3735\">Jesus sagte:<\/p>\n<blockquote data-start=\"3737\" data-end=\"4109\">\n<p data-start=\"3739\" data-end=\"4109\"><strong data-start=\"3739\" data-end=\"3758\">Lukas 12,54\u201356:<\/strong><br data-start=\"3758\" data-end=\"3761\" \/>\u201eEr sprach aber auch zu dem Volk: Wenn ihr eine Wolke vom Westen aufsteigen seht, so sagt ihr gleich: Es kommt Regen \u2013 und es geschieht so.<br data-start=\"3902\" data-end=\"3905\" \/>Und wenn der S\u00fcdwind weht, so sagt ihr: Es wird hei\u00df \u2013 und es geschieht.<br data-start=\"3979\" data-end=\"3982\" \/>Ihr Heuchler! Das Aussehen der Erde und des Himmels k\u00f6nnt ihr beurteilen \u2013 warum aber diese Zeit k\u00f6nnt ihr nicht beurteilen?\u201c<\/p>\n<\/blockquote>\n<p data-start=\"4111\" data-end=\"4338\">Wie tragisch w\u00e4re es, wenn wir Menschen \u2013 mit all unserer Intelligenz \u2013 weniger Einsicht zeigen als die Tiere des Himmels. Wir m\u00fcssen uns selbst pr\u00fcfen, aus dem geistlichen Schlaf erwachen. Das Gericht Gottes steht vor der T\u00fcr.<\/p>\n<p data-start=\"4340\" data-end=\"4512\">Wenn du dich noch au\u00dferhalb der Arche Christi befindest \u2013 z\u00f6gere nicht. Komm zu Jesus mit deinem ganzen Herzen und bitte Ihn, dich zu retten. Unsere Zeit hier ist begrenzt.<\/p>\n<blockquote data-start=\"4514\" data-end=\"4614\">\n<p data-start=\"4516\" data-end=\"4614\"><strong data-start=\"4516\" data-end=\"4535\">Matth\u00e4us 24,35:<\/strong><br data-start=\"4535\" data-end=\"4538\" \/>\u201eHimmel und Erde werden vergehen; aber meine Worte werden nicht vergehen.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"4616\" data-end=\"4697\">Der Himmel ist real \u2013 aber ebenso auch die H\u00f6lle. Die Entscheidung liegt bei dir.<\/p>\n<p data-start=\"4699\" data-end=\"4730\"><strong data-start=\"4699\" data-end=\"4730\">Maranatha \u2013 der Herr kommt!<\/strong><\/p>\n<p data-start=\"4732\" data-end=\"4777\">Bitte teile diese gute Nachricht mit anderen!<\/p>\n<hr data-start=\"4779\" data-end=\"4782\" \/>\n<p data-start=\"4784\" data-end=\"4894\" data-is-last-node=\"\" data-is-only-node=\"\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='KOIKOI AM HIMMEL KENNT SEINE VORGEGEBENEN ZEITEN' data-link='https:\/\/wingulamashahidi.org\/de\/2021\/04\/23\/koikoi-am-himmel-kennt-seine-vorgegebenen-zeiten\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jeremia 8,7: \u201eSogar der Storch am Himmel kennt seine bestimmten Zeiten, Turteltaube, Schwalbe und Kranich halten die Zeit ihres Wiederkommens ein; aber m<\/p>\n","protected":false},"author":1212,"featured_media":46009,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-52101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/04\/Black-necked-Stork-flight-Hans-Wohlmuth-600x350-1.png","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/04\/Black-necked-Stork-flight-Hans-Wohlmuth-600x350-1.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"tEqjLHqzqa\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2021\/04\/23\/koikoi-am-himmel-kennt-seine-vorgegebenen-zeiten\/\">KOIKOI AM HIMMEL KENNT SEINE VORGEGEBENEN ZEITEN<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2021\/04\/23\/koikoi-am-himmel-kennt-seine-vorgegebenen-zeiten\/embed\/#?secret=tEqjLHqzqa\" width=\"500\" height=\"350\" title=\"&#8222;KOIKOI AM HIMMEL KENNT SEINE VORGEGEBENEN ZEITEN&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"tEqjLHqzqa\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1212"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=52101"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52101\/revisions"}],"predecessor-version":[{"id":52102,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52101\/revisions\/52102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/46009"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=52101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=52101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=52101"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=52101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}