{"id":52323,"date":"2020-03-12T13:17:39","date_gmt":"2020-03-12T10:17:39","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=52323"},"modified":"2025-07-08T20:58:10","modified_gmt":"2025-07-08T17:58:10","slug":"gebet-das-werkzeug-das-deine-bitte-verbirgt","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/","title":{"rendered":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT"},"content":{"rendered":"<div class=\"flex basis-auto flex-col -mb-(--composer-overlap-px) [--composer-overlap-px:55px] grow overflow-hidden\">\n<div class=\"relative h-full\">\n<div class=\"flex h-full flex-col overflow-y-auto [scrollbar-gutter:stable_both-edges] @[84rem]\/thread:pt-(--header-height)\">\n<div class=\"@thread-xl\/thread:pt-header-height flex flex-col text-sm keyboard-open:pb-[calc(var(--composer-height,100px)+var(--screen-keyboard-height,0))] pb-25\">\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ea4bb238-8dda-489a-8008-ef5a9f03a383\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark\">\n<h3 data-start=\"144\" data-end=\"193\"><\/h3>\n<p data-start=\"195\" data-end=\"588\">Das Gebet ist das m\u00e4chtigste Mittel, um jemanden schnell in die Gegenwart Gottes zu f\u00fchren. Wir wissen: Wer vor den Herrn, den allm\u00e4chtigen Gott, tritt, hat eine gro\u00dfe Chance, dass seine Anliegen erf\u00fcllt werden. Der Teufel wei\u00df das nur zu gut \u2013 und deshalb setzt er alles daran, Menschen davon abzuhalten. Er \u00fcberflutet sie mit ablenkenden, d\u00e4monischen Gedanken, um sie vom Gebet fernzuhalten.<\/p>\n<p data-start=\"590\" data-end=\"618\">Einige dieser Gedanken sind:<\/p>\n<h4 data-start=\"620\" data-end=\"655\">1. \u201eIch bin zu m\u00fcde zum Beten\u201c<\/h4>\n<p data-start=\"657\" data-end=\"948\">Noch bevor man \u00fcberhaupt ans Beten denkt, kommt oft zuerst der Gedanke: \u201eIch bin zu m\u00fcde.\u201c Man denkt sich: \u201eIch habe den ganzen Tag gearbeitet, hatte keine Zeit zum Ausruhen. Ich bin ersch\u00f6pft, mir ist schwindlig \u2013 ich lasse das Gebet heute aus und erhole mich lieber. Morgen bete ich dann.\u201c<\/p>\n<p data-start=\"950\" data-end=\"1164\">Andere sagen vielleicht: \u201eIch habe den ganzen Tag f\u00fcr Gott gedient, von fr\u00fch bis sp\u00e4t. Die Menschen verlassen sich auf mich, ich habe viele Einladungen zu Predigten und Seminaren \u2013 ich bin heute zu m\u00fcde zum Beten.\u201c<\/p>\n<p data-start=\"1166\" data-end=\"1596\">Aber unser Herr Jesus Christus war weit ersch\u00f6pfter, als wir es uns vorstellen k\u00f6nnen. Er reiste unerm\u00fcdlich, lehrte die Massen, heilte die Kranken \u2013 doch statt sich auszuruhen, zog Er sich zur\u00fcck, um zu beten. Manchmal lie\u00df Er sogar seine J\u00fcnger vorausgehen, damit Er allein auf den Berg gehen konnte, um zu beten. Er verbrachte Stunden im Gebet \u2013 nicht, weil Er nicht m\u00fcde war, sondern weil Er wusste, wie wichtig das Gebet ist.<\/p>\n<blockquote data-start=\"1598\" data-end=\"1888\">\n<p data-start=\"1600\" data-end=\"1888\"><strong data-start=\"1600\" data-end=\"1621\">Matth\u00e4us 14,22\u201323<\/strong><br data-start=\"1621\" data-end=\"1624\" \/>\u201eUnd sogleich n\u00f6tigte Jesus die J\u00fcnger, in das Boot zu steigen und vor ihm ans andre Ufer zu fahren, bis er das Volk gehen lie\u00dfe. Und als er das Volk hatte gehen lassen, stieg er auf einen Berg, um f\u00fcr sich zu sein und zu beten. Und am Abend war er dort allein.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"1890\" data-end=\"2067\">Jesu Entschlossenheit im Gebet \u2013 selbst inmitten von Ersch\u00f6pfung \u2013 zeigt uns, wie hoch er das Gebet einsch\u00e4tzte. F\u00fcr Ihn war es wichtiger als k\u00f6rperliche Ruhe. Die Schrift sagt:<\/p>\n<blockquote data-start=\"2069\" data-end=\"2192\">\n<p data-start=\"2071\" data-end=\"2192\"><strong data-start=\"2071\" data-end=\"2087\">Matth\u00e4us 4,4<\/strong><br data-start=\"2087\" data-end=\"2090\" \/>\u201eDer Mensch lebt nicht vom Brot allein, sondern von einem jeden Wort, das aus dem Mund Gottes geht.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"2194\" data-end=\"2334\">Warum also sollten wir den Gedanken \u201eIch bin zu m\u00fcde\u201c \u00fcber unser Gebetsleben stellen? Erlaube der M\u00fcdigkeit niemals, dein Gebet zu ersetzen.<\/p>\n<hr data-start=\"2336\" data-end=\"2339\" \/>\n<h4 data-start=\"2341\" data-end=\"2380\">2. \u201eIch habe keine Zeit zum Beten\u201c<\/h4>\n<p data-start=\"2382\" data-end=\"2679\">Ein weiterer weitverbreiteter Gedanke, den der Feind streut, ist: \u201eIch habe keine Zeit zum Beten.\u201c Viele sagen, sie seien zu besch\u00e4ftigt. Manche sogar im Dienst f\u00fcr Gott sagen: \u201eIch bin so sehr mit Predigten, Gemeindearbeit und Seminaren besch\u00e4ftigt \u2013 ich finde keine Zeit zum pers\u00f6nlichen Gebet.\u201c<\/p>\n<p data-start=\"2681\" data-end=\"2860\">Doch Jesus war besch\u00e4ftigter als wir alle. Die Menschenmassen dr\u00e4ngten sich um Ihn, um Ihn zu h\u00f6ren und geheilt zu werden. Und trotzdem zog Er sich regelm\u00e4\u00dfig zur\u00fcck, um zu beten.<\/p>\n<blockquote data-start=\"2862\" data-end=\"3089\">\n<p data-start=\"2864\" data-end=\"3089\"><strong data-start=\"2864\" data-end=\"2881\">Lukas 5,15\u201316<\/strong><br data-start=\"2881\" data-end=\"2884\" \/>\u201eAber die Kunde von ihm verbreitete sich umso mehr, und eine gro\u00dfe Menge kam zusammen, ihn zu h\u00f6ren und sich heilen zu lassen von ihren Krankheiten. Er aber zog sich zur\u00fcck in die Einsamkeit und betete.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3091\" data-end=\"3398\">Selbst inmitten von Anfragen, Druck und Dienst hat Jesus nie das pers\u00f6nliche Gebet vernachl\u00e4ssigt. Auch die J\u00fcnger mussten das lernen: Die Beziehung zu Gott kommt vor dem Dienst. In <strong data-start=\"3273\" data-end=\"3288\">Markus 1,35<\/strong> hei\u00dft es, dass Jesus fr\u00fchmorgens aufstand, um zu beten \u2013 das Gebet war ein unverzichtbarer Teil Seines Tages.<\/p>\n<p data-start=\"3400\" data-end=\"3483\">Wie k\u00f6nnen wir also behaupten, Gott zu dienen, aber keine Zeit f\u00fcrs Gebet zu haben?<\/p>\n<hr data-start=\"3485\" data-end=\"3488\" \/>\n<h4 data-start=\"3490\" data-end=\"3534\">3. \u201eWarum brauche ich \u00fcberhaupt Gebet?\u201c<\/h4>\n<p data-start=\"3536\" data-end=\"3730\">Der Teufel fl\u00fcstert auch diesen Gedanken ein: \u201eWarum soll ich beten? Ich komme auch ohne aus.\u201c Ja, du kannst vielleicht dein weltliches Leben auch ohne Gebet organisieren \u2013 aber dein Heil nicht.<\/p>\n<p data-start=\"3732\" data-end=\"3941\">Du kannst in Clubs gehen, trinken, stehlen, unmoralisch leben und arbeiten \u2013 ohne zu beten. Aber wenn du behauptest, gerettet zu sein und nicht betest, wirst du den Versuchungen nicht standhalten. Jesus sagte:<\/p>\n<blockquote data-start=\"3943\" data-end=\"4075\">\n<p data-start=\"3945\" data-end=\"4075\"><strong data-start=\"3945\" data-end=\"3963\">Matth\u00e4us 26,41<\/strong><br data-start=\"3963\" data-end=\"3966\" \/>\u201eWacht und betet, damit ihr nicht in Anfechtung fallt! Der Geist ist willig, aber das Fleisch ist schwach.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"4077\" data-end=\"4213\">Denkst du, der Teufel l\u00e4sst dich in Ruhe, nur weil du Christ bist? Nein \u2013 wenn du nicht betest, wirst du seine Angriffe nicht \u00fcberleben.<\/p>\n<blockquote data-start=\"4215\" data-end=\"4642\">\n<p data-start=\"4217\" data-end=\"4642\"><strong data-start=\"4217\" data-end=\"4234\">Jakobus 4,1\u20133<\/strong><br data-start=\"4234\" data-end=\"4237\" \/>\u201eWoher kommen Kriege und Streitigkeiten unter euch? Kommen sie nicht daher, dass in euren Gliedern die Gel\u00fcste gegeneinander streiten? Ihr seid begehrlich und habt\u2019s doch nicht; ihr mordet und neidet und gewinnt doch nichts; ihr streitet und k\u00e4mpft. Ihr habt nichts, weil ihr nicht bittet. Ihr bittet und empfangt nichts, weil ihr in b\u00f6ser Absicht bittet, n\u00e4mlich damit ihr&#8217;s in euren L\u00fcsten vergeudet.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"4644\" data-end=\"4770\">Gebet ist der Treibstoff f\u00fcr dein Heil. Wie ein Auto ohne Benzin nicht f\u00e4hrt, so kommt deine Errettung ohne Gebet nicht voran.<\/p>\n<hr data-start=\"4772\" data-end=\"4775\" \/>\n<h4 data-start=\"4777\" data-end=\"4834\">4. \u201eIch glaube nicht, dass mein Gebet etwas bewirkt\u201c<\/h4>\n<p data-start=\"4836\" data-end=\"5010\">Ein weiterer tr\u00fcgerischer Gedanke ist: \u201eWas bringt mein Gebet? Gott h\u00f6rt mich sowieso nicht.\u201c Doch das ist eine L\u00fcge. Wenn du gem\u00e4\u00df dem Willen Gottes betest, wirst du geh\u00f6rt.<\/p>\n<p data-start=\"5012\" data-end=\"5154\">Manche Anliegen brauchen wiederholtes Gebet \u2013 heute, morgen, \u00fcbermorgen. Aber Jesus versprach, dass alle Gebete in Seinem Namen erh\u00f6rt werden.<\/p>\n<blockquote data-start=\"5156\" data-end=\"5272\">\n<p data-start=\"5158\" data-end=\"5272\"><strong data-start=\"5158\" data-end=\"5172\">Lukas 18,1<\/strong><br data-start=\"5172\" data-end=\"5175\" \/>\u201eEr sagte ihnen aber ein Gleichnis davon, dass man allezeit beten und nicht nachlassen sollte.\u201c<\/p>\n<\/blockquote>\n<blockquote data-start=\"5274\" data-end=\"5498\">\n<p data-start=\"5276\" data-end=\"5498\"><strong data-start=\"5276\" data-end=\"5294\">Matth\u00e4us 7,7\u20138<\/strong><br data-start=\"5294\" data-end=\"5297\" \/>\u201eBittet, so wird euch gegeben; suchet, so werdet ihr finden; klopft an, so wird euch aufgetan. Denn wer da bittet, der empf\u00e4ngt; und wer da sucht, der findet; und wer da anklopft, dem wird aufgetan.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"5500\" data-end=\"5684\">Viele versuchen, Gott auf anderen Wegen zu erreichen \u2013 aber Jesus hat uns bereits gezeigt, wie: durch Gebet. Selbst Er, der s\u00fcndenlose Sohn Gottes, betete mit Tr\u00e4nen, Schwei\u00df und Blut.<\/p>\n<blockquote data-start=\"5686\" data-end=\"5821\">\n<p data-start=\"5688\" data-end=\"5821\"><strong data-start=\"5688\" data-end=\"5703\">Lukas 22,44<\/strong><br data-start=\"5703\" data-end=\"5706\" \/>\u201eUnd er rang mit dem Tode und betete heftiger; und sein Schwei\u00df wurde wie Blutstropfen, die auf die Erde fielen.\u201c<\/p>\n<\/blockquote>\n<blockquote data-start=\"5823\" data-end=\"6050\">\n<p data-start=\"5825\" data-end=\"6050\"><strong data-start=\"5825\" data-end=\"5840\">Hebr\u00e4er 5,7<\/strong><br data-start=\"5840\" data-end=\"5843\" \/>\u201eUnd er hat in den Tagen seines irdischen Lebens Bitten und Flehen mit lautem Schreien und mit Tr\u00e4nen dem dargebracht, der ihn vom Tode erretten konnte, und ist erh\u00f6rt worden, weil er Gott in Ehren hielt.\u201c<\/p>\n<\/blockquote>\n<hr data-start=\"6052\" data-end=\"6055\" \/>\n<p data-start=\"6057\" data-end=\"6359\">Lass uns also keine Abk\u00fcrzungen suchen. Wenn wir wollen, dass Gott sich in unserem Leben m\u00e4chtig zeigt, dann ist jetzt die Zeit, unser Gebetsleben zu erneuern. Der Herr hat uns aufgefordert, mindestens eine Stunde am Tag zu beten. Lasst uns k\u00e4mpfen, wachsam sein, und den L\u00fcgen des Feindes widerstehen.<\/p>\n<p data-start=\"6361\" data-end=\"6471\">Verlass dich nicht auf deine Kraft oder deinen Verstand. Gib dem Gebet Vorrang \u2013 es wird dein Leben ver\u00e4ndern.<\/p>\n<p data-start=\"6473\" data-end=\"6493\"><strong data-start=\"6473\" data-end=\"6493\">Gott segne dich.<\/strong><\/p>\n<hr data-start=\"6495\" data-end=\"6498\" \/>\n<p data-start=\"6500\" data-end=\"6615\" data-is-last-node=\"\" data-is-only-node=\"\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Das Gebet ist das m\u00e4chtigste Mittel, um jemanden schnell in die Gegenwart Gottes zu f\u00fchren. Wir wissen: Wer vor den Herrn, den allm\u00e4chtigen Gott, tritt,<\/p>\n","protected":false},"author":1212,"featured_media":52324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-52323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"eQXl4uEzan\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/\">GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/embed\/#?secret=eQXl4uEzan\" width=\"500\" height=\"350\" title=\"&#8222;GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"eQXl4uEzan\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Das Gebet ist das m\u00e4chtigste Mittel, um jemanden schnell in die Gegenwart Gottes zu f\u00fchren. Wir wissen: Wer vor den Herrn, den allm\u00e4chtigen Gott, tritt,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T10:17:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T17:58:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rose Makero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose Makero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/\"},\"author\":{\"name\":\"Rose Makero\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/e8cbdb4ed98d3fcb92864ba3165ab61d\"},\"headline\":\"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT\",\"datePublished\":\"2020-03-12T10:17:39+00:00\",\"dateModified\":\"2025-07-08T17:58:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/\"},\"wordCount\":1081,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/89375082_798719573956436_8037323591227801600_n.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/\",\"name\":\"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/89375082_798719573956436_8037323591227801600_n.jpg\",\"datePublished\":\"2020-03-12T10:17:39+00:00\",\"dateModified\":\"2025-07-08T17:58:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/89375082_798719573956436_8037323591227801600_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/89375082_798719573956436_8037323591227801600_n.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/12\\\/gebet-das-werkzeug-das-deine-bitte-verbirgt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/e8cbdb4ed98d3fcb92864ba3165ab61d\",\"name\":\"Rose Makero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g\",\"caption\":\"Rose Makero\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/","og_locale":"de_DE","og_type":"article","og_title":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title","og_description":"Das Gebet ist das m\u00e4chtigste Mittel, um jemanden schnell in die Gegenwart Gottes zu f\u00fchren. Wir wissen: Wer vor den Herrn, den allm\u00e4chtigen Gott, tritt,","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-03-12T10:17:39+00:00","article_modified_time":"2025-07-08T17:58:10+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","type":"image\/jpeg"}],"author":"Rose Makero","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rose Makero","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/"},"author":{"name":"Rose Makero","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/e8cbdb4ed98d3fcb92864ba3165ab61d"},"headline":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT","datePublished":"2020-03-12T10:17:39+00:00","dateModified":"2025-07-08T17:58:10+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/"},"wordCount":1081,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/","name":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","datePublished":"2020-03-12T10:17:39+00:00","dateModified":"2025-07-08T17:58:10+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89375082_798719573956436_8037323591227801600_n.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/12\/gebet-das-werkzeug-das-deine-bitte-verbirgt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"GEBET: DAS WERKZEUG, DAS DEINE BITTE VERBIRGT"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/e8cbdb4ed98d3fcb92864ba3165ab61d","name":"Rose Makero","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f36ff7a0b48c7e45fd19ed0dd9b34815f620cbe1e7e19f508c0085b66be3c58?s=96&d=mm&r=g","caption":"Rose Makero"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1212"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=52323"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52323\/revisions"}],"predecessor-version":[{"id":52325,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52323\/revisions\/52325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/52324"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=52323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=52323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=52323"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=52323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}