{"id":52600,"date":"2024-07-25T08:36:36","date_gmt":"2024-07-25T05:36:36","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=52600"},"modified":"2025-07-15T00:19:11","modified_gmt":"2025-07-14T21:19:11","slug":"was-bedeutet-ich-habe-beschlossen-bei-euch-nichts-zu-wissen-ausser-jesus-christus1-korinther-22","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/25\/was-bedeutet-ich-habe-beschlossen-bei-euch-nichts-zu-wissen-ausser-jesus-christus1-korinther-22\/","title":{"rendered":"Was bedeutet \u201eIch habe beschlossen, bei euch nichts zu wissen au\u00dfer Jesus Christus\u201c?(1. Korinther 2,2)"},"content":{"rendered":"<p>Lass uns diese wichtige Aussage n\u00e4her betrachten.<\/p>\n<p>In 1. Korinther 2,2 schreibt Paulus:<\/p>\n<blockquote><p><strong>\u201eDenn ich hielt mich daf\u00fcr, unter euch nichts zu wissen au\u00dfer Jesus Christus, und zwar nur ihn, den Gekreuzigten.\u201c<\/strong><br \/>\n<em>(Luther 2017)<\/em><\/p><\/blockquote>\n<p>Paulus schreibt an die Gemeinde in Korinth und betont, dass sein Hauptanliegen, als er zu ihnen kam, Jesus Christus und dessen Kreuzigung war. Einfach gesagt, war Paulus\u2019 Ziel:<br \/>\n\u201eAls ich zu euch kam, wollte ich nichts anderes verstehen als das, was ihr \u00fcber Jesus Christus wusstet \u2013 besonders, dass er gekreuzigt wurde.\u201c<\/p>\n<p>Paulus\u2019 Fokus auf \u201eJesus Christus und ihn, den Gekreuzigten\u201c unterstreicht die zentrale Bedeutung des Kreuzes im christlichen Glauben. Die Kreuzigung ist nicht nur ein historisches Ereignis, sondern das Herz der Botschaft des Evangeliums (Kerygma). Wie Paulus an anderer Stelle sagt:<\/p>\n<blockquote><p><strong>\u201eDenn das Wort vom Kreuz ist denen, die verloren gehen, eine Torheit; uns aber, die wir gerettet werden, ist es Gottes Kraft.\u201c<\/strong><br \/>\n<em>(1. Korinther 1,18, Luther 2017)<\/em><\/p><\/blockquote>\n<p>Paulus wollte, dass die Korinther das Evangelium klar verstehen \u2013 ohne Ablenkung durch philosophische Argumente oder menschliche Weisheit.<\/p>\n<hr \/>\n<h3>Warum auf den gekreuzigten Christus konzentrieren?<\/h3>\n<p>Weil der wahre christliche Glaube darauf beruht, Jesus als den gekreuzigten Retter zu erkennen, der f\u00fcr unsere S\u00fcnden gestorben ist (1. Korinther 15,3). Wenn der Glaube auf etwas anderes basiert \u2013 wie menschliche Weisheit, Redekunst oder nur Wunder \u2013 ist er instabil und unvollst\u00e4ndig.<\/p>\n<p>Paulus sagt in 1. Korinther 2,1-2:<\/p>\n<blockquote><p><strong>\u201eAls ich zu euch kam, kam ich nicht mit \u00dcberredungskunst oder menschlicher Weisheit, das Zeugnis von Gott zu verk\u00fcndigen, sondern ich beschloss, bei euch nichts zu wissen au\u00dfer Jesus Christus und ihm, dem Gekreuzigten.\u201c<\/strong><br \/>\n<em>(Elberfelder)<\/em><\/p><\/blockquote>\n<p>Dies zeigt Paulus\u2019 Ablehnung weltlicher Weisheit zugunsten der einfachen, aber tiefen Wahrheit des Evangeliums.<\/p>\n<hr \/>\n<h3>Glaube an Wunder versus Glaube an den gekreuzigten Retter<\/h3>\n<p>Wenn die Korinther nur wegen Zeichen und Wundern glaubten, w\u00e4re ihr Glaube oberfl\u00e4chlich und von \u00e4u\u00dferen Beweisen abh\u00e4ngig. Jesus selbst warnte vor solchem Glauben:<\/p>\n<blockquote><p><strong>\u201eWahrlich, wahrlich, ich sage euch: Ihr sucht mich nicht, weil ihr die Zeichen gesehen habt, sondern weil ihr von den Broten gegessen habt und satt geworden seid.\u201c<\/strong><br \/>\n<em>(Johannes 6,26, Luther 2017)<\/em><\/p><\/blockquote>\n<p>Wahrer Glaube richtet sich auf Jesus als den gekreuzigten und auferstandenen Herrn, was zu Umkehr und Ver\u00e4nderung f\u00fchrt.<\/p>\n<hr \/>\n<h3>Die Wirkung des Verstehens von Jesus als gekreuzigtem Retter<\/h3>\n<p>Ein solcher Glaube ist fest und lebensver\u00e4ndernd. Er f\u00fchrt zur Umkehr und zum Wunsch, Gottes Willen zu tun. Diese Gehorsam ist das Zeichen echten Glaubens und \u00f6ffnet letztlich den Weg zum ewigen Leben. Jesus sagt:<\/p>\n<blockquote><p><strong>\u201eNicht jeder, der zu mir sagt: Herr, Herr! wird in das Himmelreich kommen, sondern nur, wer den Willen tut meines Vaters im Himmel. Viele werden an jenem Tag zu mir sagen: Herr, Herr, haben wir nicht in deinem Namen geweissagt und in deinem Namen D\u00e4monen ausgetrieben und viele Wunder getan? Und dann werde ich ihnen bekennen: Ich habe euch nie gekannt. Weicht von mir, ihr \u00dcbelt\u00e4ter!\u201c<\/strong><br \/>\n<em>(Matth\u00e4us 7,21-23, Luther 2017)<\/em><\/p><\/blockquote>\n<hr \/>\n<h3>Anwendung f\u00fcr uns heute:<\/h3>\n<p>Das Wichtigste ist, fest an diesem grundlegenden Glauben festzuhalten \u2013 dem \u201eMutter-Glauben\u201c \u2013, der auf Jesus Christus, dem Gekreuzigten, zentriert ist. Dieser Glaube reinigt uns und bewahrt uns vor der S\u00fcnde (1. Johannes 3,3), f\u00fchrt uns dazu, ein Leben zu f\u00fchren, das Gott gef\u00e4llt.<\/p>\n<p>M\u00f6ge der Herr uns helfen, diesen Glauben stark zu halten, und uns reichlich segnen.<\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Was bedeutet \u201eIch habe beschlossen, bei euch nichts zu wissen au\u00dfer Jesus Christus\u201c?(1. Korinther 2,2)' data-link='https:\/\/wingulamashahidi.org\/de\/2024\/07\/25\/was-bedeutet-ich-habe-beschlossen-bei-euch-nichts-zu-wissen-ausser-jesus-christus1-korinther-22\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Lass uns diese wichtige Aussage n\u00e4her betrachten. In 1. Korinther 2,2 schreibt Paulus: \u201eDenn ich hielt mich daf\u00fcr, unter euch nichts zu wissen au\u00dfer J<\/p>\n","protected":false},"author":1198,"featured_media":52601,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-52600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/51tuTfdWAcL.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/51tuTfdWAcL.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"6SUo4QQj7n\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/25\/was-bedeutet-ich-habe-beschlossen-bei-euch-nichts-zu-wissen-ausser-jesus-christus1-korinther-22\/\">Was bedeutet \u201eIch habe beschlossen, bei euch nichts zu wissen au\u00dfer Jesus Christus\u201c?(1. Korinther 2,2)<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/25\/was-bedeutet-ich-habe-beschlossen-bei-euch-nichts-zu-wissen-ausser-jesus-christus1-korinther-22\/embed\/#?secret=6SUo4QQj7n\" width=\"500\" height=\"350\" title=\"&#8222;Was bedeutet \u201eIch habe beschlossen, bei euch nichts zu wissen au\u00dfer Jesus Christus\u201c?(1. Korinther 2,2)&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"6SUo4QQj7n\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=52600"}],"version-history":[{"count":2,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52600\/revisions"}],"predecessor-version":[{"id":52604,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/52600\/revisions\/52604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/52601"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=52600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=52600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=52600"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=52600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}