{"id":53399,"date":"2020-12-23T21:49:40","date_gmt":"2020-12-23T18:49:40","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=53399"},"modified":"2025-07-23T23:23:18","modified_gmt":"2025-07-23T20:23:18","slug":"der-koenigsweg-eine-reise-zu-gott-durch-christus","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/12\/23\/der-koenigsweg-eine-reise-zu-gott-durch-christus\/","title":{"rendered":"Der K\u00f6nigsweg \u2013 Eine Reise zu Gott durch Christus"},"content":{"rendered":"<p>In biblischer Zeit gab es eine besondere Stra\u00dfe, die \u201eK\u00f6nigsweg\u201c genannt wurde \u2013 eine wichtige Route, die \u00c4gypten mit Syrien verband und durch Jordanien f\u00fchrte. Sie war lebenswichtig f\u00fcr Handel und Reiseverkehr, mit Br\u00fccken \u00fcber Fl\u00fcsse und ebenerdigem Weg \u00fcber T\u00e4ler. Wer darauf reiste, hatte einen klaren und sicheren Pfad, viel sicherer und schneller als das Umherirren durch unwegsames Gel\u00e4nde.<\/p>\n<p>Diese historische Stra\u00dfe wird im Alten Testament erw\u00e4hnt und war in der antiken Welt wohlbekannt. Aber noch wichtiger ist, dass sie f\u00fcr uns heute eine geistliche Bedeutung hat, besonders f\u00fcr das Verst\u00e4ndnis unserer Glaubensreise.<\/p>\n<hr \/>\n<p><strong>1. Der historische K\u00f6nigsweg in der Schrift<\/strong><\/p>\n<p>Als die Israeliten ins verhei\u00dfene Land zogen, erreichten sie Edom und baten um Durchreise auf diesem Weg:<\/p>\n<blockquote><p>\u201eLasst uns doch durch euer Land ziehen! Wir wollen nicht \u00fcber Acker oder Weinberg gehen und auch kein Wasser aus dem Brunnen trinken, sondern wir wollen den K\u00f6nigsweg gehen und nicht abbiegen, weder rechts noch links, bis wir durch euer Gebiet gezogen sind.\u201c<br \/>\n(4. Mose 20,17)<\/p><\/blockquote>\n<p>Doch die Edomiter verweigerten die Durchreise:<\/p>\n<blockquote><p>\u201eIhr sollt nicht durchziehen, damit ich nicht mit dem Schwert gegen euch herauskomme.\u201c<br \/>\n(4. Mose 20,18)<\/p><\/blockquote>\n<p>Sp\u00e4ter baten die Israeliten die Amoriter um dasselbe:<\/p>\n<blockquote><p>\u201eLass mich durch dein Land ziehen! Wir wollen nicht abbiegen in den Acker oder Weinberg und kein Wasser aus dem Brunnen trinken, sondern den K\u00f6nigsweg gehen, bis wir dein Gebiet durchzogen haben.\u201c<br \/>\n(4. Mose 21,22)<\/p><\/blockquote>\n<p>Auch diesmal wurde die Bitte abgelehnt \u2013 und es kam zum Krieg. Doch Israel siegte.<\/p>\n<hr \/>\n<p><strong>2. Theologischer Einblick: Alttestamentliche Schatten und neutestamentliche Wirklichkeiten<\/strong><\/p>\n<p>Der Apostel Paulus lehrt, dass die Ereignisse im Alten Testament Beispiele oder Schatten f\u00fcr uns heute sind:<\/p>\n<blockquote><p>\u201eDiese Dinge aber sind ihnen als Vorbild widerfahren, und sie sind uns zur Ermahnung geschrieben worden\u2026\u201c<br \/>\n(1. Korinther 10,11)<\/p><\/blockquote>\n<p>Was symbolisiert also der K\u00f6nigsweg?<\/p>\n<p>Er steht f\u00fcr einen direkten, sicheren und von Gott bestimmten Weg zu Seinen Verhei\u00dfungen. Im Alten Testament war er die beste Route ins verhei\u00dfene Land. Im Neuen Testament ist dieser \u201eWeg\u201c Jesus Christus \u2013 der einzige wahre Weg zum ewigen verhei\u00dfenen Land: dem Himmel.<\/p>\n<hr \/>\n<p><strong>3. Jesus Christus: Der wahre und lebendige Weg<\/strong><\/p>\n<p>Jesus machte diese klare Aussage:<\/p>\n<blockquote><p>\u201eIch bin der Weg und die Wahrheit und das Leben; niemand kommt zum Vater denn durch mich.\u201c<br \/>\n(Johannes 14,6)<\/p><\/blockquote>\n<p>Diese Aussage ist exklusiv und absolut. Es gibt keinen anderen geistlichen Weg zu Gott \u2013 weder durch Religion, gute Werke, Propheten noch geistliche F\u00fchrer. Nur der Glaube an Jesus Christus, sichtbar durch Gehorsam und Liebe, f\u00fchrt uns zum Vater.<\/p>\n<p>Der Prophet Jesaja sah diesen Heiligen Weg voraus:<\/p>\n<blockquote><p>\u201eUnd eine Stra\u00dfe wird da sein und wird hei\u00dfen \u201aHeiliger Weg\u2018. Kein Unreiner wird darauf gehen\u2026 Er wird denen geh\u00f6ren, die gehen auf diesem Weg; auch wenn sie Toren sind, werden sie nicht irregehen.\u201c<br \/>\n(Jesaja 35,8)<\/p><\/blockquote>\n<p>Diese Prophezeiung erf\u00fcllt sich in Christus, der S\u00fcnder durch seine Gnade heiligt und sie sicher zum ewigen Leben f\u00fchrt.<\/p>\n<hr \/>\n<p><strong>4. Beharrlichkeit auf dem Weg<\/strong><\/p>\n<p>Wie Israel Widerstand von Edom und den Amoriten erlebte, so begegnen auch wir Herausforderungen \u2013 geistlichen K\u00e4mpfen, Versuchungen, Ablehnung, Leiden. Aber wie sie m\u00fcssen wir entschlossen bleiben auf dem Weg, den Gott bereitet hat. Jesus warnte:<\/p>\n<blockquote><p>\u201eDenn der Weg ist eng, und das Tor ist schmal, das zum Leben f\u00fchrt, und wenige sind\u2019s, die es finden.\u201c<br \/>\n(Matth\u00e4us 7,14)<\/p><\/blockquote>\n<p>Der Weg mag schwierig sein, doch er ist sicher \u2013 und er f\u00fchrt zur ewigen Freude.<\/p>\n<hr \/>\n<p><strong>5. Ein Aufruf zur Entscheidung<\/strong><\/p>\n<p>Viele Menschen gehen unsichere Wege, in der Hoffnung, dass ihre guten Werke, Religion oder Traditionen sie zu Gott f\u00fchren. Aber ohne Christus f\u00fchrt jeder andere Weg ins Verderben.<\/p>\n<blockquote><p>\u201eEs gibt einen Weg, der dem Menschen richtig erscheint, aber am Ende f\u00fchrt er zum Tod.\u201c<br \/>\n(Spr\u00fcche 14,12)<\/p><\/blockquote>\n<p>Jesus ist der einzige Weg, den Gott selbst bereitet hat \u2013 durch Gnade geebnet, mit Wahrheit gepflastert und durch Sein Blut gesichert. Er ist der K\u00f6nigsweg von der Erde zum Himmel.<\/p>\n<hr \/>\n<p><strong>W\u00e4hle den richtigen Weg<\/strong><\/p>\n<p>Wenn du auf unsicheren Pfaden gehst, kehre heute zu Jesus um. Vertraue Ihm, folge Ihm und wandere in Seinen Wegen. Die Reise mit Ihm mag Opfer kosten, doch sie ist der einzige Weg, der das Ziel bei Gottes Gegenwart garantiert.<\/p>\n<p>Die Israeliten gingen den K\u00f6nigsweg trotz Widerstand, weil sie wussten, dass es sich lohnte. So m\u00fcssen auch wir handeln.<\/p>\n<blockquote><p>\u201eLasst uns laufen mit Geduld in dem Kampf, der uns bestimmt ist, und aufsehen zu Jesus, dem Anf\u00e4nger und Vollender des Glaubens.\u201c<br \/>\n(Hebr\u00e4er 12,1\u20132)<\/p><\/blockquote>\n<p>Jesus ist der Weg. Gehe in Ihm. Lebe in Ihm. Und du wirst den Vater erreichen.<\/p>\n<p>Das ist die Wahrheit, die alle Generationen \u00fcberdauert hat.<\/p>\n<p><strong>Der Herr segne dich auf deinem Weg auf dem K\u00f6nigsweg.<\/strong><\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Der K\u00f6nigsweg \u2013 Eine Reise zu Gott durch Christus' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/12\/23\/der-koenigsweg-eine-reise-zu-gott-durch-christus\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>In biblischer Zeit gab es eine besondere Stra\u00dfe, die \u201eK\u00f6nigsweg\u201c genannt wurde \u2013 eine wichtige Route, die \u00c4gypten mit Syrien verband und durch Jor<\/p>\n","protected":false},"author":1198,"featured_media":53401,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-53399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/12\/jordan-kings-highway.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/12\/jordan-kings-highway.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"JsMDI1BwWY\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/12\/23\/der-koenigsweg-eine-reise-zu-gott-durch-christus\/\">Der K\u00f6nigsweg \u2013 Eine Reise zu Gott durch Christus<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/12\/23\/der-koenigsweg-eine-reise-zu-gott-durch-christus\/embed\/#?secret=JsMDI1BwWY\" width=\"500\" height=\"350\" title=\"&#8222;Der K\u00f6nigsweg \u2013 Eine Reise zu Gott durch Christus&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"JsMDI1BwWY\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/53399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=53399"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/53399\/revisions"}],"predecessor-version":[{"id":53402,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/53399\/revisions\/53402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/53401"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=53399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=53399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=53399"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=53399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}