{"id":54886,"date":"2020-03-14T22:13:08","date_gmt":"2020-03-14T19:13:08","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=54886"},"modified":"2025-09-13T10:58:30","modified_gmt":"2025-09-13T07:58:30","slug":"unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/","title":{"rendered":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!"},"content":{"rendered":"<div class=\"relative basis-auto flex-col -mb-(--composer-overlap-px) [--composer-overlap-px:55px] grow flex overflow-hidden\">\n<div class=\"relative h-full\">\n<div class=\"flex h-full flex-col overflow-y-auto thread-xl:pt-(--header-height) [scrollbar-gutter:stable_both-edges]\">\n<div class=\"flex flex-col text-sm thread-xl:pt-header-height keyboard-open:pb-[calc(var(--composer-height,100px)+var(--screen-keyboard-height,0))] pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:3509d5b6-f78e-4125-8e60-9d885cf8177c-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-sm:[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"91117115-ed42-46f9-ba72-1b9f019ac09e\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<h2 data-start=\"275\" data-end=\"341\"><\/h2>\n<p data-start=\"343\" data-end=\"669\">Eines der Dinge, die David immer wieder zum Lobpreis Gottes bewegten, ohne je m\u00fcde zu werden, war seine Gewohnheit, \u00fcber Gottes Gr\u00f6\u00dfe nachzusinnen \u2013 ganz gleich, wo er sich befand. Oft blickte er zum Himmel und betrachtete, wie wunderbar und geheimnisvoll die Sterne und der Mond dort gesetzt waren \u2013 Werke von Gottes Fingern.<\/p>\n<p data-start=\"671\" data-end=\"936\">Es ist eine einzigartige Freude und Ehrfurcht, die das Herz erf\u00fcllt, wenn man \u00fcber Gottes Werke nachdenkt, besonders \u00fcber Seine Sch\u00f6pfung \u2013 den Himmel, die Berge, T\u00e4ler, Fl\u00fcsse und Ozeane. Diese sind nicht nur Naturwunder, sondern Offenbarungen von Gottes Majest\u00e4t.<\/p>\n<p data-start=\"938\" data-end=\"956\">Wie David schrieb:<\/p>\n<blockquote data-start=\"958\" data-end=\"1171\">\n<p data-start=\"960\" data-end=\"1171\">\u201eHERR, unser Herrscher, wie herrlich ist dein Name in allen Landen,<br data-start=\"1027\" data-end=\"1030\" \/>der du zeigst deine Hoheit am Himmel! \u2026<br data-start=\"1071\" data-end=\"1074\" \/>Wenn ich sehe die Himmel, deiner Finger Werk, den Mond und die Sterne, die du bereitet hast&#8230;\u201c<\/p>\n<\/blockquote>\n<p data-start=\"1173\" data-end=\"1199\">\u2014 <em data-start=\"1175\" data-end=\"1188\">Psalm 8,2.4<\/em> (LUT 2017)<\/p>\n<hr data-start=\"1201\" data-end=\"1204\" \/>\n<h3 data-start=\"1206\" data-end=\"1241\">Alter Lobpreis ohne Technologie<\/h3>\n<p data-start=\"1243\" data-end=\"1666\">Manchmal fragen wir uns: Wie konnten Menschen wie David \u2013 ohne Teleskope oder moderne Wissenschaft \u2013 Gott dennoch mit solcher Freude und Ehrfurcht loben? Wenn sie nur die Sterne sahen, die mit blo\u00dfem Auge sichtbar sind \u2013 wie h\u00e4tten sie wohl reagiert, wenn sie in unserer Zeit lebten? In einer Zeit, in der wir Galaxien, Nebel, Schwarze L\u00f6cher und ein Universum entdecken, das so gewaltig ist, dass es nicht messbar scheint?<\/p>\n<p data-start=\"1668\" data-end=\"1869\">Heute wissen wir: Unsere Sonne und all die Sterne, die wir sehen k\u00f6nnen, sind nur winzige K\u00f6rner im Vergleich zu den Billionen anderer Himmelsk\u00f6rper, die Gott erschaffen hat. Und doch sagt die Schrift:<\/p>\n<blockquote data-start=\"1871\" data-end=\"1959\">\n<p data-start=\"1873\" data-end=\"1959\">\u201eDie Himmel erz\u00e4hlen die Ehre Gottes,<br data-start=\"1910\" data-end=\"1913\" \/>und die Feste verk\u00fcndigt seiner H\u00e4nde Werk.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"1961\" data-end=\"1986\">\u2014 <em data-start=\"1963\" data-end=\"1975\">Psalm 19,2<\/em> (LUT 2017)<\/p>\n<p data-start=\"1988\" data-end=\"2110\">Was f\u00fcr ein Gott erschafft solch eine gewaltige Sch\u00f6pfung \u2013 von der wir den gr\u00f6\u00dften Teil noch nicht einmal entdeckt haben?<\/p>\n<hr data-start=\"2112\" data-end=\"2115\" \/>\n<h3 data-start=\"2117\" data-end=\"2168\">Warum wir uns Zeit zum Nachdenken nehmen m\u00fcssen<\/h3>\n<p data-start=\"2170\" data-end=\"2528\">Auch wir sollen Gott echten Lobpreis bringen \u2013 nicht nur routinem\u00e4\u00dfige Anbetung am Sonntag, sondern t\u00e4gliche Betrachtung Seiner Gr\u00f6\u00dfe. Geh hinaus. Schau zum Himmel. Beobachte einen Sonnenaufgang oder -untergang. Sp\u00fcre den Wind. Sieh den Wellen des Ozeans zu. Diese sind wie g\u00f6ttliche Predigten \u2013 ganz ohne Worte \u2013 und bezeugen die Herrlichkeit des Sch\u00f6pfers.<\/p>\n<p data-start=\"2530\" data-end=\"2727\">Ohne solch ein Nachsinnen wird unser Lobpreis leicht zur leeren Routine \u2013 ohne Tiefe oder Aufrichtigkeit. Es ist leicht, Gott mechanisch zu loben, wenn wir nicht aktiv \u00fcber Seine Wunder meditieren.<\/p>\n<hr data-start=\"2729\" data-end=\"2732\" \/>\n<h3 data-start=\"2734\" data-end=\"2770\">Gottes Weisheit in der Sch\u00f6pfung<\/h3>\n<p data-start=\"2772\" data-end=\"2896\">Denk auch an die erstaunliche Vielfalt der Gesch\u00f6pfe, die Gott erschaffen hat \u2013 jedes mit einem bestimmten Design und Zweck:<\/p>\n<p data-start=\"2898\" data-end=\"2998\">Warum hat ein Tier (wie die Giraffe) einen langen Hals, ein anderes nicht \u2013 und doch gedeihen beide?<\/p>\n<p data-start=\"3000\" data-end=\"3114\">Warum hat ein Tausendf\u00fc\u00dfler viele Beine und eine Schlange gar keine \u2013 und doch gleitet die Schlange schnell dahin?<\/p>\n<p data-start=\"3116\" data-end=\"3252\">Warum kann ein Papagei, obwohl er nur einen Schnabel hat, menschliche Sprache nachahmen, besser als ein Affe mit menschen\u00e4hnlichem Mund?<\/p>\n<p data-start=\"3254\" data-end=\"3357\">Warum frisst eine weiche, zahnlose Schnecke Knochen, w\u00e4hrend eine starke, zahnreiche Kuh es nicht kann?<\/p>\n<p data-start=\"3359\" data-end=\"3586\">Diese Paradoxien zeigen: Sprache kommt nicht allein von der Zunge, und Funktion nicht allein von der k\u00f6rperlichen F\u00e4higkeit. Ein Stummer kann eine perfekte Zunge haben \u2013 und doch nicht sprechen, denn Gott bestimmt die Funktion.<\/p>\n<p data-start=\"3588\" data-end=\"3619\">Die Schrift erinnert uns daran:<\/p>\n<blockquote data-start=\"3621\" data-end=\"3754\">\n<p data-start=\"3623\" data-end=\"3754\">\u201eNun aber, HERR, du bist unser Vater.<br data-start=\"3660\" data-end=\"3663\" \/>Wir sind der Ton, und du bist unser T\u00f6pfer,<br data-start=\"3708\" data-end=\"3711\" \/>und wir alle sind das Werk deiner H\u00e4nde.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3756\" data-end=\"3782\">\u2014 <em data-start=\"3758\" data-end=\"3771\">Jesaja 64,7<\/em> (LUT 2017)<\/p>\n<p data-start=\"3784\" data-end=\"3892\">Dies zeigt: Design und Bestimmung kommen aus g\u00f6ttlicher Weisheit \u2013 nicht aus Zufall oder menschlicher Logik.<\/p>\n<hr data-start=\"3894\" data-end=\"3897\" \/>\n<h3 data-start=\"3899\" data-end=\"3918\">Alles ist Gnade<\/h3>\n<p data-start=\"3920\" data-end=\"4199\">Wenn wir \u00fcber Gottes Sch\u00f6pfung und Weisheit nachsinnen, beginnen wir zu verstehen: Gott ist nicht auf unsere Kraft, Bildung oder F\u00e4higkeiten angewiesen, um uns zu erh\u00f6hen. Er braucht keine zwei Beine, um uns in unsere Berufung zu f\u00fchren, und kein Diplom, um uns zu qualifizieren.<\/p>\n<blockquote data-start=\"4201\" data-end=\"4309\">\n<p data-start=\"4203\" data-end=\"4309\">\u201eEs soll nicht durch Heer oder Kraft,<br data-start=\"4240\" data-end=\"4243\" \/>sondern durch meinen Geist geschehen, spricht der HERR Zebaoth.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"4311\" data-end=\"4338\">\u2014 <em data-start=\"4313\" data-end=\"4327\">Sacharja 4,6<\/em> (LUT 2017)<\/p>\n<p data-start=\"4340\" data-end=\"4415\">Es geschieht allein durch Seine Gnade \u2013 nicht durch unser eigenes Verm\u00f6gen.<\/p>\n<hr data-start=\"4417\" data-end=\"4420\" \/>\n<h3 data-start=\"4422\" data-end=\"4462\">Alles, was Odem hat, lobe den HERRN!<\/h3>\n<p data-start=\"4464\" data-end=\"4672\">Wir alle sind berufen, Gott stets zu loben \u2013 f\u00fcr Seine wunderbaren Werke und die Herrlichkeit, die sich in der Sch\u00f6pfung offenbart. Durch solches Lob begegnen wir Ihm tiefer und pers\u00f6nlicher in unserem Leben.<\/p>\n<blockquote data-start=\"4674\" data-end=\"5110\">\n<p data-start=\"4676\" data-end=\"5110\">\u201eHalleluja!<br data-start=\"4687\" data-end=\"4690\" \/>Lobet Gott in seinem Heiligtum,<br data-start=\"4723\" data-end=\"4726\" \/>lobet ihn in der Feste seiner Macht!<br data-start=\"4764\" data-end=\"4767\" \/>Lobet ihn f\u00fcr seine Taten,<br data-start=\"4795\" data-end=\"4798\" \/>lobet ihn in seiner gro\u00dfen Herrlichkeit!<br data-start=\"4840\" data-end=\"4843\" \/>Lobet ihn mit Posaunen,<br data-start=\"4868\" data-end=\"4871\" \/>lobet ihn mit Psalter und Harfen!<br data-start=\"4906\" data-end=\"4909\" \/>Lobet ihn mit Pauken und Reigen,<br data-start=\"4943\" data-end=\"4946\" \/>lobet ihn mit Saiten und Pfeifen!<br data-start=\"4981\" data-end=\"4984\" \/>Lobet ihn mit hellen Zimbeln,<br data-start=\"5015\" data-end=\"5018\" \/>lobet ihn mit klingenden Zimbeln!<br data-start=\"5053\" data-end=\"5056\" \/>Alles, was Odem hat, lobe den HERRN!<br data-start=\"5094\" data-end=\"5097\" \/>Halleluja!\u201c<\/p>\n<\/blockquote>\n<p data-start=\"5112\" data-end=\"5140\">\u2014 <em data-start=\"5114\" data-end=\"5129\">Psalm 150,1\u20136<\/em> (LUT 2017)<\/p>\n<hr data-start=\"5142\" data-end=\"5145\" \/>\n<h3 data-start=\"5147\" data-end=\"5171\">Der Herr segne dich!<\/h3>\n<p data-start=\"5173\" data-end=\"5358\">Bitte teile diese Botschaft mit anderen. Wenn du regelm\u00e4\u00dfig solche Lehren per E-Mail oder WhatsApp erhalten m\u00f6chtest, schreibe uns einfach in den Kommentaren oder kontaktiere uns unter:<\/p>\n<p data-start=\"5360\" data-end=\"5449\">+255 789 001 312<br data-start=\"5379\" data-end=\"5382\" \/>Unser WhatsApp-Kanal: Hier klicken zum Beitreten &gt;&gt; <a href=\"https:\/\/whatsapp.com\/channel\/0029VaBVhuA3WHTbKoz8jx10\"><strong data-start=\"5437\" data-end=\"5449\">WHATSAPP<\/strong><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Eines der Dinge, die David immer wieder zum Lobpreis Gottes bewegten, ohne je m\u00fcde zu werden, war seine Gewohnheit, \u00fcber Gottes Gr\u00f6\u00dfe nachzusinnen \u2013 <\/p>\n","protected":false},"author":1097,"featured_media":54887,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-54886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2rubOW2mFX\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/\">UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/embed\/#?secret=2rubOW2mFX\" width=\"500\" height=\"350\" title=\"&#8222;UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"2rubOW2mFX\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Eines der Dinge, die David immer wieder zum Lobpreis Gottes bewegten, ohne je m\u00fcde zu werden, war seine Gewohnheit, \u00fcber Gottes Gr\u00f6\u00dfe nachzusinnen \u2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-14T19:13:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T07:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1041\" \/>\n\t<meta property=\"og:image:height\" content=\"781\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rogath Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rogath Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/\"},\"author\":{\"name\":\"Rogath Henry\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\"},\"headline\":\"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!\",\"datePublished\":\"2020-03-14T19:13:08+00:00\",\"dateModified\":\"2025-09-13T07:58:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/\"},\"wordCount\":817,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/hubble4.png\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/\",\"name\":\"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/hubble4.png\",\"datePublished\":\"2020-03-14T19:13:08+00:00\",\"dateModified\":\"2025-09-13T07:58:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/hubble4.png\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/hubble4.png\",\"width\":1041,\"height\":781,\"caption\":\"kazi ya vidole vyako\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/03\\\/14\\\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\",\"name\":\"Rogath Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"caption\":\"Rogath Henry\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/","og_locale":"de_DE","og_type":"article","og_title":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title","og_description":"Eines der Dinge, die David immer wieder zum Lobpreis Gottes bewegten, ohne je m\u00fcde zu werden, war seine Gewohnheit, \u00fcber Gottes Gr\u00f6\u00dfe nachzusinnen \u2013","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-03-14T19:13:08+00:00","article_modified_time":"2025-09-13T07:58:30+00:00","og_image":[{"width":1041,"height":781,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","type":"image\/png"}],"author":"Rogath Henry","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rogath Henry","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/"},"author":{"name":"Rogath Henry","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d"},"headline":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!","datePublished":"2020-03-14T19:13:08+00:00","dateModified":"2025-09-13T07:58:30+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/"},"wordCount":817,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/","name":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE! &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","datePublished":"2020-03-14T19:13:08+00:00","dateModified":"2025-09-13T07:58:30+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/hubble4.png","width":1041,"height":781,"caption":"kazi ya vidole vyako"},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/unser-gott-wie-majestaetisch-ist-dein-name-auf-der-ganzen-erde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"UNSER GOTT, WIE MAJEST\u00c4TISCH IST DEIN NAME AUF DER GANZEN ERDE!"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d","name":"Rogath Henry","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","caption":"Rogath Henry"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=54886"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54886\/revisions"}],"predecessor-version":[{"id":54888,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54886\/revisions\/54888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/54887"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=54886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=54886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=54886"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=54886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}