{"id":54998,"date":"2020-03-14T21:58:23","date_gmt":"2020-03-14T18:58:23","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=54998"},"modified":"2025-09-13T22:09:10","modified_gmt":"2025-09-13T19:09:10","slug":"warum-ist-jesus-christus-heute-wichtig-fuer-uns","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/warum-ist-jesus-christus-heute-wichtig-fuer-uns\/","title":{"rendered":"Warum ist Jesus Christus heute wichtig f\u00fcr uns?"},"content":{"rendered":"<div class=\"relative basis-auto flex-col -mb-(--composer-overlap-px) [--composer-overlap-px:55px] grow flex overflow-hidden\">\n<div class=\"relative h-full\">\n<div class=\"flex h-full flex-col overflow-y-auto thread-xl:pt-(--header-height) [scrollbar-gutter:stable_both-edges]\">\n<div class=\"flex flex-col text-sm thread-xl:pt-header-height keyboard-open:pb-[calc(var(--composer-height,100px)+var(--screen-keyboard-height,0))] pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:6baee54b-ab64-40d4-bb23-0d65edb36664-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-sm:[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"42bfdfd3-8542-4288-a367-ece964121f8f\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<h3 data-start=\"207\" data-end=\"258\"><\/h3>\n<p data-start=\"260\" data-end=\"744\">Eine der wichtigsten Aufgaben, die wir als Gl\u00e4ubige haben, ist es, Jesus Christus tiefgehend zu erkennen. Dies ist keine leichte Aufgabe\u2014es ist das Fundament unserer Erl\u00f6sung. Ohne ein wahres Verst\u00e4ndnis davon, wer Jesus ist und was Er getan hat, k\u00f6nnen wir unsere Identit\u00e4t in Ihm nicht vollst\u00e4ndig begreifen, noch k\u00f6nnen wir die Gnade sch\u00e4tzen, die uns zuteilwurde. Ein Mangel an Verst\u00e4ndnis f\u00fchrt viele dazu, diese Gnade zu verachten und letztlich in den geistlichen Ruin zu gehen.<\/p>\n<blockquote>\n<p data-start=\"746\" data-end=\"916\">\u201e<em>Und bis wir alle zur Einheit des Glaubens und der Erkenntnis des Sohnes Gottes gelangen, zum vollendeten Mann, zum Ma\u00df der Gr\u00f6\u00dfe der F\u00fclle Christi.\u201c<\/em><br \/>\n\u2014 Epheser 4:13 (LUT)<\/p>\n<\/blockquote>\n<h3 data-start=\"918\" data-end=\"966\">Jesus kennen ist mehr als nur Wissen im Kopf<\/h3>\n<p data-start=\"968\" data-end=\"1294\">Die Aufforderung, Christus zu erkennen, geht nicht darum, triviale Details zu wissen\u2014wie Er aussah, welches Essen Er mochte oder wie Er sich die Haare schnitt. Nein. Wir sind berufen, die Position und Rolle zu erkennen, die Er im ewigen Plan Gottes hat. Je mehr wir dies verstehen, desto mehr werden wir Gott lieben und ehren.<\/p>\n<p data-start=\"1296\" data-end=\"1499\">Niemand hat vollst\u00e4ndig die Bedeutung von Christi Rolle begriffen, aber wenn wir geistlich wachsen, w\u00e4chst auch dieses Verst\u00e4ndnis. Je mehr wir Jesus erkennen, desto tiefer wird unsere Ehrfurcht vor Ihm.<\/p>\n<h3 data-start=\"1501\" data-end=\"1554\">Die Bedeutung von Jesu Tod: Der Fall von Barabbas<\/h3>\n<p data-start=\"1556\" data-end=\"1674\">Lassen Sie uns \u00fcber ein bemerkenswertes Ereignis aus den Evangelien nachdenken, das die Tiefe von Christi Opfer zeigt.<\/p>\n<p data-start=\"1676\" data-end=\"2020\">Vor der Kreuzigung Jesu stellte Pontius Pilatus der Menge eine Wahl: Entweder sollte Jesus oder ein ber\u00fcchtigter Verbrecher namens Barabbas\u2014ein M\u00f6rder und Rebellenf\u00fchrer\u2014freigelassen werden (Matth\u00e4us 27:16). Barabbas war zu Recht inhaftiert und wartete auf die Hinrichtung f\u00fcr seine Verbrechen. Alle waren sich einig, dass er den Tod verdiente.<\/p>\n<p data-start=\"2022\" data-end=\"2175\">Doch zu einer schockierenden Wendung riefen die Leute: \u201eLass Barabbas los!\u201c Und so wurde er freigelassen\u2014w\u00e4hrend Jesus an seiner Stelle verurteilt wurde.<\/p>\n<blockquote>\n<p data-start=\"2177\" data-end=\"2416\"><em>\u201eNun war es Sitte, dass der Statthalter zu dem Fest der Menge einen Gefangenen loslie\u00df, den sie wollten\u2026 Sie hatten aber einen ber\u00fcchtigten Gefangenen, der hie\u00df Barabbas\u2026 Da riefen sie alle: \u2018Lass ihn kreuzigen!\u2019\u201c<\/em><br \/>\n\u2014 Matth\u00e4us 27:15-22 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"2418\" data-end=\"2727\">Stellen Sie sich Barabbas vor, der den Tod erwartete, nur um unerwartet freigelassen zu werden. Er muss verwirrt gewesen sein: \u201eWarum ich? Ich bin schuldig!\u201c Doch direkt daneben stand Jesus, blutig und schweigend, mit Dornen gekr\u00f6nt, der wahre Unschuldige. Barabbas ging frei, weil Jesus seinen Platz einnahm.<\/p>\n<p data-start=\"2729\" data-end=\"2962\">Dies ist nicht nur eine Geschichte aus der Geschichte\u2014Barabbas stellt uns dar. Wir waren schuldig, verdienten das Urteil, aber Jesus nahm unsere Strafe auf sich. Er wurde verspottet, geschlagen und gekreuzigt, damit wir leben k\u00f6nnen.<\/p>\n<blockquote>\n<p data-start=\"2964\" data-end=\"3156\">\u201e<em>Er wurde durchbohrt wegen unserer Missetaten, zerschlagen wegen unserer S\u00fcnden; die Strafe, die uns Frieden brachte, lag auf ihm, und durch seine Wunden sind wir geheilt.\u201c<\/em><br \/>\n\u2014 Jesaja 53:5 (LUT)<\/p>\n<\/blockquote>\n<h3 data-start=\"3158\" data-end=\"3208\">Gnade ist nicht billig\u2014sie kostete Jesus alles<\/h3>\n<p data-start=\"3210\" data-end=\"3311\">Jesus trug unsere S\u00fcnden nicht einfach wie eine Tasche auf seinem R\u00fccken. Er wurde zur S\u00fcnde f\u00fcr uns.<\/p>\n<blockquote>\n<p data-start=\"3313\" data-end=\"3463\">\u201e<em>Denn er hat den, der von keiner S\u00fcnde wusste, f\u00fcr uns zur S\u00fcnde gemacht, damit wir in ihm die Gerechtigkeit Gottes w\u00fcrden.\u201c<\/em><br \/>\n\u2014 2. Korinther 5:21 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"3465\" data-end=\"3625\">Seine Erniedrigung erh\u00f6hte unseren Wert. Seine Ablehnung sicherte unsere Annahme. W\u00e4hrend Barabbas die Freiheit feierte, wurde Jesus an seiner Stelle verachtet.<\/p>\n<p data-start=\"3627\" data-end=\"3871\">Viele heute wissen nicht, dass die Segnungen, die sie genie\u00dfen\u2014Leben, Atem, Versorgung\u2014allesamt wegen Jesus Christus sind. Selbst diejenigen, die in Rebellion leben, profitieren von der Gnade Gottes, die durch Christus zug\u00e4nglich gemacht wurde.<\/p>\n<h3 data-start=\"3873\" data-end=\"3911\">Missbrauche die Gnade Gottes nicht<\/h3>\n<p data-start=\"3913\" data-end=\"4170\">Die Gnade, die wir jetzt genie\u00dfen, wird nicht ewig dauern. Ein Tag wird kommen, an dem die T\u00fcr der Barmherzigkeit geschlossen wird und die Gemeinde entr\u00fcckt wird (der \u201eHochzeit\u201c). Dann wird die Gro\u00dfe Tr\u00fcbsal beginnen\u2014eine Zeit des Zorns Gottes auf der Erde.<\/p>\n<blockquote>\n<p data-start=\"4172\" data-end=\"4324\">\u201e<em>Weil du mein Wort bewahrt hast\u2026 werde ich dich bewahren vor der Stunde der Pr\u00fcfung, die \u00fcber den ganzen Erdkreis kommen wird.\u201c<\/em><br \/>\n\u2014 Offenbarung 3:10 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"4326\" data-end=\"4626\">Es wird keine Prediger mehr geben, die die Menschen zur Umkehr aufrufen. Stattdessen wird das Gericht \u00fcber die Erde kommen: Fl\u00fcsse werden zu Blut, unheilbare Wunden werden die Menschheit treffen, und schreckliche Dunkelheit wird die Erde bedecken. All das wird in Offenbarung 16 deutlich beschrieben.<\/p>\n<blockquote>\n<p data-start=\"4628\" data-end=\"4772\">\u201e<em>Und sie wurden von der gl\u00fchenden Hitze verbrannt und verfluchten den Namen Gottes, der Macht \u00fcber diese Plagen hatte.\u201c<\/em><br \/>\n\u2014 Offenbarung 16:9 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"4774\" data-end=\"5076\">Denken Sie nicht, dass dies ein M\u00e4rchen ist. So wie die Welt von COVID-19 ersch\u00fcttert wurde, werden diese Urteile viel schwerwiegender sein. Die Sonne wird sich verfinstern, der Mond wird blutrot werden, und t\u00f6dliche Plagen werden die Erde schlagen. Es wird keine Sicherheit geben, keinen Zufluchtsort.<\/p>\n<h3 data-start=\"5078\" data-end=\"5122\">Eine ernste Warnung aus dem Hebr\u00e4erbrief<\/h3>\n<blockquote>\n<p data-start=\"5124\" data-end=\"5331\"><em>\u201eDenn wenn wir absichtlich s\u00fcndigen, nachdem wir die Erkenntnis der Wahrheit empfangen haben, bleibt kein Opfer mehr f\u00fcr die S\u00fcnden, sondern ein schreckliches Erwarten des Gerichts\u2026\u201c<\/em><br \/>\n\u2014 Hebr\u00e4er 10:26-27 (LUT)<\/p>\n<p data-start=\"5333\" data-end=\"5499\">\u201e<em>Wie viel schwerer Strafe, meinen Sie, wird derjenige f\u00fcr sich verdienen, der den Sohn Gottes mit F\u00fc\u00dfen tritt und das Blut des Bundes entweiht?\u201c<\/em><br \/>\n\u2014 Hebr\u00e4er 10:29 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"5501\" data-end=\"5728\">Nehmen Sie diese Gnade nicht leichtfertig. Wenn Sie noch nicht gerettet sind, ist die T\u00fcr der Barmherzigkeit noch offen. Aber Sie m\u00fcssen umkehren\u2014nicht nur f\u00fchlen Sie sich schlecht, sondern sich wirklich von der S\u00fcnde abwenden.<\/p>\n<h3 data-start=\"5730\" data-end=\"5763\">Was bedeutet es, Bu\u00dfe zu tun?<\/h3>\n<p data-start=\"5765\" data-end=\"5888\">Bu\u00dfe tun bedeutet, sich umzukehren. Sie verlassen Ihren s\u00fcndigen Lebensstil und unterwerfen sich Christus. Dies beinhaltet:<\/p>\n<ul data-start=\"5890\" data-end=\"6074\">\n<li data-start=\"5890\" data-end=\"5936\">\n<p data-start=\"5892\" data-end=\"5936\">Sich von der S\u00fcnde abzuwenden (Matth\u00e4us 3:8)<\/p>\n<\/li>\n<li data-start=\"5937\" data-end=\"6005\">\n<p data-start=\"5939\" data-end=\"6005\">Im Namen Jesu zu Wasser getauft zu werden (Apostelgeschichte 2:38)<\/p>\n<\/li>\n<li data-start=\"6006\" data-end=\"6074\">\n<p data-start=\"6008\" data-end=\"6074\">Den Heiligen Geist zu empfangen (R\u00f6mer 8:9; Apostelgeschichte 2:4)<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"6076\" data-end=\"6201\">Tun Sie es mit ganzem Herzen. Jesus ist nicht nur eine Figur in einer Geschichte\u2014Er ist unsere einzige Hoffnung auf Erl\u00f6sung.<\/p>\n<h3 data-start=\"6203\" data-end=\"6224\">Letzte Ermutigung<\/h3>\n<p data-start=\"6226\" data-end=\"6416\">Wenn Sie bis hierher gelesen haben, scrollen Sie nicht einfach weiter oder kommentieren. Treffen Sie eine Entscheidung. Lassen Sie sich von dieser Botschaft ermutigen, Ihr Herz zu ver\u00e4ndern.<\/p>\n<blockquote>\n<p data-start=\"6418\" data-end=\"6504\">\u201e<em>Heute, wenn ihr seine Stimme h\u00f6rt, verh\u00e4rtet eure Herzen nicht.\u201c<\/em><br \/>\n\u2014 Hebr\u00e4er 3:15 (LUT)<\/p>\n<\/blockquote>\n<p data-start=\"6506\" data-end=\"6629\">Jesus Christus ist wichtig\u2014nicht nur f\u00fcr die Vergangenheit, nicht nur f\u00fcr die Zukunft, sondern auch f\u00fcr Sie hier und jetzt.<\/p>\n<p data-start=\"6631\" data-end=\"6840\">M\u00f6ge der Herr Sie segnen und Ihnen den Mut geben, auf seinen Ruf zu antworten. Wenn Sie weiterhin solche Lehren erhalten m\u00f6chten, k\u00f6nnen Sie sich gerne dem <a href=\"https:\/\/whatsapp.com\/channel\/0029VaBVhuA3WHTbKoz8jx10\">WhatsApp<\/a>-Kanal anschlie\u00dfen, der bereitgestellt wurde.<\/p>\n<hr data-start=\"6842\" data-end=\"6845\" \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"thread-bottom-container\" class=\"group\/thread-bottom-container relative isolate z-10 w-full basis-auto has-data-has-thread-error:pt-2 has-data-has-thread-error:[box-shadow:var(--sharp-edge-bottom-shadow)] md:border-transparent md:pt-0 dark:border-white\/20 md:dark:border-transparent content-fade flex flex-col\">\n<div id=\"thread-bottom\">\n<div class=\"text-base mx-auto [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-sm:[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1\">\n<div class=\"relative z-1 flex h-full max-w-full flex-1 flex-col\">\n<form class=\"group\/composer w-full\" data-expanded=\"\" data-type=\"unified-composer\">\n<div class=\"keyboard-open:fixed keyboard-open:bottom-[var(--screen-keyboard-height,0)] keyboard-open:start-3 keyboard-open:end-3 keyboard-open:z-50 keyboard-open:w-auto! keyboard-open:-translate-y-2\">\n<div class=\"bg-token-bg-primary cursor-text overflow-clip bg-clip-padding p-2.5 contain-inline-size dark:bg-[#303030] grid grid-cols-[auto_1fr_auto] [grid-template-areas:'header_header_header'_'leading_primary_trailing'_'._footer_.'] group-data-expanded\/composer:[grid-template-areas:'header_header_header'_'primary_primary_primary'_'leading_footer_trailing'] shadow-short\">\n<div class=\"-m-1 max-w-full overflow-x-auto p-1 [grid-area:footer] [scrollbar-width:none] group-not-data-expanded\/composer:-mb-12\" data-testid=\"composer-footer-actions\">\n<div class=\"flex min-w-fit items-center gap-1.5 ps-0 pe-1.5\">\n<div class=\"radix-state-open:bg-black\/10 inline-flex h-9 rounded-full border text-[13px] font-medium text-token-text-secondary border-token-border-default hover:bg-token-main-surface-secondary focus-visible:outline-black dark:focus-visible:outline-white\">\n<div class=\"ps-1 pe-1 font-semibold whitespace-nowrap [[data-collapse-labels]_&amp;]:sr-only\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Warum ist Jesus Christus heute wichtig f\u00fcr uns?' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/warum-ist-jesus-christus-heute-wichtig-fuer-uns\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Eine der wichtigsten Aufgaben, die wir als Gl\u00e4ubige haben, ist es, Jesus Christus tiefgehend zu erkennen. Dies ist keine leichte Aufgabe\u2014es ist das Fund<\/p>\n","protected":false},"author":1097,"featured_media":54999,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-54998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89158088_800541263774267_8330269635312091136_n.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/03\/89158088_800541263774267_8330269635312091136_n.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"7A7GMWCHXK\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/warum-ist-jesus-christus-heute-wichtig-fuer-uns\/\">Warum ist Jesus Christus heute wichtig f\u00fcr uns?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/03\/14\/warum-ist-jesus-christus-heute-wichtig-fuer-uns\/embed\/#?secret=7A7GMWCHXK\" width=\"500\" height=\"350\" title=\"&#8222;Warum ist Jesus Christus heute wichtig f\u00fcr uns?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"7A7GMWCHXK\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=54998"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54998\/revisions"}],"predecessor-version":[{"id":55000,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/54998\/revisions\/55000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/54999"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=54998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=54998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=54998"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=54998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}