{"id":55172,"date":"2020-05-26T22:10:43","date_gmt":"2020-05-26T19:10:43","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=55172"},"modified":"2025-09-15T16:06:25","modified_gmt":"2025-09-15T13:06:25","slug":"jeder-link-muss-beachtet-werden","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/26\/jeder-link-muss-beachtet-werden\/","title":{"rendered":"JEDER LINK MUSS BEACHTET WERDEN."},"content":{"rendered":"\n<p>Die Gemeinde Christi wird mit einem menschlichen K\u00f6rper verglichen. So wie der K\u00f6rper verschiedene Glieder hat\u00a0 H\u00e4nde, F\u00fc\u00dfe, Augen, Ohren, Mund usw. die alle von einem wichtigen Teil, dem Kopf, gesteuert werden, so ist auch die Gemeinde Christi. Die Bibel sagt, dass wir unterschiedliche Glieder sind, und Christus ist unser Haupt.<\/p>\n<p>Genauso wie es im menschlichen K\u00f6rper kein einziges Glied gibt, das keine Funktion hat, so kann auch kein Christ sagen, er sei gerettet, aber habe keine Aufgabe im Leib Christi. Ein weiteres Merkmal der Glieder ist, dass sie alle in au\u00dfergew\u00f6hnlicher Einheit miteinander zusammenarbeiten.<\/p>\n<blockquote>\n<p><strong>Epheser 4,16<\/strong><br \/>\u201eVon ihm aus wird der ganze Leib zusammengef\u00fcgt und verbunden durch alle Gelenke, die einander Handreichung tun nach dem Ma\u00df der Leistungsf\u00e4higkeit jedes einzelnen Gliedes und macht, dass der Leib w\u00e4chst und sich selbst aufbaut in der Liebe.\u201c<\/p>\n<\/blockquote>\n<p>Du siehst: Du kannst nicht sagen, dass du gerettet bist Monate vergehen, Jahre vergehen\u00a0 und du tr\u00e4gst nichts zum Leib Christi bei. Wenn das der Fall ist, dann erkenne, dass du vom Leib Christi abgeschnitten bist, abgestorben und f\u00fcr lange Zeit hinausgeworfen wurdest. Wenn du dich immer nur predigen l\u00e4sst, aber nichts f\u00fcr Christus tust, dann musst du dein Heil \u00fcberdenken.<\/p>\n<h3>Das sind die Merkmale lebendiger Glieder Christi:<\/h3>\n<hr \/>\n<h2><strong>1.<\/strong> Das Glied dient der Gemeinde Christi mit seinen <strong>Besitzt\u00fcmern<\/strong><\/h2>\n<p>Es ist die Verantwortung jedes Christen, Gott zu geben, damit das Werk des Evangeliums voranschreiten kann. Diese Verantwortung liegt nicht nur bei denen, die das Evangelium empfangen, sondern auch bei denen, die es senden. Jeder hat die Pflicht, nach dem Ma\u00df der ihm gegebenen Gnade einen Teil dessen zu geben, was er hat. Denn diese Verantwortung betrifft jedes einzelne Glied.<\/p>\n<hr \/>\n<h2><strong>2.<\/strong> Das Glied hat die Pflicht, f\u00fcr die <strong>Gemeinde zu beten<\/strong><\/h2>\n<p>Gebet ist ein unverzichtbarer Bestandteil des Lebens eines Christen. Er soll f\u00fcr die ganze Gemeinde Gottes weltweit beten. Es ist nicht leicht, alle Glieder zur gleichen Zeit zu treffen, aber das Gebet vereint uns im Geist. Auch im K\u00f6rper begegnen sich nicht alle Glieder direkt, aber sie kennen sich, unterst\u00fctzen einander und tragen einander in ihren Schw\u00e4chen. So ist es auch mit uns: T\u00e4gliches Gebet f\u00fcr die Gemeinde Christi ist unsere Pflicht. Die Augen k\u00f6nnen sich nicht selbst waschen\u00a0 die H\u00e4nde m\u00fcssen helfen. Und sogar die eine Hand braucht die andere.<\/p>\n<hr \/>\n<h2><strong>3.<\/strong> Das Glied muss das Evangelium <strong>weitergeben<\/strong><\/h2>\n<p>Der Auftrag unseres Herrn, der unser Haupt ist, lautete:<\/p>\n<blockquote>\n<p><strong>Matth\u00e4us 28,19<\/strong><br \/>\u201eDarum gehet hin und macht zu J\u00fcngern alle V\u00f6lker.\u201c<\/p>\n<\/blockquote>\n<p>Jeder von uns hat je nach Gabe, die er empfangen hat, die Verantwortung, das Evangelium auf seine Weise weiterzugeben. Wenn du ein Prediger bist \u2013 dann predige mit Hingabe. Wenn du Evangelist, Lehrer, Apostel, Prophet, S\u00e4nger, Schriftsteller usw. bist \u2013 dann tue es mit Flei\u00df, im Geist und in Wahrheit. Das ist der Beweis daf\u00fcr, dass du ein lebendiges Glied bist.<\/p>\n<hr \/>\n<p>Das sind die Zeichen, die die Lebendigkeit der Glieder Christi bezeugen.<\/p>\n<p>Aber warum haben viele Menschen, die sich Christen nennen, keines dieser drei Merkmale?<\/p>\n<p>Weil sie nicht bereit sind, in Christus zu bleiben und ihm zu gehorchen, der allein uns dieses Leben gibt. Bruder, wenn du dem Haupt nicht gehorchst, kannst du im Leib nichts bewirken. Der Herr Jesus selbst sagte:<\/p>\n<blockquote>\n<p><strong>Johannes 15,4\u20136<\/strong><br \/>\u201eBleibt in mir und ich in euch. Wie die Rebe keine Frucht bringen kann aus sich selbst, wenn sie nicht am Weinstock bleibt, so auch ihr nicht, wenn ihr nicht in mir bleibt.<br \/>Ich bin der Weinstock, ihr seid die Reben. Wer in mir bleibt und ich in ihm, der bringt viel Frucht; denn ohne mich k\u00f6nnt ihr nichts tun.<br \/>Wer nicht in mir bleibt, der wird weggeworfen wie eine Rebe und verdorrt, und man sammelt sie, wirft sie ins Feuer, und sie verbrennen.\u201c<\/p>\n<\/blockquote>\n<p>Du siehst: Wenn du nicht bereit bist, dein Leben ganz Christus hinzugeben, also ein Leben mit einem Fu\u00df in der Welt und einem in Christus zu verlassen, kannst du niemals ein lebendiges Glied sein egal was du tust. Du bist wie ein abgeschnittenes, vertrocknetes Zweig, das nur noch auf das Feuer wartet.<\/p>\n<p>Und denk daran: Du kannst nicht alle Gaben besitzen. Schon der menschliche K\u00f6rper zeigt uns das. Aber du hast eine besondere Gabe, die wichtig f\u00fcr die Gemeinde Christi ist.<\/p>\n<hr \/>\n<h3><strong>Jetzt ist die Zeit, ein lebendiges Glied Christi zu werden.<\/strong><\/h3>\n<p>Wenn du bereit bist, dann bereue deine Fehler, kehre zu Christus zur\u00fcck, und lasse dich taufen, falls du noch nicht auf richtige Weise getauft wurdest n\u00e4mlich durch die vollst\u00e4ndige Taufe im Wasser, wie es geschrieben steht in:<\/p>\n<p>\u00a0<\/p>\n<blockquote>\n<p><strong>Johannes 3,23<\/strong><br \/>\u201eDenn Johannes taufte an einem Ort mit viel Wasser\u2026\u201c<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<blockquote>\n<p><strong>Apostelgeschichte 2,38<\/strong><br \/>\u201eTut Bu\u00dfe und jeder von euch lasse sich taufen auf den Namen Jesu Christi zur Vergebung eurer S\u00fcnden.\u201c<\/p>\n<\/blockquote>\n<p>Ab diesem Zeitpunkt beginne, ein Leben zu f\u00fchren, das deine Errettung widerspiegelt.<\/p>\n<p>Und du wirst selbst sehen, wie Christus beginnt, dich durch die Gabe zu gebrauchen, die er dir gegeben hat. Du wirst ein Glied mit einer bestimmten Aufgabe im Leib Christi\u00a0 und am letzten Tag wird dir deine besondere Ehre zuteil.<\/p>\n<hr \/>\n<p><strong>Der Herr segne dich reichlich.<\/strong><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='JEDER LINK MUSS BEACHTET WERDEN.' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/05\/26\/jeder-link-muss-beachtet-werden\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Gemeinde Christi wird mit einem menschlichen K\u00f6rper verglichen. So wie der K\u00f6rper verschiedene Glieder hat\u00a0 H\u00e4nde, F\u00fc\u00dfe, Augen, Ohren, Mund usw. <\/p>\n","protected":false},"author":1220,"featured_media":55173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-55172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/4.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/4.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"FIA8tDxx1V\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/26\/jeder-link-muss-beachtet-werden\/\">JEDER LINK MUSS BEACHTET WERDEN.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/26\/jeder-link-muss-beachtet-werden\/embed\/#?secret=FIA8tDxx1V\" width=\"500\" height=\"350\" title=\"&#8222;JEDER LINK MUSS BEACHTET WERDEN.&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"FIA8tDxx1V\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1220"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=55172"}],"version-history":[{"count":2,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55172\/revisions"}],"predecessor-version":[{"id":55175,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55172\/revisions\/55175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/55173"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=55172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=55172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=55172"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=55172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}