{"id":55464,"date":"2020-10-20T11:16:41","date_gmt":"2020-10-20T08:16:41","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=55464"},"modified":"2025-09-18T01:03:52","modified_gmt":"2025-09-17T22:03:52","slug":"es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/","title":{"rendered":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<p><strong>\u201eGelobt sei der Name unseres Herrn Jesus Christus, jetzt und in Ewigkeit.\u201c<\/strong><\/p>\n<p>Wir leben in den letzten Tagen \u2013 in Zeiten, die die Schrift als \u201eschwer\u201c bezeichnet (2. Timotheus 3,1). Gerade deshalb ist es umso dringender, dass wir die Dinge, die unser Heil betreffen, tiefer verstehen. Ein oberfl\u00e4chlicher Glaube wird uns auf das, was kommt, nicht vorbereiten. Wir m\u00fcssen Christus mit Entschlossenheit, Unterscheidungsverm\u00f6gen und geistlicher Reife nachfolgen.<\/p>\n<p>Lasst uns auf einen Moment im Leben Jesu schauen, der eine tiefgehende geistliche Lektion enth\u00e4lt.<\/p>\n<h3><strong>Markus 9,30\u201331<\/strong><\/h3>\n<blockquote>\n<p>\u201eUnd sie gingen von dort weg und zogen durch Galil\u00e4a; und er wollte nicht, dass es jemand erfahre. Denn er lehrte seine J\u00fcnger und sprach zu ihnen: Der Menschensohn wird in die H\u00e4nde der Menschen ausgeliefert, und sie werden ihn t\u00f6ten; und nachdem er get\u00f6tet ist, wird er nach drei Tagen auferstehen.\u201c<\/p>\n<\/blockquote>\n<p>Dieses Wort zeigt uns etwas Erstaunliches: Jesus entzog sich bewusst der \u00d6ffentlichkeit \u2013 selbst in Galil\u00e4a, wo er zuvor viele Wunder getan und gro\u00dfe Volksmengen angezogen hatte (vgl. Markus 1,39; Matth\u00e4us 4,23\u201325). Warum?<br \/><strong>Er wollte ungest\u00f6rte Zeit haben, um seine J\u00fcnger zu lehren.<\/strong><\/p>\n<p>Das offenbart eine wichtige geistliche Wahrheit: <strong>Es gibt Zeiten, in denen Jesus sich \u00f6ffentlich offenbart \u2013 und Zeiten, in denen er leise, pers\u00f6nlich und gezielt wirkt.<\/strong> So wie er sich von den Menschenmengen zur\u00fcckzog, um sich seinen \u201eFreunden\u201c zuzuwenden (Johannes 15,15), so zieht er sich auch heute zur\u00fcck \u2013 nicht um sich zu verbergen, sondern um tiefer mit denen zu gehen, die ihn wirklich suchen.<\/p>\n<blockquote>\n<p>Jesus sagte:<br \/>\u201eIhr sollt das Heilige nicht den Hunden geben und eure Perlen nicht vor die S\u00e4ue werfen\u201c (Matth\u00e4us 7,6).<\/p>\n<\/blockquote>\n<p>Das lehrt uns: <strong>Manche geistlichen Wahrheiten sind nur f\u00fcr diejenigen bestimmt, die bereit sind, sie zu empfangen und zu sch\u00e4tzen.<\/strong><\/p>\n<p>Die J\u00fcnger \u2013 im Gegensatz zur Menge \u2013 wurden vorbereitet auf das, was kommen sollte: das Leiden, den Tod und die Auferstehung Christi. Das ist das Herzst\u00fcck des Evangeliums (1. Korinther 15,3\u20134). Es sind \u201eGeheimnisse des Reiches\u201c (R\u00f6mer 16,25\u201326), die geistliche Reife erfordern.<\/p>\n<blockquote>\n<p>Sp\u00e4ter sagte Jesus zu ihnen:<br \/>\u201eNoch vieles habe ich euch zu sagen; aber ih<span style=\"font-size: revert; color: initial;\">r k\u00f6nnt es jetzt nicht ertragen. Wenn aber jener, der Geist der Wahrheit, kommen wird, wird er euch in alle Wahrheit leiten\u201c (Johannes 16,12\u201313).<\/span><\/p>\n<\/blockquote>\n<p>Das zeigt uns: <strong>Geistliches Wachstum und J\u00fcngerschaft sind Voraussetzung f\u00fcr tiefere Offenbarung.<\/strong><\/p>\n<hr \/>\n<h3><strong>Die \u00d6lbergrede \u2013 private Lehre an die J\u00fcnger<\/strong><\/h3>\n<p>Die Lehre \u00fcber die Endzeit gab Jesus nicht den Massen, sondern nur seinen engsten Nachfolgern:<\/p>\n<ul>\n<li>Matth\u00e4us 24<\/li>\n<li>Markus 13<\/li>\n<li>Lukas 21,5\u201336<\/li>\n<\/ul>\n<p>Sie geschah im Verborgenen, auf dem \u00d6lberg (Matth\u00e4us 24,3). Damit macht Jesus deutlich: <strong>Er teilt sensible Wahrheiten nur mit denen, die in enger Beziehung zu ihm stehen.<\/strong><\/p>\n<blockquote>\n<p>Er sagte:<br \/>\u201eWas ich euch sage in der Finsternis, das redet im Licht; und was euch gesagt wird ins Ohr, das verk\u00fcndigt auf den D\u00e4chern\u201c (Matth\u00e4us 10,27).<\/p>\n<\/blockquote>\n<p>Darum k\u00f6nnen auch wir heute von diesen Wahrheiten profitieren: Was einst im Verborgenen gesprochen wurde, ist nun durch die Apostel \u00f6ffentlich geworden.<\/p>\n<hr \/>\n<h3><strong>J\u00fcngerschaft statt blo\u00dfes Zuschauen<\/strong><\/h3>\n<p>Auch heute jagen viele immer noch Zeichen und Wundern nach. Aber Jesus ruft uns zu mehr. Zeichen sind gut (Markus 16,17), aber sie sind nicht das Ziel. Sie sollen uns zu tieferem Glauben f\u00fchren \u2013 nicht uns ablenken von der Nachfolge Christi.<\/p>\n<blockquote>\n<p>\u201eDa sprach Jesus zu seinen J\u00fcngern: Will mir jemand nachfolgen, der verleugne sich selbst und nehme sein Kreuz auf sich und folge mir\u201c (Matth\u00e4us 16,24).<\/p>\n<\/blockquote>\n<p><strong>Ein J\u00fcnger zu sein<\/strong> bedeutet mehr als oberfl\u00e4chliches Glauben. Es hei\u00dft: sich hinzugeben, das Kreuz zu tragen und seiner Lehre zu folgen \u2013 auch wenn es schwer ist.<\/p>\n<p>Wir d\u00fcrfen uns nicht damit zufriedengeben, Teil der Menge zu sein, die Jesus nur wegen der Segnungen nachfolgt. Sonst k\u00f6nnten wir den Moment verpassen, wenn er still vor\u00fcbergeht \u2013 wenn er wirkt und sich nur denen offenbart, die aufmerksam und wachsam sind.<\/p>\n<p>Jesus ist derselbe gestern, heute und in Ewigkeit (Hebr\u00e4er 13,8). So wie er damals die Massen zur\u00fccklie\u00df und sich nur wenigen zuwandte, kann er es auch heute tun. Wenn wir geistlich nicht wach sind, k\u00f6nnte er in unserem Leben, in unseren Gemeinden und St\u00e4dten wirken \u2013 und wir merken es nicht.<\/p>\n<blockquote>\n<p>\u201eAber selig sind eure Augen, dass sie sehen, und eure Ohren, dass sie h\u00f6ren\u201c (Matth\u00e4us 13,16).<\/p>\n<\/blockquote>\n<p>Darum: Erwarte nicht immer, dass Jesus sich offensichtlich zeigt. Er kann auch in der Stille, im Verborgenen, vor\u00fcbergehen \u2013 und sich nur denen offenbaren, die wachen und warten (Lukas 12,37).<\/p>\n<hr \/>\n<h3><strong>Die Dringlichkeit der Stunde<\/strong><\/h3>\n<p>Wir m\u00fcssen uns bewusst sein: <strong>Die Zeit ist kurz.<\/strong> Alle Zeichen der Endzeit haben sich erf\u00fcllt (Matth\u00e4us 24,33). Die Entr\u00fcckung kann jederzeit geschehen (1. Thessalonicher 4,16\u201317). Jetzt ist nicht die Zeit, mit der Gnade zu spielen oder Gottes Dinge auf die leichte Schulter zu nehmen.<\/p>\n<p>Jesus ist nicht nur ein Gedanke, ein Symbol oder ein guter Lehrer. Er ist <strong>\u201eGottes Kraft und Gottes Weisheit\u201c<\/strong> (1. Korinther 1,24). Wer ihm ganz nachfolgt, dessen Leben bleibt nicht dasselbe.<\/p>\n<hr \/>\n<h3><strong>Was sollen wir also tun?<\/strong><\/h3>\n<ol>\n<li><strong>W\u00e4hle J\u00fcngerschaft<\/strong> statt oberfl\u00e4chlichem Glauben.<\/li>\n<li><strong>Trenne dich von weltlichen Ablenkungen<\/strong> und suche die N\u00e4he zu Jesus.<\/li>\n<li><strong>Lass den Heiligen Geist wirken<\/strong>, damit er dich lehrt, \u00fcberf\u00fchrt und leitet.<\/li>\n<li><strong>Bleibe geistlich wach<\/strong>, damit du ihn nicht verpasst, wenn er vor\u00fcbergeht.<\/li>\n<\/ol>\n<blockquote>\n<p>\u201eDarum wachet! Denn ihr wisst nicht, an welchem Tag euer Herr kommt\u201c (Matth\u00e4us 24,42).<\/p>\n<\/blockquote>\n<p>Lasst uns den Augenblick nicht verpassen. Lasst uns wahre J\u00fcnger Christi werden \u2013 das Kreuz tragen, die Welt hinter uns lassen und uns bereiten f\u00fcr seine Wiederkunft.<\/p>\n<p><strong>Maranatha \u2013 Komm, Herr Jesus!<\/strong><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u201eGelobt sei der Name unseres Herrn Jesus Christus, jetzt und in Ewigkeit.\u201c Wir leben in den letzten Tagen \u2013 in Zeiten, die die Schrift als \u201eschwer\u201c bezeichnet (2. Timotheus 3,1). Gerade deshalb ist es umso dringender, dass wir die Dinge, die unser Heil betreffen, tiefer verstehen. Ein oberfl\u00e4chlicher Glaube wird uns auf das, was [&hellip;]<\/p>\n","protected":false},"author":1097,"featured_media":55465,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-55464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"XKevoLI9tI\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/\">Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/embed\/#?secret=XKevoLI9tI\" width=\"500\" height=\"350\" title=\"&#8222;Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"XKevoLI9tI\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u201eGelobt sei der Name unseres Herrn Jesus Christus, jetzt und in Ewigkeit.\u201c Wir leben in den letzten Tagen \u2013 in Zeiten, die die Schrift als \u201eschwer\u201c bezeichnet (2. Timotheus 3,1). Gerade deshalb ist es umso dringender, dass wir die Dinge, die unser Heil betreffen, tiefer verstehen. Ein oberfl\u00e4chlicher Glaube wird uns auf das, was [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-20T08:16:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T22:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rogath Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rogath Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/\"},\"author\":{\"name\":\"Rogath Henry\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\"},\"headline\":\"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken\",\"datePublished\":\"2020-10-20T08:16:41+00:00\",\"dateModified\":\"2025-09-17T22:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/\"},\"wordCount\":931,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/maxresdefault.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/\",\"name\":\"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/maxresdefault.jpg\",\"datePublished\":\"2020-10-20T08:16:41+00:00\",\"dateModified\":\"2025-09-17T22:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/maxresdefault.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/maxresdefault.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/10\\\/20\\\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\",\"name\":\"Rogath Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"caption\":\"Rogath Henry\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/","og_locale":"de_DE","og_type":"article","og_title":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title","og_description":"\u00a0 \u201eGelobt sei der Name unseres Herrn Jesus Christus, jetzt und in Ewigkeit.\u201c Wir leben in den letzten Tagen \u2013 in Zeiten, die die Schrift als \u201eschwer\u201c bezeichnet (2. Timotheus 3,1). Gerade deshalb ist es umso dringender, dass wir die Dinge, die unser Heil betreffen, tiefer verstehen. Ein oberfl\u00e4chlicher Glaube wird uns auf das, was [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-10-20T08:16:41+00:00","article_modified_time":"2025-09-17T22:03:52+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","type":"image\/jpeg"}],"author":"Rogath Henry","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rogath Henry","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/"},"author":{"name":"Rogath Henry","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d"},"headline":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken","datePublished":"2020-10-20T08:16:41+00:00","dateModified":"2025-09-17T22:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/"},"wordCount":931,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/","name":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","datePublished":"2020-10-20T08:16:41+00:00","dateModified":"2025-09-17T22:03:52+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/10\/maxresdefault.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/10\/20\/es-wird-eine-zeit-kommen-da-jesus-voruebergeht-und-die-menschen-werden-es-nicht-einmal-bemerken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\/"},{"@type":"ListItem","position":2,"name":"Es wird eine Zeit kommen, da Jesus vor\u00fcbergeht \u2013 und die Menschen werden es nicht einmal bemerken"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d","name":"Rogath Henry","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","caption":"Rogath Henry"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=55464"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55464\/revisions"}],"predecessor-version":[{"id":55466,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55464\/revisions\/55466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/55465"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=55464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=55464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=55464"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=55464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}