{"id":55678,"date":"2020-02-13T22:31:38","date_gmt":"2020-02-13T19:31:38","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=55678"},"modified":"2025-09-19T13:23:16","modified_gmt":"2025-09-19T10:23:16","slug":"was-soll-ich-tun-um-gottes-zweck-zu-erfuellen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/","title":{"rendered":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?"},"content":{"rendered":"<p>Welcher ist Gottes Zweck?<\/p>\n<p>Gelobt sei der Name unseres Herrn Jesus Christus. Willkommen, lasst uns die Worte des Lebens studieren.<\/p>\n<p>Manche von uns denken, dass wir erst dann sicher sein k\u00f6nnen, Gottes Willen zu tun, wenn Gott uns ausdr\u00fccklich sagt: \u201eTu dies\u201c oder \u201eTu das\u201c. Aber etwas, das wir vielleicht nicht verstehen, ist: Jeder Gedanke oder jede Absicht, die wir ausf\u00fchren \u2013 ob gut oder b\u00f6se \u2013 kann Gottes Plan enthalten.<\/p>\n<p>Sogar Satan, als er von dem Wunsch erf\u00fcllt wurde, wie Gott zu sein, und Konflikte im Himmel verursachte, dann auf die Erde geworfen wurde und weiterhin Zerst\u00f6rung brachte, erf\u00fcllte er dennoch Gottes Plan. Deshalb hat Gott ihn von damals bis heute nicht get\u00f6tet. Erst wenn er Gottes endg\u00fcltigen Zweck vollendet hat, wird er im Feuersee zerst\u00f6rt werden.<\/p>\n<p>Als Judas von dem Gedanken erf\u00fcllt wurde, Jesus zu verraten \u2013 es war sicherlich ein b\u00f6ser Gedanke \u2013, enthielt dieser Gedanke dennoch Gottes vollkommenen Plan. Es musste so geschehen, damit Christus gekreuzigt wird und wir Erl\u00f6sung empfangen. In der Bibel gibt es viele \u00e4hnliche Beispiele: Pharao mit seinem harten Herzen, Simson, der die Frauen der Philister liebte, und viele mehr.<\/p>\n<p>Heute wollen wir einen weiteren Abschnitt betrachten: Ein Volk, das Gott erw\u00e4hlte, um seinen Willen zu vollziehen, obwohl es selbst nicht wusste, dass es Gottes Arbeit tat. Daraus lernen wir unsere heutige Lektion.<\/p>\n<blockquote><p>Jesaja 10,5-8:<br \/>\n\u201eWehe dem Assyrer, der Rute meines Zorns, dessen Stock in meiner Hand ist!<br \/>\nIch sende ihn \u00fcber ein gottloses Volk, gebe ihm den Auftrag, mein Gericht auszuf\u00fchren; er wird Beute machen, Gefangene nehmen und wie Schlamm auf der Erde trampeln.<br \/>\nAber nicht nach seinem eigenen Willen handelt er, noch nach dem, was sein Herz will; denn in seinem Herzen hat er nur Zerst\u00f6rung und Vernichtung der V\u00f6lker geplant.<br \/>\nDenn er sagt: \u201aSind nicht all meine F\u00fcrsten K\u00f6nige?\u2018\u201c<\/p><\/blockquote>\n<p>Kurz gesagt: Das assyrische Reich zur Zeit der K\u00f6nige war eine der drei m\u00e4chtigen Nationen der Welt \u2013 neben \u00c4gypten und Babylon. \u00c4hnlich wie heute die USA, Russland und China milit\u00e4risch und wirtschaftlich stark sind.<\/p>\n<p>Wenn man die Bibel liest, erkennt man: Assyrien war gro\u00df und milit\u00e4risch stark. Gott nutzte dieses Reich, um Israel in die Gefangenschaft zu f\u00fchren (die zehn St\u00e4mme), und sp\u00e4ter wurde das verbleibende Volk von Babylon eingenommen.<\/p>\n<p>Nicht nur Israel, sondern viele andere V\u00f6lker wurden ebenfalls bestraft. Gott selbst erhob Assyrien zu solcher Macht, damit es die V\u00f6lker, die G\u00f6tzen anbeteten, bestrafen konnte.<\/p>\n<p>Aber, wie Jesaja 10,7 sagt: \u201eAber nicht nach seinem eigenen Willen handelt er\u2026\u201c<\/p>\n<p>Seht ihr? In seinem Herzen dachte der Assyrer nicht, dass er von Gott benutzt wurde. Er dachte, er w\u00fcrde die V\u00f6lker zerst\u00f6ren, um sein eigenes Reich zu vergr\u00f6\u00dfern, Reichtum zu erlangen und Gefangene zu machen. Und doch erf\u00fcllte er damit Gottes Plan \u2013 ohne es zu wissen.<\/p>\n<p>Jesus sagte auch zu Judas: \u201eWas du tust, das tue bald\u201c (Johannes 13,27). Seine b\u00f6sen Absichten \u2013 Geld durch den Verrat Jesu zu erhalten \u2013 wurden schnell benutzt, um Gottes Plan zu beschleunigen.<\/p>\n<p>Alle diese Menschen sehen am Ende schlecht aus \u2013 die Nationen wurden vernichtet, Judas starb im Verderben.<\/p>\n<p>Das Prinzip ist dasselbe: Gott erf\u00fcllt oft seinen Willen durch Menschen, die selbst nicht wissen, dass sie dienen.<\/p>\n<p>Wenn Gott zum Beispiel jemanden retten m\u00f6chte, der im Verderben lebt, kann er zuerst eine andere Person ausw\u00e4hlen, die glaubt, sie tue etwas gew\u00f6hnliches, wie einen Flyer zu verteilen. Zwei Jahre sp\u00e4ter findet jemand, der verloren war, diesen Flyer, liest ihn und findet Gottes Botschaft. Diese Person kehrt um, und Gottes Plan wird durch einen unscheinbaren Mittler erf\u00fcllt.<\/p>\n<blockquote><p>Prediger 11,4-6:<br \/>\n\u201eWer den Wind beobachtet, wird nicht s\u00e4en; wer die Wolken betrachtet, wird nicht ernten.<br \/>\nDenn du wei\u00dft nicht, welcher Weg der Wind nimmt oder wie ein Leib im Mutterleib w\u00e4chst. So kennst du auch nicht die Werke Gottes, der alles vollbringt.<br \/>\nS\u00e4e am Morgen dein Saatgut und halte deine Hand nicht zur\u00fcck am Abend; denn du wei\u00dft nicht, was gelingt, ob dies oder jenes, oder ob beides gleich gut gedeiht.\u201c<\/p><\/blockquote>\n<p>Wenn wir also alles in unserer Macht Stehende f\u00fcr Gottes Werk tun, wird er seinen Plan erf\u00fcllen. Und je flei\u00dfiger wir sind, desto mehr wird Gott uns benutzen, seinen Willen zu verwirklichen.<\/p>\n<p>Wenn du predigst, arbeite eifrig weiter. Frage nicht st\u00e4ndig: \u201eTue ich wirklich Gottes Willen?\u201c Tue einfach das Gute, und Gott wird wirken.<\/p>\n<p>Aber wenn du b\u00f6se handelst, wie Babylon, \u00c4gypten oder Assyrien \u2013 Nationen, die zerst\u00f6rt wurden, nachdem sie Gottes Plan erf\u00fcllt hatten \u2013, wird auch dein Ende schlecht sein. Wer andere unterdr\u00fcckt, betr\u00fcgt oder schadet, wird letztlich von Gottes Gericht getroffen werden.<\/p>\n<p>Beginne jetzt, gute Werke zu tun, die Gott gefallen.<\/p>\n<p>Maranatha!<\/p>\n<p>Teile diese gute Nachricht gerne mit anderen. Wenn du m\u00f6chtest, senden wir dir diese Lektionen auch per E-Mail oder WhatsApp: +255 789001312<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Welcher ist Gottes Zweck? Gelobt sei der Name unseres Herrn Jesus Christus. Willkommen, lasst uns die Worte des Lebens studieren. Manche von uns denken, da<\/p>\n","protected":false},"author":1235,"featured_media":55679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-55678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"6ilaypwBuh\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/\">WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/embed\/#?secret=6ilaypwBuh\" width=\"500\" height=\"350\" title=\"&#8222;WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"6ilaypwBuh\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Welcher ist Gottes Zweck? Gelobt sei der Name unseres Herrn Jesus Christus. Willkommen, lasst uns die Worte des Lebens studieren. Manche von uns denken, da\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-13T19:31:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T10:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neema Joshua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neema Joshua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/\"},\"author\":{\"name\":\"Neema Joshua\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\"},\"headline\":\"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?\",\"datePublished\":\"2020-02-13T19:31:38+00:00\",\"dateModified\":\"2025-09-19T10:23:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/\"},\"wordCount\":834,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/2147028709_bb40696e3c.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/\",\"name\":\"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/2147028709_bb40696e3c.jpg\",\"datePublished\":\"2020-02-13T19:31:38+00:00\",\"dateModified\":\"2025-09-19T10:23:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/2147028709_bb40696e3c.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/2147028709_bb40696e3c.jpg\",\"width\":500,\"height\":333,\"caption\":\"kusudi la Mungu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/02\\\/13\\\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\",\"name\":\"Neema Joshua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"caption\":\"Neema Joshua\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/","og_locale":"de_DE","og_type":"article","og_title":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title","og_description":"Welcher ist Gottes Zweck? Gelobt sei der Name unseres Herrn Jesus Christus. Willkommen, lasst uns die Worte des Lebens studieren. Manche von uns denken, da","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-02-13T19:31:38+00:00","article_modified_time":"2025-09-19T10:23:16+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","type":"image\/jpeg"}],"author":"Neema Joshua","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Neema Joshua","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/"},"author":{"name":"Neema Joshua","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a"},"headline":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?","datePublished":"2020-02-13T19:31:38+00:00","dateModified":"2025-09-19T10:23:16+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/"},"wordCount":834,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/","name":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN? &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","datePublished":"2020-02-13T19:31:38+00:00","dateModified":"2025-09-19T10:23:16+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/02\/2147028709_bb40696e3c.jpg","width":500,"height":333,"caption":"kusudi la Mungu"},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/02\/13\/was-soll-ich-tun-um-gottes-zweck-zu-erfuellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"WAS SOLL ICH TUN, UM GOTTES ZWECK ZU ERF\u00dcLLEN?"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a","name":"Neema Joshua","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","caption":"Neema Joshua"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1235"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=55678"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55678\/revisions"}],"predecessor-version":[{"id":55680,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55678\/revisions\/55680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/55679"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=55678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=55678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=55678"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=55678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}