{"id":55768,"date":"2020-05-11T12:18:03","date_gmt":"2020-05-11T09:18:03","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=55768"},"modified":"2025-09-20T12:35:41","modified_gmt":"2025-09-20T09:35:41","slug":"bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/","title":{"rendered":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS."},"content":{"rendered":"<p><span style=\"font-size: revert; color: initial;\">Lukas 21,20\u201324:<\/span><\/p>\n<blockquote><p>\u201eWenn ihr aber seht, dass Jerusalem von Heeren umzingelt ist, dann erkennt, dass seine Verw\u00fcstung naht.<br \/>\n21 Dann flieht, die in Jud\u00e4a sind, auf die Berge, die in der Stadt sind, gehen hinaus, und die auf dem Land sind, kommen nicht hinein;<br \/>\n22 denn dies sind Tage der Vergeltung, damit alles erf\u00fcllt wird, was geschrieben steht.<br \/>\n23 Wehe den Schwangeren und den Stillenden in jenen Tagen! Denn es wird gro\u00dfe Not im Land sein und Zorn \u00fcber dieses Volk kommen.<br \/>\n24 Sie werden durch das Schwert fallen, und Gefangenschaft werden sie erleiden unter allen V\u00f6lkern, und Jerusalem wird von den Nationen zertreten werden, bis die Zeiten der Nationen erf\u00fcllt sind.\u201c<\/p><\/blockquote>\n<p>Obwohl die Stadt Jerusalem Christus ablehnte, bis hin zur Kreuzigung, h\u00f6rte er nicht auf, sie vor den kommenden \u00dcbeln zu warnen. Mehr noch: Er zeigte ihnen den Weg, wie sie diesen \u00dcbeln entkommen konnten \u2013 welch eine Liebe!<\/p>\n<p>Jesus sah voraus, dass Jerusalem von r\u00f6mischen Heeren umzingelt und sp\u00e4ter zerst\u00f6rt und verbrannt w\u00fcrde. Die Bewohner der Stadt w\u00fcrden schwer leiden, manche get\u00f6tet, andere gefangen genommen oder \u00fcber alle L\u00e4nder zerstreut werden.<\/p>\n<blockquote><p>Lukas 19,41\u201344:<br \/>\n\u201eAls er nahe kam, sah er die Stadt und weinte \u00fcber sie und sprach: \u201aAch, wenn doch auch du, wenigstens an diesem Tag, den Frieden erkannt h\u00e4ttest! Jetzt aber ist es vor deinen Augen verborgen.<br \/>\n43 Denn es werden Tage kommen, in denen deine Feinde einen Wall gegen dich aufrichten und dich umzingeln werden;<br \/>\n44 sie werden dich und deine Kinder in deiner Mitte niederwerfen und keinen Stein auf dem anderen lassen, weil du die Zeit deiner Pr\u00fcfung nicht erkannt hast.\u2018\u201c<\/p><\/blockquote>\n<p>Doch Jesus \u00fcberlie\u00df sie nicht einfach ihrem Schicksal. Er sagte ihnen genau, wann sie die Zeichen der Armee sehen w\u00fcrden \u2013 dann sollten sie wissen, dass die Zeit der Zerst\u00f6rung gekommen war. Diejenigen in der Stadt sollten schnell fliehen, diejenigen mitten in der Stadt andere sichere Orte aufsuchen, und die auf dem Land ihre Projekte und Felder verlassen, bevor Jerusalem vernichtet wird.<\/p>\n<p>Dieses Ereignis geschah etwa 33 Jahre nach Christi Himmelfahrt. Um die Zeitspanne zu verdeutlichen: Wenn die Zerst\u00f6rung wie 2020 in unserem Kalender stattgefunden h\u00e4tte, h\u00e4tte Christus die Warnung etwa 1987 gegeben. Die Generationen, die seine Worte h\u00f6rten, hatten die M\u00f6glichkeit, zu handeln.<\/p>\n<p>Diejenigen, die auf Christus h\u00f6rten, sahen im Jahr 66 n. Chr. r\u00f6mische Heere, verlie\u00dfen ihre Felder, H\u00e4user und Projekte und retteten ihre Seelen \u2013 selbst wenn sie materiellen Verlust erlitten. Andere aber, die seine Worte f\u00fcr M\u00e4rchen hielten, blieben in der Stadt. Im Jahr 70 n. Chr. wurden diese Menschen brutal get\u00f6tet, gefangen genommen oder zerstreut, und der Tempel wurde v\u00f6llig zerst\u00f6rt \u2013 die Prophezeiung wurde erf\u00fcllt.<\/p>\n<p>Warum warnte Jesus zuerst?<br \/>\nWeil er ein Beispiel f\u00fcr die zuk\u00fcnftige Gro\u00dfe Tr\u00fcbsal gab. Manche Christen denken, die Tr\u00fcbsal betreffe jeden Gl\u00e4ubigen \u2013 die Bibel lehrt jedoch, dass es zwei Gruppen gibt:<\/p>\n<p>Diejenigen, die Jesu Worte ernst nehmen und danach leben \u2013 sie werden durch das Ereignis der Entr\u00fcckung gerettet.<\/p>\n<p>Diejenigen, die achtlos leben, geistlich kalt oder unbeteiligt sind \u2013 f\u00fcr sie ist die Gro\u00dfe Tr\u00fcbsal real, und sie werden nicht verschont.<\/p>\n<blockquote><p>Markus 13,32\u201337:<br \/>\n\u201eVon jenem Tag aber und jener Stunde wei\u00df niemand, auch die Engel im Himmel nicht, auch der Sohn nicht, nur der Vater.<br \/>\n33 Seht zu, wachet und betet; denn ihr wisst nicht, wann die Zeit kommt.<br \/>\n34 Es ist wie ein Mann, der auf Reisen ging, sein Haus verlie\u00df, seinen Dienern Macht gab und jedem seine Arbeit, und dem T\u00fcrh\u00fcter gebot, zu wachen.<br \/>\n35 Wachet also! Denn ihr wisst nicht, wann der Herr des Hauses kommt, ob am Abend, um Mitternacht, beim Hahnenschrei oder am Morgen;<br \/>\n36 damit er euch nicht pl\u00f6tzlich schlafend finde.<br \/>\n37 Dies aber sage ich euch allen: Wachet!\u201c<\/p><\/blockquote>\n<p>Niemand wei\u00df den Tag der Entr\u00fcckung, doch die Zeichen wurden uns gegeben: Erdbeben, Kriege, Seuchen wie COVID-19 \u2013 dies sind die Hinweise auf die Erntezeit.<\/p>\n<p>Wenn die Heiligen entr\u00fcckt werden, frage dich selbst: Bist du bereit? W\u00e4hrend andere am Festmahl des Lammes teilnehmen, k\u00f6nntest du noch auf der Erde sein in der Tr\u00fcbsal des Antichristen. Wer unvorbereitet ist, verpasst das Himmelreich.<\/p>\n<p>Dies ist keine Zeit f\u00fcr weltliche Ablenkungen. Es ist Zeit, Jesu Worte ernst zu nehmen, wie in der Heiligen Schrift geschrieben:<\/p>\n<blockquote><p>Offenbarung 1,3:<br \/>\n\u201eSelig, der da liest und die da h\u00f6ren die Worte der Weissagung und bewahren, was darin geschrieben steht; denn die Zeit ist nahe.\u201c<\/p><\/blockquote>\n<p>Der Herr segne dich.<\/p>\n<p>Teile diese gute Nachricht mit anderen. Wenn du m\u00f6chtest, k\u00f6nnen wir dir diese Lehren auch per E-Mail oder WhatsApp senden. Kontaktiere uns unter +255 789001312.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Lukas 21,20\u201324: \u201eWenn ihr aber seht, dass Jerusalem von Heeren umzingelt ist, dann erkennt, dass seine Verw\u00fcstung naht. 21 Dann flieht, die in Jud\u00e4a sind, auf die Berge, die in der Stadt sind, gehen hinaus, und die auf dem Land sind, kommen nicht hinein; 22 denn dies sind Tage der Vergeltung, damit alles erf\u00fcllt wird, [&hellip;]<\/p>\n","protected":false},"author":1235,"featured_media":55769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-55768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"UecnureKH8\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/\">BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/embed\/#?secret=UecnureKH8\" width=\"500\" height=\"350\" title=\"&#8222;BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"UecnureKH8\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Lukas 21,20\u201324: \u201eWenn ihr aber seht, dass Jerusalem von Heeren umzingelt ist, dann erkennt, dass seine Verw\u00fcstung naht. 21 Dann flieht, die in Jud\u00e4a sind, auf die Berge, die in der Stadt sind, gehen hinaus, und die auf dem Land sind, kommen nicht hinein; 22 denn dies sind Tage der Vergeltung, damit alles erf\u00fcllt wird, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-11T09:18:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-20T09:35:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1891\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neema Joshua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neema Joshua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/\"},\"author\":{\"name\":\"Neema Joshua\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\"},\"headline\":\"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.\",\"datePublished\":\"2020-05-11T09:18:03+00:00\",\"dateModified\":\"2025-09-20T09:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Francesco_Hayez_017-scaled.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/\",\"name\":\"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Francesco_Hayez_017-scaled.jpg\",\"datePublished\":\"2020-05-11T09:18:03+00:00\",\"dateModified\":\"2025-09-20T09:35:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Francesco_Hayez_017-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Francesco_Hayez_017-scaled.jpg\",\"width\":2560,\"height\":1891,\"caption\":\"mji wa yerusalemu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/05\\\/11\\\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\",\"name\":\"Neema Joshua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"caption\":\"Neema Joshua\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/","og_locale":"de_DE","og_type":"article","og_title":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title","og_description":"Lukas 21,20\u201324: \u201eWenn ihr aber seht, dass Jerusalem von Heeren umzingelt ist, dann erkennt, dass seine Verw\u00fcstung naht. 21 Dann flieht, die in Jud\u00e4a sind, auf die Berge, die in der Stadt sind, gehen hinaus, und die auf dem Land sind, kommen nicht hinein; 22 denn dies sind Tage der Vergeltung, damit alles erf\u00fcllt wird, [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-05-11T09:18:03+00:00","article_modified_time":"2025-09-20T09:35:41+00:00","og_image":[{"width":2560,"height":1891,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","type":"image\/jpeg"}],"author":"Neema Joshua","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Neema Joshua","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/"},"author":{"name":"Neema Joshua","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a"},"headline":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS.","datePublished":"2020-05-11T09:18:03+00:00","dateModified":"2025-09-20T09:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/","name":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS. &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","datePublished":"2020-05-11T09:18:03+00:00","dateModified":"2025-09-20T09:35:41+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/Francesco_Hayez_017-scaled.jpg","width":2560,"height":1891,"caption":"mji wa yerusalemu"},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/11\/bevor-die-zerstoerung-kommt-zeigt-christus-zuerst-den-weg-des-entkommens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\/"},{"@type":"ListItem","position":2,"name":"BEVOR DIE ZERST\u00d6RUNG KOMMT, ZEIGT CHRISTUS ZUERST DEN WEG DES ENTKOMMENS."}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a","name":"Neema Joshua","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","caption":"Neema Joshua"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1235"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=55768"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55768\/revisions"}],"predecessor-version":[{"id":55770,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/55768\/revisions\/55770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/55769"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=55768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=55768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=55768"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=55768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}