{"id":56442,"date":"2018-07-10T11:35:30","date_gmt":"2018-07-10T08:35:30","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=56442"},"modified":"2025-09-28T14:34:04","modified_gmt":"2025-09-28T11:34:04","slug":"esta-tueren-1-2","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/","title":{"rendered":"ESTA: T\u00fcren 1 &amp; 2"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<p>K\u00f6nig der K\u00f6nige, unser Herr Jesus Christus, sei in Ewigkeit verherrlicht!<\/p>\n<p>Seid herzlich willkommen in der Gnade Gottes. Heute besch\u00e4ftigen wir uns mit dem Buch Esther, beginnend mit den Kapiteln 1 und 2. Es ist empfehlenswert, die Bibel zur Hand zu haben, um die Verse nachzulesen. Wie wir wissen, ist der Alte Bund (das Alte Testament) ein Schatten des Neuen Bundes. Jede Geschichte des Alten Testaments offenbart geistliche Wahrheiten, die auch heute noch f\u00fcr unser Leben g\u00fcltig sind (Hebr\u00e4er 10,1).<\/p>\n<p>Das Buch Esther erz\u00e4hlt kurz die Geschichte von K\u00f6nig Ahasveros, dem Herrscher des Persischen Reiches. Er war au\u00dferordentlich reich und m\u00e4chtig, regierte \u00fcber 127 Provinzen \u2013 von Indien bis nach Kusch (\u00c4thiopien) \u2013 und war somit zu jener Zeit praktisch ein Herrscher \u00fcber die ganze Welt.<\/p>\n<p>Eines Tages veranstaltete K\u00f6nig Ahasveros ein gro\u00dfes Fest f\u00fcr seine F\u00fcrsten und B\u00fcrger in Schuschan (Susa). W\u00e4hrend dieser Feier befahl er K\u00f6nigin Waschti, vor den G\u00e4sten zu erscheinen, damit man ihre Sch\u00f6nheit sehen k\u00f6nne. Die Bibel beschreibt Waschti als au\u00dferordentlich sch\u00f6n; ihr Name selbst bedeutet \u201edie Sch\u00f6ne\u201c (Esther 1,11).<\/p>\n<p>Doch Waschti gehorchte dem K\u00f6nig nicht. Sie weigerte sich zu kommen und bestand auf ihrer W\u00fcrde und Eigenst\u00e4ndigkeit. Dieser Akt des Ungehorsams wurde als gro\u00dfe Schande angesehen, da es kulturell unangebracht war, wenn eine Frau dem K\u00f6nig nicht gehorchte. Deshalb wurde Waschti abgesetzt, und die Suche nach einer neuen K\u00f6nigin begann (Esther 1,19):<\/p>\n<blockquote>\n<p>\u201eSo erging der Beschluss des K\u00f6nigs, und es wurde in das Gesetz der Meder und Perser geschrieben, das unwiderruflich ist: Waschti soll nicht mehr vor K\u00f6nig Ahasveros erscheinen, und der K\u00f6nig gebe ihre k\u00f6nigliche W\u00fcrde einer anderen, die besser ist als sie.\u201c<\/p>\n<\/blockquote>\n<p>Daraufhin wurden junge Frauen aus dem ganzen Reich in den Palast gebracht, darunter auch Esther. Sie kamen aus ganz unterschiedlichen sozialen Schichten \u2013 einige aus wohlhabenden oder adeligen Familien, andere aus einfachen Verh\u00e4ltnissen. Vielleicht waren es \u00fcber 30.000 M\u00e4dchen.<\/p>\n<p>Jede durfte sich nach ihrem Wunsch vorbereiten, doch unter der Leitung von Hegai, dem Eunuchen des K\u00f6nigs, der f\u00fcr die Frauen verantwortlich war (Esther 2,1\u20134). Auch Esther wurde unter seine Aufsicht gestellt.<\/p>\n<p>Warum aber hatte Esther Erfolg, wo viele andere scheiterten?<\/p>\n<p>Die Bibel beschreibt sie nicht als die Sch\u00f6nste oder Reichste, auch nicht als Tochter einer k\u00f6niglichen Familie. Stattdessen hatte sie einen sanftm\u00fctigen und dem\u00fctigen Geist. Sie folgte dem Rat ihres Vormundes Mordechai (ihres Onkels) und dem von Hegai. Esther gehorchte Mordechais Anweisung, ihre Herkunft nicht zu verraten und sich nicht zu r\u00fchmen \u2013 dadurch gewann sie Gunst (Esther 2,8\u20139).<\/p>\n<p>Das zeigt uns ein geistliches Prinzip: Gott ehrt Demut, Gehorsam und Zur\u00fcckhaltung mehr als Stolz, gesellschaftlichen Rang oder \u00e4u\u00dfere Sch\u00f6nheit (1. Petrus 5,5; Spr\u00fcche 16,18).<\/p>\n<h2>Theologische Bedeutung<\/h2>\n<p>Die Geschichte Esthers ist ein Vorausbild auf Christus und die Gemeinde:<\/p>\n<ul>\n<li>K\u00f6nig Ahasveros steht sinnbildlich f\u00fcr Jesus Christus, den K\u00f6nig der K\u00f6nige.<\/li>\n<li>K\u00f6nigin Waschti symbolisiert Israel, das zuerst Gottes Messias ablehnte.<\/li>\n<li>Esther stellt die wahre Braut Christi dar, die erw\u00e4hlt und dem K\u00f6nig wohlgef\u00e4llig ist.<\/li>\n<li>Die anderen jungen Frauen versinnbildlichen verschiedene Denominationen und Gruppen, die Anspruch auf Gottes Gunst erheben.<\/li>\n<li>Hegai und Mordechai stehen f\u00fcr das Wort Gottes und den Heiligen Geist, die die Braut auf ihre Begegnung mit dem K\u00f6nig vorbereiten.<\/li>\n<\/ul>\n<p>So wie Israel Jesus ablehnte (Matth\u00e4us 23,37), wandte sich das Reich den Nationen zu und bereitete den Weg f\u00fcr die Braut Christi \u2013 jene, die dem\u00fctig und gehorsam unter Gottes Wort bleiben.<\/p>\n<h2>Zentrale Prinzipien f\u00fcr die Braut Christi<\/h2>\n<ul>\n<li><strong>Demut und Gehorsam:<\/strong> Esther prahlte nicht mit ihrer Herkunft, sondern blieb bescheiden. Auch wir sollen in Demut handeln (Philipper 2,3\u20134).<\/li>\n<li><strong>Gottes F\u00fchrung folgen:<\/strong> Esther gehorchte Mordechai und Hegai. Ebenso m\u00fcssen Gl\u00e4ubige heute dem Wort Gottes und dem Geist folgen \u2013 nicht menschlichen Traditionen (Johannes 14,26).<\/li>\n<li><strong>Reinheit und Vorbereitung:<\/strong> Esther bereitete sich innerlich und \u00e4u\u00dferlich vor. Dies weist auf die Heiligung der Gemeinde hin, die als reine Braut vor Christus treten soll (2. Korinther 11,2).<\/li>\n<\/ul>\n<h2>Warnung vor konfessionellem Stolz<\/h2>\n<p>Heute beanspruchen viele Denominationen, die \u201ewahre Braut Christi\u201c zu sein \u2013 Katholiken, Lutheraner, Anglikaner, Pfingstler, Zeugen Jehovas und andere. Doch die Bibel lehrt, dass es nur <strong>eine<\/strong> wahre Braut gibt: die Gemeinde, die sich Christus in Demut unterordnet und Seinem Wort durch den Geist folgt \u2013 nicht menschlichen Traditionen (Offenbarung 19,7; 1. Korinther 1,2).<\/p>\n<p>Ungehorsam oder das Vertrauen auf eine konfessionelle Identit\u00e4t kann uns disqualifizieren, Teil der Braut Christi zu sein. So wie Esther ohne Hegais Rat abgelehnt worden w\u00e4re, wird auch jeder Christ, der Gottes Wort ignoriert, abgewiesen (Matth\u00e4us 25,1\u201313).<\/p>\n<h2>Anwendung<\/h2>\n<ul>\n<li>Lege konfessionellen Stolz ab und folge Christus, wie Er wirklich ist.<\/li>\n<li>Unterordne dich vollkommen dem Wort Gottes und dem Heiligen Geist.<\/li>\n<li>Strebe nach Demut, Reinheit und Gehorsam \u2013 wie Esther.<\/li>\n<\/ul>\n<h3>Wichtige Bibelstellen<\/h3>\n<ul>\n<li>Esther 1,11.19; 2,1\u20134.8\u20139<\/li>\n<li>Hebr\u00e4er 10,1<\/li>\n<li>Jeremia 3,14<\/li>\n<li>Matth\u00e4us 23,37\u201339<\/li>\n<li>Philipper 2,3\u20134<\/li>\n<li>Johannes 14,26<\/li>\n<li>\n<ol>\n<li>Korinther 1,2<\/li>\n<\/ol>\n<\/li>\n<li>\n<ol start=\"2\">\n<li>Korinther 11,2<\/li>\n<\/ol>\n<\/li>\n<li>Offenbarung 19,7<\/li>\n<\/ul>\n<hr \/>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='ESTA: T\u00fcren 1 &amp; 2' data-link='https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 K\u00f6nig der K\u00f6nige, unser Herr Jesus Christus, sei in Ewigkeit verherrlicht! Seid herzlich willkommen in der Gnade Gottes. Heute besch\u00e4ftigen wir uns m<\/p>\n","protected":false},"author":1235,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-56442","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"gIPFlNYKga\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/\">ESTA: T\u00fcren 1 &amp; 2<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/embed\/#?secret=gIPFlNYKga\" width=\"500\" height=\"350\" title=\"&#8222;ESTA: T\u00fcren 1 &amp; 2&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"gIPFlNYKga\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"\u00a0 K\u00f6nig der K\u00f6nige, unser Herr Jesus Christus, sei in Ewigkeit verherrlicht! Seid herzlich willkommen in der Gnade Gottes. Heute besch\u00e4ftigen wir uns m\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-10T08:35:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-28T11:34:04+00:00\" \/>\n<meta name=\"author\" content=\"Neema Joshua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neema Joshua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/\"},\"author\":{\"name\":\"Neema Joshua\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\"},\"headline\":\"ESTA: T\u00fcren 1 &amp; 2\",\"datePublished\":\"2018-07-10T08:35:30+00:00\",\"dateModified\":\"2025-09-28T11:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/\",\"name\":\"ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"datePublished\":\"2018-07-10T08:35:30+00:00\",\"dateModified\":\"2025-09-28T11:34:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2018\\\/07\\\/10\\\/esta-tueren-1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESTA: T\u00fcren 1 &amp; 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\",\"name\":\"Neema Joshua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"caption\":\"Neema Joshua\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/","og_locale":"de_DE","og_type":"article","og_title":"ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title","og_description":"\u00a0 K\u00f6nig der K\u00f6nige, unser Herr Jesus Christus, sei in Ewigkeit verherrlicht! Seid herzlich willkommen in der Gnade Gottes. Heute besch\u00e4ftigen wir uns m","og_url":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2018-07-10T08:35:30+00:00","article_modified_time":"2025-09-28T11:34:04+00:00","author":"Neema Joshua","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Neema Joshua","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/"},"author":{"name":"Neema Joshua","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a"},"headline":"ESTA: T\u00fcren 1 &amp; 2","datePublished":"2018-07-10T08:35:30+00:00","dateModified":"2025-09-28T11:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/","url":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/","name":"ESTA: T\u00fcren 1 &amp; 2 &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"datePublished":"2018-07-10T08:35:30+00:00","dateModified":"2025-09-28T11:34:04+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2018\/07\/10\/esta-tueren-1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"ESTA: T\u00fcren 1 &amp; 2"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a","name":"Neema Joshua","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","caption":"Neema Joshua"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1235"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=56442"}],"version-history":[{"count":3,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56442\/revisions"}],"predecessor-version":[{"id":57067,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56442\/revisions\/57067"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=56442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=56442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=56442"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=56442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}