{"id":56844,"date":"2019-04-27T13:15:27","date_gmt":"2019-04-27T10:15:27","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=56844"},"modified":"2025-09-26T13:55:35","modified_gmt":"2025-09-26T10:55:35","slug":"dieser-sieb-ist-wirklich-seltsam","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/","title":{"rendered":"DIESER SIEB IST WIRKLICH SELTSAM!"},"content":{"rendered":"<p>Stellen Sie sich Folgendes vor:<br \/>\nEin Mann hat einen schlimmen Motorradunfall. Sein Bein wird abgetrennt und er blutet stark. Er liegt am Boden und braucht dringend Hilfe. Gl\u00fccklicherweise kommt ein guter Samariter vorbei und m\u00f6chte helfen. Doch anstatt sich um die lebensbedrohliche Verletzung zu k\u00fcmmern, schaut er sich das Gesicht des Mannes genau an, bemerkt einen kleinen eitrigen Pickel auf seiner Wange und dr\u00fcckt ihn aus.<\/p>\n<p>Dann sagt er: \u201eDa, ich habe dir geholfen. H\u00e4ttest du nicht eine so ruhige und sorgf\u00e4ltige Person wie mich gefunden, w\u00e4re der Pickel vielleicht schlimmer geworden.\u201c<br \/>\nUnd dann geht er weg und meint: \u201eIch komme morgen wieder, um zu sehen, wie es dir geht.\u201c<\/p>\n<p>Fragen Sie sich: Hat dieser Mann dem Verletzten wirklich geholfen?<br \/>\nTechnisch gesehen ja, er bot Hilfe an. Aber es war nicht die Hilfe, die in diesem Moment n\u00f6tig war. Der blutende Mann brauchte lebensrettende Hilfe, keinen kosmetischen Eingriff.<\/p>\n<p>Dieses Szenario zeigt, wie Heuchelei aussieht: Man konzentriert sich auf Kleinigkeiten und \u00fcbersieht, was wirklich dringend ist.<\/p>\n<p>Jesus tadelte die religi\u00f6sen F\u00fchrer wegen derselben Heuchelei<\/p>\n<p>Jesus erkannte diese Art von Heuchelei bei den religi\u00f6sen F\u00fchrern seiner Zeit. In Matth\u00e4us 23,23\u201324 sagt er:<\/p>\n<blockquote><p>\u201eWehe euch, Schriftgelehrte und Pharis\u00e4er, Heuchler! Denn ihr gebt den Zehnten von Minze, Dill und K\u00fcmmel, aber lasst das Wichtigere im Gesetz au\u00dfer Acht: Gerechtigkeit, Barmherzigkeit und Glauben. Dies sollte man tun, ohne das andere zu vernachl\u00e4ssigen.<br \/>\nIhr blinden F\u00fchrer, die ihr die M\u00fccke aussiebt und das Kamel verschluckt!\u201c<\/p><\/blockquote>\n<p>Diese F\u00fchrer hatten Gottes Priorit\u00e4ten auf den Kopf gestellt. Sie betonten die akribische Zehntgabe, selbst von Kr\u00e4utern und Gew\u00fcrzen, aber vernachl\u00e4ssigten das Wesentliche des Gesetzes Gottes:<\/p>\n<p>Gerechtigkeit<\/p>\n<p>Barmherzigkeit<\/p>\n<p>Treue oder Glauben<\/p>\n<p>Ja, Zehnten zu geben war gut \u2013 daran war nichts falsch. Aber die grundlegenden Angelegenheiten des Glaubens zu ignorieren machte sie zu blinden F\u00fchrern. Sie sieben winzige M\u00fccken (kleine Regeln) aus, aber verschluckten ganze Kamele (gro\u00dfe spirituelle Vers\u00e4umnisse).<\/p>\n<p>Sie machten Anbetung zum Gesch\u00e4ft<\/p>\n<p>Die gleichen F\u00fchrer legten so gro\u00dfen Wert auf Spenden und Tempelsteuern, dass sie das Haus Gottes in einen Marktplatz verwandelten (Johannes 2,14\u201316). Solange Menschen Geld, Opfer und Zehnten brachten, ignorierten sie S\u00fcnden, Ungerechtigkeiten und Korruption unter dem Volk.<\/p>\n<p>Wer keinen Zehnten gab, wurde gerufen, getadelt und beschuldigt, \u201eGott zu berauben\u201c (Maleachi 3,8). Doch die, die in S\u00fcnde lebten, blieben unbehelligt. Das Ergebnis? Eine Generation, \u00e4u\u00dferlich religi\u00f6s, aber innerlich geistlich bankrott.<\/p>\n<p>Sie ignorierten die geistliche Unwissenheit in der Gemeinde. Anstatt die Menschen \u00fcber:<\/p>\n<p>Wahre Bu\u00dfe<\/p>\n<p>Heiliges Leben<\/p>\n<p>Das kommende Reich Gottes<\/p>\n<p>zu lehren, konzentrierten sie sich auf materiellen Reichtum und Kircheneinnahmen. Kein Wunder, dass Jesus sie \u201eblinde F\u00fchrer\u201c nannte.<br \/>\nSie hatten das seltsamste Sieb \u00fcberhaupt \u2013 sie fingen M\u00fccken und lie\u00dfen Kamele passieren.<\/p>\n<p>Dieses seltsame Sieb existiert auch heute noch<\/p>\n<p>Wenn moderne Predigten sich nur auf Folgendes konzentrieren:<\/p>\n<p>Geben<\/p>\n<p>Erfolg<\/p>\n<p>Wohlstand<\/p>\n<p>Finanzielle Partnerschaften<\/p>\n<p>\u2026aber Folgendes ignorieren:<\/p>\n<p>Bu\u00dfe<\/p>\n<p>Taufe<\/p>\n<p>Den neuen Himmel und die neue Erde<\/p>\n<p>Liebe zu Gott und zu anderen<\/p>\n<p>Das Wirken des Heiligen Geistes<\/p>\n<p>\u2026dann benutzen wir dasselbe seltsame Sieb.<\/p>\n<p>Jesus sagte, das gr\u00f6\u00dfte Gebot ist:<\/p>\n<blockquote><p>\u201eDu sollst den Herrn, deinen Gott, lieben von ganzem Herzen, von ganzer Seele und von ganzem Verstand.<br \/>\nDas ist das gr\u00f6\u00dfte und erste Gebot. Das zweite ist ihm gleich: Du sollst deinen N\u00e4chsten lieben wie dich selbst.\u201c (Matth\u00e4us 22,37\u201339)<\/p><\/blockquote>\n<p>Wenn die Liebe zu Gott und zu anderen selten gelehrt wird, aber Geld und Segnungen Jahr f\u00fcr Jahr betont werden, dann werden Prediger und H\u00f6rer gleicherma\u00dfen geistlich fehlgeleitet.<\/p>\n<p>Echte Hilfe oder fehlgeleitete Hilfe?<\/p>\n<p>Es ist wie folgt:<br \/>\nSie haben sechs Tage lang nichts gegessen und hungern fast zu Tode. Dann gibt jemand einen Designeranzug, statt eine Mahlzeit zu bringen. Ein sch\u00f6nes Geschenk, aber in diesem Moment v\u00f6llig nutzlos. Sie brauchen Nahrung, keine Mode.<\/p>\n<p>Sp\u00e4ter, nachdem Sie gegessen und sich erholt haben, k\u00f6nnen Sie den Anzug sch\u00e4tzen.<\/p>\n<p>So ist es geistlich. Wenn der Ort, an dem Sie jetzt sind, Ihre Seele nicht n\u00e4hrt, wenn Ihre Beziehung zu Gott k\u00e4lter wird, m\u00fcssen Sie nicht bleiben. Suchen Sie einen Ort, an dem Sie geistlich gen\u00e4hrt werden. Es ist keine S\u00fcnde. Jesus rief Sie nicht zu einer Konfession.<\/p>\n<blockquote><p>\u201eTrachtet zuerst nach dem Reich Gottes und nach seiner Gerechtigkeit, so wird euch alles andere hinzugef\u00fcgt werden.\u201c (Matth\u00e4us 6,33)<\/p><\/blockquote>\n<p>Wohlstand ist nicht s\u00fcndhaft, aber sekund\u00e4r. Die erste Priorit\u00e4t ist Gottes Reich und seine Gerechtigkeit.<\/p>\n<p>Sind Sie wirklich gerettet?<\/p>\n<p>Dies sind die letzten Tage. Fragen Sie sich:<\/p>\n<p>Bin ich gerettet?<\/p>\n<p>Habe ich den Heiligen Geist empfangen?<\/p>\n<p>Die Bibel warnt:<\/p>\n<blockquote><p>\u201eIhr aber seid nicht Fleisch und Blut, sondern Geist, der Geist Gottes, und wer den Geist Christi nicht hat, geh\u00f6rt ihm nicht.\u201c (R\u00f6mer 8,9)<\/p><\/blockquote>\n<p>Wenn Sie heute weit von Gott entfernt sind, bereuen Sie. Lassen Sie sich im Namen Jesu Christi zur Vergebung Ihrer S\u00fcnden taufen, und Sie werden das Geschenk des Heiligen Geistes empfangen (Apostelgeschichte 2,38).<\/p>\n<p>Der Heilige Geist wird:<\/p>\n<p>Sie f\u00fchren<\/p>\n<p>Sie lehren<\/p>\n<p>Sie st\u00e4rken<\/p>\n<p>Sie f\u00fcr die Ewigkeit versiegeln (Epheser 1,13)<\/p>\n<p>Wie ein Brief mit einem Siegel werden Sie als Gottes Eigentum markiert, bereit f\u00fcr das Himmelreich.<\/p>\n<p>Gott segne Sie im Namen Jesu Christi, des Herrn der Heerscharen.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DIESER SIEB IST WIRKLICH SELTSAM!' data-link='https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Stellen Sie sich Folgendes vor: Ein Mann hat einen schlimmen Motorradunfall. Sein Bein wird abgetrennt und er blutet stark. Er liegt am Boden und braucht d<\/p>\n","protected":false},"author":1235,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-56844","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"N0jC7ZgAtx\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/\">DIESER SIEB IST WIRKLICH SELTSAM!<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/embed\/#?secret=N0jC7ZgAtx\" width=\"500\" height=\"350\" title=\"&#8222;DIESER SIEB IST WIRKLICH SELTSAM!&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"N0jC7ZgAtx\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Stellen Sie sich Folgendes vor: Ein Mann hat einen schlimmen Motorradunfall. Sein Bein wird abgetrennt und er blutet stark. Er liegt am Boden und braucht d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-27T10:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T10:55:35+00:00\" \/>\n<meta name=\"author\" content=\"Neema Joshua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neema Joshua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/\"},\"author\":{\"name\":\"Neema Joshua\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\"},\"headline\":\"DIESER SIEB IST WIRKLICH SELTSAM!\",\"datePublished\":\"2019-04-27T10:15:27+00:00\",\"dateModified\":\"2025-09-26T10:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/\",\"name\":\"DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"datePublished\":\"2019-04-27T10:15:27+00:00\",\"dateModified\":\"2025-09-26T10:55:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/04\\\/27\\\/dieser-sieb-ist-wirklich-seltsam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIESER SIEB IST WIRKLICH SELTSAM!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\",\"name\":\"Neema Joshua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"caption\":\"Neema Joshua\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/","og_locale":"de_DE","og_type":"article","og_title":"DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title","og_description":"Stellen Sie sich Folgendes vor: Ein Mann hat einen schlimmen Motorradunfall. Sein Bein wird abgetrennt und er blutet stark. Er liegt am Boden und braucht d","og_url":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2019-04-27T10:15:27+00:00","article_modified_time":"2025-09-26T10:55:35+00:00","author":"Neema Joshua","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Neema Joshua","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/"},"author":{"name":"Neema Joshua","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a"},"headline":"DIESER SIEB IST WIRKLICH SELTSAM!","datePublished":"2019-04-27T10:15:27+00:00","dateModified":"2025-09-26T10:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/","url":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/","name":"DIESER SIEB IST WIRKLICH SELTSAM! &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"datePublished":"2019-04-27T10:15:27+00:00","dateModified":"2025-09-26T10:55:35+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/04\/27\/dieser-sieb-ist-wirklich-seltsam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"DIESER SIEB IST WIRKLICH SELTSAM!"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a","name":"Neema Joshua","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","caption":"Neema Joshua"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1235"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=56844"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56844\/revisions"}],"predecessor-version":[{"id":56846,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/56844\/revisions\/56846"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=56844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=56844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=56844"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=56844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}