{"id":58049,"date":"2025-09-09T10:18:23","date_gmt":"2025-09-09T07:18:23","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=58049"},"modified":"2025-10-06T22:49:23","modified_gmt":"2025-10-06T19:49:23","slug":"warum-verfluchte-der-prophet-jeremia-den-tag-seiner-geburt-und-ist-es-richtig-dass-wir-unsere-eigenen-geburtstage-verfluchen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2025\/09\/09\/warum-verfluchte-der-prophet-jeremia-den-tag-seiner-geburt-und-ist-es-richtig-dass-wir-unsere-eigenen-geburtstage-verfluchen\/","title":{"rendered":"Warum verfluchte der Prophet Jeremia den Tag seiner Geburt \u2013 und ist es richtig, dass wir unsere eigenen Geburtstage verfluchen?"},"content":{"rendered":"<p><strong>Antwort:<\/strong><br \/>\nBeginnen wir mit einem Blick in die Heilige Schrift, insbesondere Jeremia 20,14\u201317:<\/p>\n<blockquote><p><strong>Jeremia 20,14\u201317 (Luther 2017)<\/strong><br \/>\n14 \u201eVerflucht sei der Tag, an dem ich geboren wurde! Der Tag, an dem meine Mutter mich gebar, soll nicht gesegnet sein!<br \/>\n15 Verflucht sei der Mann, der meinem Vater die Nachricht brachte: \u201aEin Sohn ist dir geboren\u2018, und ihn sehr erfreute.<br \/>\n16 M\u00f6ge dieser Mann wie die St\u00e4dte sein, die der HERR ohne Erbarmen zerst\u00f6rte; m\u00f6ge er am Morgen einen Schrei h\u00f6ren und um die Mittagszeit ein Alarmzeichen,<br \/>\n17 weil er mich nicht im Mutterleib get\u00f6tet hat, sodass meine Mutter mein Grab geworden w\u00e4re, und ihr Mutterleib ewig gro\u00df.\u201c<\/p><\/blockquote>\n<p>Hier sehen wir, dass Jeremia von der Intensit\u00e4t des Leidens und der Verfolgung, die er als Prophet des HERRN erlebte, \u00fcberw\u00e4ltigt war. Er wurde geschlagen, eingesperrt, verspottet und gejagt \u2013 allein daf\u00fcr, dass er Gottes Wort verk\u00fcndete.<\/p>\n<p><strong>Siehe auch:<\/strong><\/p>\n<ul>\n<li>Jeremia 20,1\u20132 \u2013 Pashchur schl\u00e4gt und sperrt ihn ein.<\/li>\n<li>Jeremia 37,15\u201316 \u2013 Er wird erneut geschlagen und eingesperrt.<\/li>\n<li>Jeremia 38,6 \u2013 Er wird in eine Zisterne geworfen.<\/li>\n<li>Jeremia 15,5 \u2013 Er beklagt sich \u00fcber Ablehnung und Verlassenheit.<\/li>\n<\/ul>\n<p>In Jeremia 20,18 fasst er sein Leid zusammen:<\/p>\n<blockquote><p><strong>\u201eWarum bin ich aus dem Mutterleib hervorgekommen, um M\u00fchsal und Kummer zu sehen, um meine Tage in Schande zu verbringen?\u201c (Jeremia 20,18, Luther 2017)<\/strong><\/p><\/blockquote>\n<p>Sein Fluch \u00fcber den Tag seiner Geburt entsprang also einem tiefen Ort emotionaler Qual, geistlicher Ersch\u00f6pfung und menschlicher Schw\u00e4che.<\/p>\n<hr \/>\n<h3>Jeremia war damit nicht allein<\/h3>\n<p>Auch der Prophet Hiob verfluchte in einem \u00e4hnlichen Zustand der Verzweiflung seinen Geburtstag:<\/p>\n<blockquote><p><strong>Hiob 3,1\u20136 (Einheits\u00fcbersetzung)<\/strong><br \/>\n1 \u201eNach alledem \u00f6ffnete Hiob seinen Mund und fluchte den Tag seiner Geburt.<br \/>\n3 \u201aVernichtet sei der Tag, an dem ich geboren wurde, und die Nacht, die sprach: Ein Kind ist empfangen!<br \/>\n4 M\u00f6ge dieser Tag finster werden; Gott oben m\u00f6ge sich nicht darum k\u00fcmmern; kein Licht m\u00f6ge \u00fcber ihn scheinen.<br \/>\n5 Finsternis und tiefe Schw\u00e4rze m\u00f6gen ihn erneut erfassen; eine Wolke m\u00f6ge sich \u00fcber ihn legen; Dunkelheit ihn \u00fcberw\u00e4ltigen.<br \/>\n6 Die Nacht m\u00f6ge von dichtem Finsternis ergriffen werden; sie sei nicht unter den Tagen des Jahres und nicht in einen der Monate eingetragen.\u2018\u201c<\/p><\/blockquote>\n<p>Wie Jeremia litt auch Hiob unvorstellbar: Er hatte Kinder, Besitz, Gesundheit und sogar den Beistand seiner Frau und Freunde verloren.<\/p>\n<hr \/>\n<h3>War es richtig, dass sie ihre Geburtstage verfluchten?<\/h3>\n<p><strong>Die Antwort lautet: NEIN.<\/strong><br \/>\nObwohl menschlich verst\u00e4ndlich, steht das Verfluchen des eigenen Geburtstags nicht im Einklang mit Glauben, Vertrauen oder Ehrfurcht vor Gottes Souver\u00e4nit\u00e4t.<\/p>\n<p>Jeremia und Hiob \u00e4u\u00dferten keine theologischen Wahrheiten, sondern emotionale Reaktionen. Sie sprachen aus tiefer Verzweiflung, nicht aus g\u00f6ttlicher Einsicht. Hiob erkennt sp\u00e4ter seine Worte als fehlgeleitet:<\/p>\n<blockquote><p><strong>Hiob 42,3\u20136 (Luther 2017)<\/strong><br \/>\n3 \u201eWer ist der, der heimlich Rat gibt ohne Wissen?\u201c Darum habe ich geredet, was ich nicht verstand, Dinge, die zu wunderbar f\u00fcr mich waren, die ich nicht kannte.<br \/>\n5 \u201eIch hatte von dir nur vom H\u00f6rensagen geh\u00f6rt; nun aber hat mein Auge dich gesehen.<br \/>\n6 Darum verachte ich mich und bereue in Staub und Asche.\u201c<\/p><\/blockquote>\n<p>Auch Jeremia erkennt sp\u00e4ter seine Zweifel und Frustration an und wird von Gott zurechtgewiesen:<\/p>\n<blockquote><p><strong>Jeremia 15,18\u201319 (Luther 2017)<\/strong><br \/>\n18 \u201eWarum ist mein Schmerz unaufh\u00f6rlich und meine Wunde so schwer und unheilbar? Du bist mir wie ein tr\u00fcgerischer Bach, wie eine Quelle, die versagt.\u201c<br \/>\n19 Darum spricht der HERR: \u201eWenn du dich bekehrst, will ich dich wiederherstellen, dass du mir dienen kannst \u2026\u201c<\/p><\/blockquote>\n<hr \/>\n<h3>Was k\u00f6nnen wir daraus lernen?<\/h3>\n<p>Hiob und Jeremia waren gottesf\u00fcrchtige M\u00e4nner, dennoch erlebten sie unvorstellbares Leid. Ihr Schmerz f\u00fchrte sie dazu, Dinge zu sagen, die sie sp\u00e4ter bereuten. Gleichzeitig zeigt uns ihre Ehrlichkeit: Es ist erlaubt, unsere Gef\u00fchle vor Gott zu bringen.<\/p>\n<p>Wir sollten jedoch nicht unser Leben, unseren Geburtstag oder unsere Eltern verfluchen. Das ist eine Reaktion der Verzweiflung, nicht des Glaubens. Selbst Jesus warnte, dass Leiden Teil des Weges seiner Nachfolger ist:<\/p>\n<blockquote><p><strong>Matth\u00e4us 10,16\u201318 (Luther 2017)<\/strong><br \/>\n16 \u201eSiehe, ich sende euch wie Schafe mitten unter die W\u00f6lfe; seid darum klug wie die Schlangen und ohne Falsch wie die Tauben.<br \/>\n17 H\u00fctet euch aber vor den Menschen; denn sie werden euch den Gerichten ausliefern und in ihren Synagogen gei\u00dfeln.<br \/>\n18 Und ihr werdet vor Statthalter und K\u00f6nige gestellt werden um meinetwillen, als Zeugnis vor ihnen und den Heiden.\u201c<\/p><\/blockquote>\n<p>Leiden ist kein Zeichen der Ablehnung durch Gott, sondern oft ein Teil des L\u00e4uterungsprozesses. Wie Jakobus 1,2\u20134 uns erinnert, st\u00e4rken Pr\u00fcfungen unseren Glauben und Charakter:<\/p>\n<blockquote><p><strong>Jakobus 1,2\u20134 (Luther 2017)<\/strong><br \/>\n2 \u201eMeine Br\u00fcder, achtet es f\u00fcr lauter Freude, wenn ihr in mancherlei Versuchungen geratet,<br \/>\n3 da ihr ja wisst, dass die Bew\u00e4hrung eures Glaubens Standhaftigkeit wirkt.<br \/>\n4 Die Standhaftigkeit aber soll zu einem vollkommenen Werk f\u00fchren, damit ihr vollkommen und untadelig seid und es euch an nichts mangelt.\u201c<\/p><\/blockquote>\n<hr \/>\n<h3>Fazit<\/h3>\n<p>Es ist nicht richtig, den Tag unserer Geburt oder unser Leben zu verfluchen, selbst in gro\u00dfem Leid.<\/p>\n<p>Stattdessen sollten wir:<\/p>\n<ul>\n<li>Unser Leid ehrlich vor Gott bringen.<\/li>\n<li>Auf seinen gr\u00f6\u00dferen Plan vertrauen, auch wenn wir ihn nicht verstehen.<\/li>\n<li>Um Kraft beten, treu zu bleiben.<\/li>\n<li>Klagen und Fluchen vermeiden, da dies nutzlos ist (vgl. Philipper 2,14\u201315).<\/li>\n<\/ul>\n<blockquote><p><strong>Philipper 2,14\u201315 (Luther 2017)<\/strong><br \/>\n14 \u201eTut alles ohne Murren und Zanken,<br \/>\n15 damit ihr untadelig und lauter seid, Kinder Gottes ohne Tadel inmitten eines krummen und verkehrten Geschlechts, unter dem ihr leuchtet wie Sterne am Himmel.\u201c<\/p><\/blockquote>\n<p>Lernen wir also von Hiob und Jeremia \u2013 nicht nur von ihren Schw\u00e4chen, sondern auch von ihrer Wiederherstellung und Bu\u00dfe. Ihr Leben lehrt uns: Leiden bedeutet nicht Verlassenheit, und Glaube wird oft im Feuer der Pr\u00fcfungen geformt.<\/p>\n<p>M\u00f6ge der Herr uns helfen, im Glauben standhaft zu bleiben, selbst in Zeiten gro\u00dfer Bedr\u00e4ngnis. Amen.<\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Warum verfluchte der Prophet Jeremia den Tag seiner Geburt \u2013 und ist es richtig, dass wir unsere eigenen Geburtstage verfluchen?' data-link='https:\/\/wingulamashahidi.org\/de\/2025\/09\/09\/warum-verfluchte-der-prophet-jeremia-den-tag-seiner-geburt-und-ist-es-richtig-dass-wir-unsere-eigenen-geburtstage-verfluchen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Antwort: Beginnen wir mit einem Blick in die Heilige Schrift, insbesondere Jeremia 20,14\u201317: Jeremia 20,14\u201317 (Luther 2017) 14 \u201eVerflucht sei der Tag<\/p>\n","protected":false},"author":1198,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-58049","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"6tpYDtjPjo\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2025\/09\/09\/warum-verfluchte-der-prophet-jeremia-den-tag-seiner-geburt-und-ist-es-richtig-dass-wir-unsere-eigenen-geburtstage-verfluchen\/\">Warum verfluchte der Prophet Jeremia den Tag seiner Geburt \u2013 und ist es richtig, dass wir unsere eigenen Geburtstage verfluchen?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2025\/09\/09\/warum-verfluchte-der-prophet-jeremia-den-tag-seiner-geburt-und-ist-es-richtig-dass-wir-unsere-eigenen-geburtstage-verfluchen\/embed\/#?secret=6tpYDtjPjo\" width=\"500\" height=\"350\" title=\"&#8222;Warum verfluchte der Prophet Jeremia den Tag seiner Geburt \u2013 und ist es richtig, dass wir unsere eigenen Geburtstage verfluchen?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"6tpYDtjPjo\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=58049"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58049\/revisions"}],"predecessor-version":[{"id":58051,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58049\/revisions\/58051"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=58049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=58049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=58049"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=58049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}