{"id":58351,"date":"2019-01-02T06:47:56","date_gmt":"2019-01-02T03:47:56","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=58351"},"modified":"2025-10-08T12:25:25","modified_gmt":"2025-10-08T09:25:25","slug":"das-werk-gottes-und-sein-allumfassender-plan","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/","title":{"rendered":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<p>Als Christen, die auf den Herrn warten, ist es unsere t\u00e4gliche Verantwortung, den Blick zum Himmel zu erheben und die Heilige Schrift sorgf\u00e4ltig zu studieren, um die Zeichen der letzten Tage und das Kommen Christi zu erkennen. Wer ein flei\u00dfiger Sch\u00fcler des Wortes ist, wird feststellen, dass die Generation, in der wir leben, genau die ist, die das zweite Kommen Christi erleben wird.<\/p>\n<p>Zwei entscheidende Gr\u00fcnde best\u00e4tigen dies:<\/p>\n<ol>\n<li>Dies ist die Generation, die die Wiedergeburt des \u201eFeigenbaums\u201c erlebt, ein Symbol f\u00fcr das Volk Israel (Matth\u00e4us 24,32\u201334).<\/li>\n<li>Wir leben in der siebten und letzten \u00c4ra der Kirche, wie in Offenbarung 2 und 3 beschrieben, die mit der Entr\u00fcckung endet. Danach wird es keine weitere Kirchen\u00e4ra geben. Diese letzte \u00c4ra begann zu Beginn des 20. Jahrhunderts (ca. 1900) und wird mit der Entr\u00fcckung der Kirche ihren H\u00f6hepunkt erreichen.<\/li>\n<\/ol>\n<hr \/>\n<p>Dar\u00fcber hinaus sagt die Bibel voraus, dass der Glaube zun\u00e4chst in der Braut Christi offenbar werden muss, bevor sie zum Hochzeitsmahl des Lammes in den Himmel aufgenommen wird (Lukas 18,8). Nur durch diesen Glauben wird sie w\u00fcrdig sein, entr\u00fcckt zu werden; andernfalls kann die Kirche nicht die geistliche Reife erreichen, die Gott w\u00fcnscht. Damit dies geschehen kann, muss zuerst eine gro\u00dfe Erweckung und Ausgie\u00dfung des Heiligen Geistes erfolgen, damit Gottes Auserw\u00e4hlte die Vollkommenheit erlangen, die Er in Seiner Kirche erwartet.<\/p>\n<p>Joel 2,23 sagt:<\/p>\n<blockquote>\n<p>\u201eSeid fr\u00f6hlich, ihr Kinder Zions, und freut euch in dem Herrn, eurem Gott! Denn er gibt euch den Fr\u00fchregen nach Gerechtigkeit, er l\u00e4sst euch Regen fallen, Fr\u00fch- und Sp\u00e4tregen, wie zuvor.\u201c<\/p>\n<\/blockquote>\n<p>Hier spricht die Bibel vom <strong>Fr\u00fchregen<\/strong> und vom <strong>Sp\u00e4tregen<\/strong>. Der Fr\u00fchregen fiel am Pfingsttag und markierte die Geburt der Kirche (Apostelgeschichte 2). Doch es wird auch einen letzten Ausguss geben, den Sp\u00e4tregen, der die Kirche vor ihrem Abgang aus dieser Welt vervollkommnet. Seine Herrlichkeit wird die der ersten Kirche \u00fcbertreffen. Haggai 2,9 best\u00e4tigt:<\/p>\n<blockquote>\n<p>\u201eDenn die Herrlichkeit dieses letzten Hauses wird gr\u00f6\u00dfer sein als die der fr\u00fcheren\u201c, spricht der HERR Zebaoth.<\/p>\n<\/blockquote>\n<p>Diese letzte Erweckung wird Kr\u00e4fte zeigen, wie sie die Kirche seit Pfingsten nicht mehr erlebt hat. Die geistlichen Gaben und Werke des Heiligen Geistes, die Joel vorausgesagt hat, werden in voller Kraft erscheinen. Joel 2,28\u201332 sagt:<\/p>\n<blockquote>\n<p>\u201eUnd danach wird es geschehen, dass ich meinen Geist ausgie\u00dfen werde \u00fcber alles Fleisch; eure S\u00f6hne und T\u00f6chter werden weissagen, eure Alten werden Tr\u00e4ume haben, eure J\u00fcnglinge werden Visionen sehen. Auch \u00fcber Knechte und M\u00e4gde will ich meinen Geist ausgie\u00dfen in jenen Tagen. Und ich werde Wunder tun am Himmel und auf der Erde: Blut, Feuer und Rauchwolken. Die Sonne wird sich in Finsternis verwandeln und der Mond in Blut, bevor der gro\u00dfe und schreckliche Tag des Herrn kommt. Und es wird geschehen, dass jeder, der den Namen des Herrn anruft, gerettet wird.\u201c<\/p>\n<\/blockquote>\n<p>W\u00e4hrend ein Teil dieser Prophezeiung bereits in Visionen, Tr\u00e4umen und Weissagungen erf\u00fcllt wurde, werden die himmlischen Zeichen \u2013 Blut, Feuer, Dunkelheit und kosmische Ph\u00e4nomene \u2013 w\u00e4hrend dieser letzten Erweckung auftreten. Offenbarung 10 spricht ebenfalls von sieben Donnerschl\u00e4gen, deren Botschaften nur der Braut Christi offenbart werden. Au\u00dfenstehende h\u00f6ren nur das Donnern, verstehen aber nichts.<\/p>\n<hr \/>\n<h3><strong>Die Lehre f\u00fcr Heute<\/strong><\/h3>\n<p>Selbst die J\u00fcnger, nachdem sie die Auferstehung Christi und seine Autorit\u00e4t \u00fcber alles gesehen hatten, hatten Schwierigkeiten, Gottes Zeitplan zu verstehen. Sie dachten, das Reich des Messias w\u00fcrde Israel sofort wiederherstellen und die Nationen bestrafen. Sie konzentrierten sich nur auf ihr eigenes Volk, nicht auf die gr\u00f6\u00dfere Mission der Rettung aller Menschen.<\/p>\n<p>Apostelgeschichte 1,6\u20138 sagt:<\/p>\n<blockquote>\n<p>\u201eAls sie aber beisammen waren, fragten sie ihn: Herr, stellst du in dieser Zeit das Reich f\u00fcr Israel wieder her?<br \/>Er aber sprach zu ihnen: Es liegt nicht an euch, die Zeiten oder Zeitpunkte zu wissen, die der Vater in seiner eigenen Macht bestimmt hat. Aber ihr werdet Kraft empfangen, wenn der Heilige Geist auf euch kommt; und ihr werdet meine Zeugen sein in Jerusalem, in ganz Jud\u00e4a und Samaria und bis an das Ende der Erde.\u201c<\/p>\n<\/blockquote>\n<p>Wir leben in derselben Zeit, in der die Ernte reif ist. Deshalb m\u00fcssen wir uns darauf konzentrieren, jetzt Frucht f\u00fcr Gott zu bringen, anstatt auf einen zuk\u00fcnftigen Ausguss zu warten. Viele verschieben den Dienst, warten auf den \u201eperfekten Zeitpunkt\u201c und erreichen dadurch wenig f\u00fcr das Reich Gottes. Prediger 11,4\u20136 warnt:<\/p>\n<blockquote>\n<p>\u201eWer den Wind beobachtet, wird nicht s\u00e4en, und wer die Wolken anschaut, wird nicht ernten. Wie du den Weg des Windes nicht kennst und nicht wei\u00dft, wie die Knochen im Leib der Mutter sich bilden, so kennst du das Werk Gottes nicht, der alles macht. S\u00e4e dein Korn am Morgen und halte deine Hand nicht zur\u00fcck am Abend, denn du wei\u00dft nicht, welches Gelingen wird \u2013 dies oder das, oder ob beides gleich gut sein wird.\u201c<\/p>\n<\/blockquote>\n<p>Gottes Werk kann nicht vorhergesagt werden; es liegt jenseits menschlichen Verstehens (Prediger 9,11; R\u00f6mer 11,33). Wenn Gott uns das Privileg gibt, seine Zeugen zu sein, m\u00fcssen wir flei\u00dfig arbeiten und heute so viele Fr\u00fcchte wie m\u00f6glich bringen, anstatt auf den \u201erichtigen Moment\u201c zu warten.<\/p>\n<hr \/>\n<h3><strong>Fazit<\/strong><\/h3>\n<p>Warte nicht auf den Sp\u00e4tregen, um Gott zu dienen. Beginne jetzt. Suche Seinen Willen heute.\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN' data-link='https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 Als Christen, die auf den Herrn warten, ist es unsere t\u00e4gliche Verantwortung, den Blick zum Himmel zu erheben und die Heilige Schrift sorgf\u00e4ltig zu st<\/p>\n","protected":false},"author":1236,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-58351","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"JWZonjeI2g\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/\">DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/embed\/#?secret=JWZonjeI2g\" width=\"500\" height=\"350\" title=\"&#8222;DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"JWZonjeI2g\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Als Christen, die auf den Herrn warten, ist es unsere t\u00e4gliche Verantwortung, den Blick zum Himmel zu erheben und die Heilige Schrift sorgf\u00e4ltig zu st\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-02T03:47:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T09:25:25+00:00\" \/>\n<meta name=\"author\" content=\"Huruma Kalaita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Huruma Kalaita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/\"},\"author\":{\"name\":\"Huruma Kalaita\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/af08d232aaaa9610b00c942ed8d751a7\"},\"headline\":\"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN\",\"datePublished\":\"2019-01-02T03:47:56+00:00\",\"dateModified\":\"2025-10-08T09:25:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/\"},\"wordCount\":884,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/\",\"name\":\"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"datePublished\":\"2019-01-02T03:47:56+00:00\",\"dateModified\":\"2025-10-08T09:25:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/01\\\/02\\\/das-werk-gottes-und-sein-allumfassender-plan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/af08d232aaaa9610b00c942ed8d751a7\",\"name\":\"Huruma Kalaita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g\",\"caption\":\"Huruma Kalaita\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/","og_locale":"de_DE","og_type":"article","og_title":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title","og_description":"\u00a0 Als Christen, die auf den Herrn warten, ist es unsere t\u00e4gliche Verantwortung, den Blick zum Himmel zu erheben und die Heilige Schrift sorgf\u00e4ltig zu st","og_url":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2019-01-02T03:47:56+00:00","article_modified_time":"2025-10-08T09:25:25+00:00","author":"Huruma Kalaita","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Huruma Kalaita","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/"},"author":{"name":"Huruma Kalaita","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/af08d232aaaa9610b00c942ed8d751a7"},"headline":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN","datePublished":"2019-01-02T03:47:56+00:00","dateModified":"2025-10-08T09:25:25+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/"},"wordCount":884,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/","url":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/","name":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"datePublished":"2019-01-02T03:47:56+00:00","dateModified":"2025-10-08T09:25:25+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/01\/02\/das-werk-gottes-und-sein-allumfassender-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"DAS WERK GOTTES UND SEIN ALLUMFASSENDER PLAN"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/af08d232aaaa9610b00c942ed8d751a7","name":"Huruma Kalaita","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2551c24e2bf313cf35a25165afaf4d82bc57be2b30bc257a5cc6f0773450e4?s=96&d=mm&r=g","caption":"Huruma Kalaita"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1236"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=58351"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58351\/revisions"}],"predecessor-version":[{"id":58352,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58351\/revisions\/58352"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=58351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=58351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=58351"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=58351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}