{"id":58569,"date":"2025-03-13T09:49:00","date_gmt":"2025-03-13T06:49:00","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=58569"},"modified":"2025-10-10T09:14:56","modified_gmt":"2025-10-10T06:14:56","slug":"58569","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/","title":{"rendered":"ELOI, ELOI, LAMA SABAKTHANI?"},"content":{"rendered":"<hr \/>\n<p><strong>Psalm 22,1<\/strong><br \/>\n<em>Mein Gott, mein Gott, warum hast du mich verlassen?<\/em><br \/>\nWarum bist du so fern von meiner Rettung,<br \/>\nvon den Worten meines Schmerzes?<br \/>\n2 <em>Mein Gott, ich rufe am Tag, doch du antwortest nicht,<br \/>\nund auch des Nachts finde ich keine Ruhe.<\/em><\/p>\n<p>Wenn man \u00fcber diese Worte nachdenkt, erkennt man, dass sie von einem Menschen stammen, der in eine so tiefe Verzweiflung geraten ist, dass er fast die Hoffnung verliert. Gr\u00fcnde daf\u00fcr k\u00f6nnen schwere Leiden, Traurigkeit oder unerkl\u00e4rliches Leid sein. Er schaut nach rechts und sieht keinen Funken Hoffnung, blickt nach links und findet keine helfende Hand Gottes, obwohl er lange gebetet und geweint hat.<\/p>\n<p>An anderer Stelle hei\u00dft es, er wurde \u00fcberall abgelehnt, sogar von seinen eigenen Verwandten.<\/p>\n<p><strong>Psalm 69,10-17<\/strong><br \/>\n10 <em>Ich weinte und strafte meine Seele durch Fasten;<br \/>\ndas wurde mir zum Spott.<\/em><br \/>\n11 <em>Als ich Sackkleider trug, wurde ich zu einem Sprichwort f\u00fcr sie.<\/em><br \/>\n12 <em>Die am Tor sitzen, reden \u00fcber mich, und die Trunkenbolde spotten mich.<\/em><br \/>\n13 <em>Aber ich bete zu dir, Herr, zur rechten Zeit;<br \/>\no Gott, in deiner gro\u00dfen G\u00fcte,<br \/>\nerh\u00f6re mich in der Wahrheit deines Heils!<\/em><\/p>\n<p>14 <em>Errette mich aus dem Schlamm, dass ich nicht versinke;<br \/>\nrette mich vor meinen Feinden und aus den tiefen Wassern!<\/em><br \/>\n15 <em>Lass den Strom mich nicht verschlingen,<br \/>\nund lass den Abgrund seinen Rachen nicht \u00fcber mich \u00f6ffnen!<\/em><br \/>\n16 <em>H\u00f6re mich, Herr, denn deine G\u00fcte ist freundlich;<br \/>\nwende dich mir zu nach der F\u00fclle deiner Barmherzigkeit!<\/em><br \/>\n17 <em>Verberge dein Antlitz nicht vor deinem Knecht,<br \/>\ndenn ich bin elend; erh\u00f6re mich bald!<\/em><\/p>\n<p>Der Verfasser dieser Psalmen war David. Er durchlebte eine lange Zeit, in der er sich f\u00fchlte, als h\u00e4tte Gott ihn verlassen. Es gab sogar Momente, in denen er dachte, es w\u00e4re besser, Zuflucht bei seinen Feinden, den Philistern, zu suchen \u2013 jenen, die er einst vertrieben und als Ungl\u00e4ubige bezeichnet hatte. Dieses Mal jedoch ging er mit Demut, um unter ihnen Schutz zu finden, um nicht v\u00f6llig zugrunde zu gehen. Er war wirklich am Ende seiner Kr\u00e4fte.<\/p>\n<p>Es ist nicht so, dass er nicht betete oder Gott nicht vertraute. Auch war er nicht s\u00fcndiger als andere, um solches Ungl\u00fcck zu verdienen. Er war stets ein Beter, doch in seiner menschlichen Realit\u00e4t f\u00fchlte er sich verlassen.<\/p>\n<p>Aber weil Gottes Barmherzigkeit gro\u00df ist, schenkte sie ihm den Mut, weiterhin auf den Herrn zu warten. Deshalb betont David an vielen Stellen in den Psalmen: <em>\u201eHoffet auf den Herrn!\u201c<\/em> (Psalm 37,7; 25,3; 31,24; 38,15; 40,1).<\/p>\n<p>Eines der wenigen Worte Davids, die Jesus zitierte, war dieses:<\/p>\n<p><em>\u201eMein Gott, mein Gott, warum hast du mich verlassen?\u201c<\/em><\/p>\n<p><strong>Matth\u00e4us 27,45-46<\/strong><br \/>\n<em>Ab der sechsten Stunde trat eine Finsternis \u00fcber das ganze Land ein bis zur neunten Stunde.<\/em><br \/>\n<em>Um die neunte Stunde schrie Jesus laut: \u201eEloi, Eloi, lama sabakthani?\u201c \u2013 das hei\u00dft: \u201eMein Gott, mein Gott, warum hast du mich verlassen?\u201c<\/em><\/p>\n<p>Glaubst du, dass Jesus mit diesen Worten wirklich meinte, Gott h\u00e4tte ihn im Stich gelassen?<\/p>\n<p>Nein! Von Anfang an wusste er, dass Gott bei ihm war. Seine Stunde war nahe, bald w\u00fcrde er erh\u00f6ht und verherrlicht werden. An anderer Stelle sagt er, er habe vom Kreuz aus geschaut (Kolosser 2,15). Doch er zitierte diese Worte, um unsere Menschlichkeit zu zeigen. Sie sprechen zu uns mitten in unserem Leid und sagen uns: Gott verl\u00e4sst uns nicht, auch wenn es sich manchmal so anf\u00fchlt.<\/p>\n<p>Jesus nahm unser menschliches Gef\u00fchl der Verlassenheit auf und erinnerte an das, was David erlebte.<\/p>\n<p>Wenige Minuten nach diesen Worten, als er seinen Geist aufgab, \u00f6ffneten sich die Gr\u00e4ber, viele Heilige wurden auferweckt, der Vorhang im Tempel zerriss \u2013 und nach drei Tagen stand Jesus von den Toten auf. Unser gro\u00dfer Erl\u00f6ser war gefunden!<\/p>\n<p><strong>Matth\u00e4us 27,50-53<\/strong><br \/>\n50 <em>Jesus schrie noch einmal laut auf und hauchte dann den Geist aus.<\/em><br \/>\n51 <em>Und siehe, der Vorhang im Tempel zerriss von oben bis unten; die Erde erbebte, die Felsen zerspalten.<\/em><br \/>\n52 <em>Die Gr\u00e4ber \u00f6ffneten sich, und viele Heilige, die schliefen, wurden auferweckt.<\/em><br \/>\n53 <em>Nach seiner Auferstehung gingen sie in die heilige Stadt und erschienen vielen.<\/em><\/p>\n<p>Liebe Freunde, wenn du gerade an dem Punkt bist, an dem dein Verstand dir sagt, Gott sei nicht mehr bei dir, er habe dich verlassen wegen langer Leiden, unheilbarer Krankheiten, st\u00e4ndigen Betens und Weinens ohne Antwort, dann \u2013 halte durch! Warte auf den Herrn. David hat es ausgehalten und wurde schlie\u00dflich best\u00e4tigt als K\u00f6nig, dessen Herrschaft viele Generationen \u00fcberdauerte \u2013 im Gegensatz zu anderen K\u00f6nigen Israels.<\/p>\n<p>Warte auf den Herrn! Betend, denn nach der Hitze kommt der Regen.<\/p>\n<p>Shalom.<\/p>\n<p>Teile diese frohe Botschaft gern mit anderen!<\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='ELOI, ELOI, LAMA SABAKTHANI?' data-link='https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Psalm 22,1 Mein Gott, mein Gott, warum hast du mich verlassen? Warum bist du so fern von meiner Rettung, von den Worten meines Schmerzes? 2 Mein Gott, ich rufe am Tag, doch du antwortest nicht, und auch des Nachts finde ich keine Ruhe. Wenn man \u00fcber diese Worte nachdenkt, erkennt man, dass sie von einem [&hellip;]<\/p>\n","protected":false},"author":1237,"featured_media":58570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-58569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"yFYJlwMJEa\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/\">ELOI, ELOI, LAMA SABAKTHANI?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/embed\/#?secret=yFYJlwMJEa\" width=\"500\" height=\"350\" title=\"&#8222;ELOI, ELOI, LAMA SABAKTHANI?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"yFYJlwMJEa\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Psalm 22,1 Mein Gott, mein Gott, warum hast du mich verlassen? Warum bist du so fern von meiner Rettung, von den Worten meines Schmerzes? 2 Mein Gott, ich rufe am Tag, doch du antwortest nicht, und auch des Nachts finde ich keine Ruhe. Wenn man \u00fcber diese Worte nachdenkt, erkennt man, dass sie von einem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T06:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T06:14:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janet Mushi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janet Mushi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/\"},\"author\":{\"name\":\"Janet Mushi\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/2e95ae9e2f2efc156e737ec0f68e5ff6\"},\"headline\":\"ELOI, ELOI, LAMA SABAKTHANI?\",\"datePublished\":\"2025-03-13T06:49:00+00:00\",\"dateModified\":\"2025-10-10T06:14:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/\"},\"wordCount\":765,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/JesusOnCross_01.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/\",\"name\":\"ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/JesusOnCross_01.jpg\",\"datePublished\":\"2025-03-13T06:49:00+00:00\",\"dateModified\":\"2025-10-10T06:14:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/JesusOnCross_01.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/JesusOnCross_01.jpg\",\"width\":300,\"height\":410,\"caption\":\"ELOI ELOI LAMA SABAKTHANI?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2025\\\/03\\\/13\\\/58569\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELOI, ELOI, LAMA SABAKTHANI?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/2e95ae9e2f2efc156e737ec0f68e5ff6\",\"name\":\"Janet Mushi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g\",\"caption\":\"Janet Mushi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/","og_locale":"de_DE","og_type":"article","og_title":"ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title","og_description":"Psalm 22,1 Mein Gott, mein Gott, warum hast du mich verlassen? Warum bist du so fern von meiner Rettung, von den Worten meines Schmerzes? 2 Mein Gott, ich rufe am Tag, doch du antwortest nicht, und auch des Nachts finde ich keine Ruhe. Wenn man \u00fcber diese Worte nachdenkt, erkennt man, dass sie von einem [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2025-03-13T06:49:00+00:00","article_modified_time":"2025-10-10T06:14:56+00:00","og_image":[{"width":300,"height":410,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","type":"image\/jpeg"}],"author":"Janet Mushi","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Janet Mushi","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/"},"author":{"name":"Janet Mushi","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/2e95ae9e2f2efc156e737ec0f68e5ff6"},"headline":"ELOI, ELOI, LAMA SABAKTHANI?","datePublished":"2025-03-13T06:49:00+00:00","dateModified":"2025-10-10T06:14:56+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/"},"wordCount":765,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/","url":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/","name":"ELOI, ELOI, LAMA SABAKTHANI? &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","datePublished":"2025-03-13T06:49:00+00:00","dateModified":"2025-10-10T06:14:56+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2025\/03\/JesusOnCross_01.jpg","width":300,"height":410,"caption":"ELOI ELOI LAMA SABAKTHANI?"},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2025\/03\/13\/58569\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\/"},{"@type":"ListItem","position":2,"name":"ELOI, ELOI, LAMA SABAKTHANI?"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/2e95ae9e2f2efc156e737ec0f68e5ff6","name":"Janet Mushi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6735610684ce4ee8114e803a26feebf466a0b3d2d7f548c3485c3a3d4c6f717?s=96&d=mm&r=g","caption":"Janet Mushi"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1237"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=58569"}],"version-history":[{"count":2,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58569\/revisions"}],"predecessor-version":[{"id":58572,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/58569\/revisions\/58572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/58570"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=58569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=58569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=58569"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=58569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}