{"id":59106,"date":"2022-01-06T08:29:50","date_gmt":"2022-01-06T05:29:50","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=59106"},"modified":"2025-10-14T11:20:59","modified_gmt":"2025-10-14T08:20:59","slug":"schweres-gericht-gottes-wen-trifft-es-und-wie","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/","title":{"rendered":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?"},"content":{"rendered":"<p>Spr\u00fcche 15,10a: \u201eStrenge trifft den, der den Weg verl\u00e4sst&#8230;\u201c<\/p>\n<p>Gottes Strafen unterscheiden sich von Person zu Person. Anders als viele denken, wird nicht der M\u00f6rder am Tag des Gerichts am st\u00e4rksten bestraft, sondern derjenige, der das Heil verlassen hat.<\/p>\n<p>Die Antwort ist eindeutig! Die Schrift sagt: \u201eStrenge trifft den, der den Weg verl\u00e4sst\u201c \u2013 es spricht nicht nur von irgendeiner Strafe, sondern von strenger Strafe.<\/p>\n<p>Jesus wiederholte diese Worte in Lukas 12,47-48:<\/p>\n<blockquote><p>\u201eDer Knecht, der die W\u00fcnsche seines Herrn kennt und sie nicht erf\u00fcllt, wird hart geschlagen.<br \/>\nWer sie aber nicht kennt und trotzdem das tut, was Strafe verdient, wird leicht bestraft. Wem viel gegeben wurde, von dem wird man viel verlangen; und wem viel anvertraut wurde, von dem wird man umso mehr fordern.\u201c<\/p><\/blockquote>\n<p>Heutzutage ist es traurig zu sehen, dass viele Menschen mit ihrem Mund behaupten, sie seien gerettet, aber in Wirklichkeit weit von Christus entfernt sind. Sie sind Christen, die den Weg verlassen haben, oder die den Willen des Herrn kennen, aber nicht danach handeln.<\/p>\n<p>Sie wissen, dass das Anschauen von Pornografie Gott missf\u00e4llt \u2013 und tun es trotzdem. Sie leben mit einem Ehepartner, der nicht ihr geistlicher Partner ist, und begehen damit S\u00fcnde, oft sogar mit Kindern. Sie wissen, dass halbnackte Kleidung und entbl\u00f6\u00dfende Handlungen s\u00fcndhaft sind, tun es aber weiterhin. Auch Pastoren und Diener wissen, dass Ehebruch und Unzucht schwere S\u00fcnden sind, doch viele haben sie zur Gewohnheit gemacht. Diese Menschen werden laut Jesus schwere Strafe in der H\u00f6lle erleiden.<\/p>\n<p>Bruder\/Schwester, miss die dortigen Qualen nicht mit deinem Verstand \u2013 selbst die Leidenden dort w\u00fcnschen sich nicht, dass du dort hingelangst. Es sind unvorstellbare, extreme Schmerzen (vgl. Lukas 16,27-29).<\/p>\n<p>Deshalb sagte Jesus:<\/p>\n<p>Markus 9,45-48:<\/p>\n<blockquote><p>\u201eWenn dein Fu\u00df dich zum S\u00fcndigen bringt, haue ihn ab; es ist besser, hinkend ins Leben einzugehen, als mit beiden F\u00fc\u00dfen in die H\u00f6lle geworfen zu werden, wo ihre W\u00fcrmer nicht sterben und das Feuer nicht erlischt.<br \/>\nWenn dein Auge dich zum S\u00fcndigen bringt, rei\u00df es aus; es ist besser, ein\u00e4ugig in das Reich Gottes einzugehen, als mit beiden Augen in die H\u00f6lle geworfen zu werden.\u201c<\/p><\/blockquote>\n<p>Bruder\/Schwester, wenn du das Evangelium h\u00f6rst und nicht danach handelst, wird es zur Strafe f\u00fcr dich. Je l\u00e4nger du es h\u00f6rst und nicht lebst, desto mehr Strafe h\u00e4ufst du auf dich. Sch\u00e4tze dein geistliches Leben \u2013 diese Zeiten sind die letzten Tage. Der Tod kommt pl\u00f6tzlich, ohne Vorwarnung. Bist du bereit, was du geh\u00f6rt hast, in die Tat umzusetzen?<\/p>\n<p>Es ist besser, dein Leben heute dem Herrn zu \u00fcbergeben, gerettet zu werden und Ihm zu folgen, ohne Kompromisse. Lege die verg\u00e4nglichen Dinge der Welt beiseite und strebe nach Heiligkeit, denn ohne sie wird niemand den Himmel sehen (Hebr\u00e4er 12,14).<\/p>\n<p>Wenn du heute Bu\u00dfe tun und dein Leben mit dem Herrn neu beginnen willst, ist Er bereit, dich zu vergeben. Sprich dieses kurze Gebet im Glauben:<\/p>\n<p>**VATER, ICH KOMME VOR DICH. ICH GEBE ZU, DASS ICH LANGE ZEIT DEIN UNGEHORSAMES KIND WAR, VIELE S\u00dcNDEN BEGANGEN HABE UND HART STRAFE VERDIENE. ICH HABE DEINEN WILLEN GEKANNT, ABER NICHT GEHANDELT. AB HEUTE BIN ICH BEREIT, MEIN LEBEN NEU MIT DIR ZU BEGINNEN. BITTE, VERGIB MIR, VATER.<br \/>\nICH VERLASSE ALLE B\u00d6SEN WEGE, LEHNE DEN TEUFEL UND SEINE WERKE AB, VERZICHTE AUF DIE WELT. DURCH DAS BLUT JESU CHRISTI, REINIGE MICH UND HEILIGE MICH VOLLST\u00c4NDIG.<br \/>\nDANKE, HERR JESUS, DASS DU MIR VERGIBST. ICH GLAUBE, DASS DU MICH ANGENOMMEN HAST UND MICH HEUTE ZU EINEM NEUEN MENSCHEN GEMACHT HAST. GIB MIR DIE KRAFT, DER WELT ZU WIDERSTEHEN UND MEIN HEIL ZU BEWAHREN. AMEN.\u201c<\/p>\n<p>Wenn du dieses Gebet aus Glauben sprichst, schaut Gott auf dein Herz, nicht nur auf die Worte. Eine Frau, die viele S\u00fcnden begangen hatte, wurde allein durch ihre aufrichtige Hingabe an Jesus sofort vergeben, bevor sie ein Wort sprach (vgl. Lukas 7,36-50).<\/p>\n<p>Wenn deine Bu\u00dfe ehrlich ist \u2013 getrennt von der falschen Beziehung, ohne Pornografie und S\u00fcnde \u2013 wird Gott sie annehmen. Beginne heute, ein Leben in Rettung zu f\u00fchren. Wenn du noch nicht getauft bist, solltest du dich taufen lassen. Wir helfen dir gern unter: +255693036618 \/ +255789001312<\/p>\n<p>F\u00fcr t\u00e4gliche Lehre per WhatsApp tritt unserem Kanal bei: https:\/\/whatsapp.com\/channel\/0029VaBVhuA3WHTbKoz8jx10<\/p>\n<p>Gott segne dich reichlich!<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?' data-link='https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Spr\u00fcche 15,10a: \u201eStrenge trifft den, der den Weg verl\u00e4sst&#8230;\u201c Gottes Strafen unterscheiden sich von Person zu Person. Anders als viele denken, wird nicht der M\u00f6rder am Tag des Gerichts am st\u00e4rksten bestraft, sondern derjenige, der das Heil verlassen hat. Die Antwort ist eindeutig! Die Schrift sagt: \u201eStrenge trifft den, der den Weg verl\u00e4sst\u201c \u2013 es [&hellip;]<\/p>\n","protected":false},"author":1235,"featured_media":59107,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-59106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"4rhBDiEM2P\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/\">SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/embed\/#?secret=4rhBDiEM2P\" width=\"500\" height=\"350\" title=\"&#8222;SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"4rhBDiEM2P\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Spr\u00fcche 15,10a: \u201eStrenge trifft den, der den Weg verl\u00e4sst&#8230;\u201c Gottes Strafen unterscheiden sich von Person zu Person. Anders als viele denken, wird nicht der M\u00f6rder am Tag des Gerichts am st\u00e4rksten bestraft, sondern derjenige, der das Heil verlassen hat. Die Antwort ist eindeutig! Die Schrift sagt: \u201eStrenge trifft den, der den Weg verl\u00e4sst\u201c \u2013 es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T05:29:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T08:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"226\" \/>\n\t<meta property=\"og:image:height\" content=\"223\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Neema Joshua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Neema Joshua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/\"},\"author\":{\"name\":\"Neema Joshua\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\"},\"headline\":\"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?\",\"datePublished\":\"2022-01-06T05:29:50+00:00\",\"dateModified\":\"2025-10-14T08:20:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/\"},\"wordCount\":731,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/images.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/\",\"name\":\"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/images.jpg\",\"datePublished\":\"2022-01-06T05:29:50+00:00\",\"dateModified\":\"2025-10-14T08:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/images.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/images.jpg\",\"width\":226,\"height\":223,\"caption\":\"ADHABU KALI KUTOKA KWA MUNGU, ITAMPATA MTU WA NAMNA GANI?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2022\\\/01\\\/06\\\/schweres-gericht-gottes-wen-trifft-es-und-wie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/c40010f860f462846c8f7de34553af3a\",\"name\":\"Neema Joshua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g\",\"caption\":\"Neema Joshua\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/","og_locale":"de_DE","og_type":"article","og_title":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title","og_description":"Spr\u00fcche 15,10a: \u201eStrenge trifft den, der den Weg verl\u00e4sst&#8230;\u201c Gottes Strafen unterscheiden sich von Person zu Person. Anders als viele denken, wird nicht der M\u00f6rder am Tag des Gerichts am st\u00e4rksten bestraft, sondern derjenige, der das Heil verlassen hat. Die Antwort ist eindeutig! Die Schrift sagt: \u201eStrenge trifft den, der den Weg verl\u00e4sst\u201c \u2013 es [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2022-01-06T05:29:50+00:00","article_modified_time":"2025-10-14T08:20:59+00:00","og_image":[{"width":226,"height":223,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","type":"image\/jpeg"}],"author":"Neema Joshua","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Neema Joshua","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/"},"author":{"name":"Neema Joshua","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a"},"headline":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?","datePublished":"2022-01-06T05:29:50+00:00","dateModified":"2025-10-14T08:20:59+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/","url":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/","name":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE? &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","datePublished":"2022-01-06T05:29:50+00:00","dateModified":"2025-10-14T08:20:59+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2022\/01\/images.jpg","width":226,"height":223,"caption":"ADHABU KALI KUTOKA KWA MUNGU, ITAMPATA MTU WA NAMNA GANI?"},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2022\/01\/06\/schweres-gericht-gottes-wen-trifft-es-und-wie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\/"},{"@type":"ListItem","position":2,"name":"SCHWERES GERICHT GOTTES \u2013 WEN TRIFFT ES UND WIE?"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/c40010f860f462846c8f7de34553af3a","name":"Neema Joshua","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0cf7e93d0f028b8e2d0351b53eb43a1875e4bbed4de43beeed3bec8fa7b329?s=96&d=mm&r=g","caption":"Neema Joshua"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1235"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=59106"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59106\/revisions"}],"predecessor-version":[{"id":59108,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59106\/revisions\/59108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/59107"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=59106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=59106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=59106"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=59106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}