{"id":59266,"date":"2018-10-05T13:23:13","date_gmt":"2018-10-05T10:23:13","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=59266"},"modified":"2025-10-15T19:17:04","modified_gmt":"2025-10-15T16:17:04","slug":"kriterien-um-jesus-christus-in-der-kuenftigen-welt-nahe-zu-sein","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2018\/10\/05\/kriterien-um-jesus-christus-in-der-kuenftigen-welt-nahe-zu-sein\/","title":{"rendered":"KRITERIEN, UM JESUS CHRISTUS IN DER K\u00dcNFTIGEN WELT NAHE ZU SEIN"},"content":{"rendered":"<hr \/>\n<h3><\/h3>\n<p>Als der damalige US-Pr\u00e4sident Barack Obama im Jahr 2013 Tansania besuchte, war vielen klar, dass es fast unm\u00f6glich sein w\u00fcrde, mit ihm an einem Tisch zu sitzen oder ihm pers\u00f6nlich die Hand zu sch\u00fctteln. Und doch hielten es viele bereits f\u00fcr ein gro\u00dfes Gl\u00fcck, wenn sie wenigstens seinen Konvoi auf der Stra\u00dfe vorbeifahren sehen konnten. Allein das reichte aus, damit sie sich als besonders beg\u00fcnstigt empfanden \u2013 denn ein solches Ereignis erleben nur sehr wenige Menschen.<\/p>\n<p>Man k\u00f6nnte denken, diejenigen, die ihn auf Schritt und Tritt begleiten durften, seien die gl\u00fccklichsten Menschen der Welt, da sie sich st\u00e4ndig in der N\u00e4he eines international hoch angesehenen und m\u00e4chtigen F\u00fchrers befanden. Und wenn du an ihrer Stelle gewesen w\u00e4rst, h\u00e4ttest du dich wohl ebenso f\u00fcr sehr gesegnet gehalten \u2013 jedenfalls aus weltlicher Sicht.<\/p>\n<p>Doch die Bibel lehrt uns von einem weit gr\u00f6\u00dferen K\u00f6nig: JESUS CHRISTUS. Er wird zur\u00fcckkehren, um alle Reiche dieser Welt zu entmachten und sein ewiges, unverg\u00e4ngliches Reich zu errichten. Die Schrift sagt, dass er <strong>der K\u00f6nig der K\u00f6nige und Herr der Herren<\/strong> sein wird. Er wird die ganze Erde mit eisernem Zepter regieren. In jener Zeit, wenn die Welt wiederhergestellt ist in ihrer urspr\u00fcnglichen Sch\u00f6nheit, wird es unter seiner Herrschaft viele K\u00f6nige, Priester und Herrscher geben.<\/p>\n<p>Die Bibel sagt, dass es dann <strong>kein Meer<\/strong> mehr geben wird (Offenbarung 21,1). Und da heute etwa 75 % der Erde vom Meer bedeckt sind, kann man sich vorstellen, wie viel mehr Land dann zur Verf\u00fcgung stehen wird. Ebenso wird es keine W\u00fcsten mehr geben, keine \u00f6den oder unfruchtbaren Gegenden \u2013 die ganze Erde wird erf\u00fcllt sein mit der <strong>Herrlichkeit Gottes<\/strong> und bewohnt von Menschen.<\/p>\n<hr \/>\n<h3><strong>DAS TAUSENDJ\u00c4HRIGE REICH<\/strong><\/h3>\n<p>Wie uns die Bibel sagt, wird unser K\u00f6nig, Jesus Christus, mit seinen Heiligen <strong>tausend Jahre<\/strong> lang regieren, bevor die Ewigkeit beginnt (vgl. Offenbarung 20,4). Heute sitzt Christus auf dem Gnadenthron als Retter, aber wenn er zum zweiten Mal kommt, wird er nicht mehr als der sanfte Erl\u00f6ser erscheinen, sondern als <strong>der herrschende K\u00f6nig<\/strong>. Und ein K\u00f6nig bringt k\u00f6nigliche Eigenschaften und Anforderungen mit sich.<\/p>\n<p>Deshalb hat Gott erlaubt, dass wir zuvor die Reiche dieser Welt erleben \u2013 damit wir zumindest eine Vorstellung bekommen von der Art des kommenden, unverg\u00e4nglichen Reiches.<\/p>\n<p>Viele glauben, dass im Himmel alle gleich sein werden und wir Tag und Nacht nur Gott Loblieder singen werden wie Engel. Aber das ist nicht die vollst\u00e4ndige Wahrheit. Die Bibel spricht klar von einem <strong>Reich<\/strong>, von einem <strong>neuen Himmel und einer neuen Erde<\/strong>. Und wo ein Reich ist, da gibt es Herrscher und Untertanen.<\/p>\n<p>So wie Menschen heute auf Erden nach Macht und Herrschaft streben, wird auch <strong>das Reich Gottes erk\u00e4mpft<\/strong>. Wer keine geistliche Kraft besitzt, wird dort nicht herrschen, sondern beherrscht werden \u2013 das gilt <strong>f\u00fcr die Geretteten<\/strong>, nicht f\u00fcr alle Menschen, denn die S\u00fcnder werden zu jenem Zeitpunkt bereits im Feuersee sein. Deshalb sagte unser Herr Jesus:<\/p>\n<blockquote><p><strong>Matth\u00e4us 11,12:<\/strong><br \/>\n<em>\u201eAber von den Tagen Johannes des T\u00e4ufers bis heute leidet das Himmelreich Gewalt, und die Gewalt tun, rei\u00dfen es an sich.\u201c<\/em><\/p><\/blockquote>\n<p>Nur zu wissen, dass man in den Himmel kommt, reicht nicht aus. Die Frage ist: <strong>Welche Position wirst du dort haben?<\/strong><\/p>\n<hr \/>\n<h3><strong>EIN BEISPIEL AUS DEM LEBEN DER J\u00dcNGER<\/strong><\/h3>\n<p>Nachdem seine J\u00fcnger erkannten, dass Christus der rechtm\u00e4\u00dfige Herrscher im Reich Gottes sein wird, kamen zwei seiner engsten J\u00fcnger, Jakobus und Johannes, zu ihm mit einer besonderen Bitte, wie in <strong>Markus 10<\/strong> geschrieben steht:<\/p>\n<blockquote><p><strong>Markus 10,35\u201337:<\/strong><br \/>\n<em>\u201eDa gingen zu ihm Jakobus und Johannes, die S\u00f6hne des Zebed\u00e4us, und sprachen: Meister, wir wollen, dass du f\u00fcr uns tust, was wir dich bitten werden&#8230; Gib uns, dass wir sitzen einer zu deiner Rechten und einer zu deiner Linken in deiner Herrlichkeit.\u201c<\/em><\/p><\/blockquote>\n<p>Doch Jesus antwortete:<\/p>\n<blockquote><p><strong>Markus 10,38\u201339:<\/strong><br \/>\n<em>\u201eIhr wisst nicht, was ihr bittet. K\u00f6nnt ihr den Kelch trinken, den ich trinke, oder euch taufen lassen mit der Taufe, mit der ich getauft werde? Sie sprachen: Ja, das k\u00f6nnen wir. Jesus aber sprach zu ihnen: Den Kelch, den ich trinke, werdet ihr trinken, und mit der Taufe, mit der ich getauft werde, werdet ihr getauft werden.\u201c<\/em><\/p><\/blockquote>\n<p>Er f\u00fcgte jedoch hinzu, dass das Sitzen zu seiner Rechten und Linken nur denen gegeben wird, <strong>denen es vom Vater bereitet ist<\/strong>.<\/p>\n<hr \/>\n<h3><strong>DER KELCH UND DIE TAUFE<\/strong><\/h3>\n<p>Was meinte Jesus mit dem <strong>Kelch<\/strong> und der <strong>Taufe<\/strong>?<\/p>\n<p>Der <strong>Kelch<\/strong> steht f\u00fcr das <strong>Leiden um des Zeugnisses willen<\/strong> \u2013 wie Jesus selbst im Garten Gethsemane betete:<\/p>\n<blockquote><p><strong>Matth\u00e4us 26,39:<\/strong><br \/>\n<em>\u201eMein Vater, ist\u2019s m\u00f6glich, so gehe dieser Kelch an mir vor\u00fcber; doch nicht wie ich will, sondern wie du willst!\u201c<\/em><\/p><\/blockquote>\n<p>Die <strong>Taufe<\/strong>, von der er sprach, war nicht die Wassertaufe \u2013 denn diese hatte er bereits empfangen. Vielmehr meinte er die <strong>Taufe des Leidens, des Todes und der Auferstehung<\/strong>, wie in:<\/p>\n<blockquote><p><strong>Lukas 12,50:<\/strong><br \/>\n<em>\u201eAber ich muss mit einer Taufe getauft werden, und wie ist mir bange, bis sie vollbracht ist!\u201c<\/em><\/p><\/blockquote>\n<p>Paulus best\u00e4tigt dies in:<\/p>\n<blockquote><p><strong>R\u00f6mer 6,3\u20134:<\/strong><br \/>\n<em>\u201eWisst ihr nicht, dass alle, die wir in Christus Jesus getauft sind, die sind in seinen Tod getauft? So sind wir mit ihm begraben durch die Taufe in den Tod.\u201c<\/em><\/p><\/blockquote>\n<hr \/>\n<h3><strong>ZUR N\u00c4HE CHRISTI BERUFEN<\/strong><\/h3>\n<p>Heute wollen viele Jesus nachfolgen \u2013 <strong>aber ohne den Preis zu zahlen<\/strong>. Doch Jesus sagte:<\/p>\n<blockquote><p><strong>Lukas 14,27:<\/strong><br \/>\n<em>\u201eWer nicht sein Kreuz tr\u00e4gt und mir nachfolgt, der kann nicht mein J\u00fcnger sein.\u201c<\/em><\/p><\/blockquote>\n<p>So wie er sein Leben f\u00fcr uns hingegeben hat, sind auch wir aufgerufen, unser Leben <strong>f\u00fcr ihn<\/strong> hinzugeben \u2013 selbst wenn es Leid und Verfolgung bedeutet. Paulus schreibt:<\/p>\n<blockquote><p><strong>Philipper 1,29:<\/strong><br \/>\n<em>\u201eDenn euch ist es gegeben um Christi willen, nicht allein an ihn zu glauben, sondern auch um seinetwillen zu leiden.\u201c<\/em><\/p><\/blockquote>\n<p>Es ist dieser Weg des Kreuzes, der Spott und Ablehnung, <strong>der Jesus zum K\u00f6nig machte<\/strong>. Wie es in <strong>Hebr\u00e4er 12<\/strong> hei\u00dft:<\/p>\n<blockquote><p><strong>Hebr\u00e4er 12,2\u20133:<\/strong><br \/>\n<em>\u201e&#8230;der um der vor ihm liegenden Freude willen das Kreuz erduldete und die Schande nicht achtete und sich gesetzt hat zur Rechten des Thrones Gottes. Achtet also auf ihn&#8230; damit ihr nicht erm\u00fcdet und den Mut verliert.\u201c<\/em><\/p><\/blockquote>\n<p>Wenn auch wir bereit sind, diesen Weg zu gehen, dann werden wir <strong>w\u00fcrdig erachtet werden<\/strong>, Jesus nahe zu sein in seinem Reich \u2013 mit einem Namen vor seinem Angesicht.<\/p>\n<p>Die Apostel hielten es nicht f\u00fcr eine Niederlage, f\u00fcr Christus zu sterben \u2013 im Gegenteil: Sie betrachteten es als eine Ehre, <strong>ihm nahe zu sein in seinem kommenden Reich<\/strong>.<\/p>\n<hr \/>\n<h3><strong>Der Herr segne dich. M\u00f6gest du zu den Auserw\u00e4hlten geh\u00f6ren, die den Kelch trinken und die Taufe der Hingabe annehmen \u2013 auf dass du mit Christus regieren m\u00f6gest.<\/strong><\/h3>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='KRITERIEN, UM JESUS CHRISTUS IN DER K\u00dcNFTIGEN WELT NAHE ZU SEIN' data-link='https:\/\/wingulamashahidi.org\/de\/2018\/10\/05\/kriterien-um-jesus-christus-in-der-kuenftigen-welt-nahe-zu-sein\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Als der damalige US-Pr\u00e4sident Barack Obama im Jahr 2013 Tansania besuchte, war vielen klar, dass es fast unm\u00f6glich sein w\u00fcrde, mit ihm an einem Tisch zu<\/p>\n","protected":false},"author":1237,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-59266","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"fg1URUKQB8\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2018\/10\/05\/kriterien-um-jesus-christus-in-der-kuenftigen-welt-nahe-zu-sein\/\">KRITERIEN, UM JESUS CHRISTUS IN DER K\u00dcNFTIGEN WELT NAHE ZU SEIN<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2018\/10\/05\/kriterien-um-jesus-christus-in-der-kuenftigen-welt-nahe-zu-sein\/embed\/#?secret=fg1URUKQB8\" width=\"500\" height=\"350\" title=\"&#8222;KRITERIEN, UM JESUS CHRISTUS IN DER K\u00dcNFTIGEN WELT NAHE ZU SEIN&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"fg1URUKQB8\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1237"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=59266"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59266\/revisions"}],"predecessor-version":[{"id":59267,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59266\/revisions\/59267"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=59266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=59266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=59266"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=59266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}