{"id":59858,"date":"2024-08-25T21:40:23","date_gmt":"2024-08-25T18:40:23","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=59858"},"modified":"2025-10-21T16:08:32","modified_gmt":"2025-10-21T13:08:32","slug":"schlaegt-deine-wurzeln-tief-damit-du-frucht-tragen-kannst","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2024\/08\/25\/schlaegt-deine-wurzeln-tief-damit-du-frucht-tragen-kannst\/","title":{"rendered":"SCHL\u00c4GT DEINE WURZELN TIEF, DAMIT DU FRUCHT TRAGEN KANNST."},"content":{"rendered":"<hr \/>\n<h3><\/h3>\n<p>Ich gr\u00fc\u00dfe dich im Namen unseres Herrn Jesus Christus. Willkommen \u2013 lass uns gemeinsam die gute Botschaft f\u00fcr das Leben unserer Seelen entdecken.<\/p>\n<p>Gottes Wort sagt:<\/p>\n<p>\ud83d\udcd6 <strong>2. K\u00f6nige 19,30<\/strong><\/p>\n<blockquote><p><em>\u201eUnd was vom Haus Juda entkommen und \u00fcbrig geblieben ist, wird wieder Wurzeln nach unten schlagen und Fr\u00fcchte nach oben tragen.\u201c<\/em><\/p><\/blockquote>\n<p>Verstehst du, was dieser Vers bedeutet? Er spricht vom Aufbl\u00fchen des Hauses Juda \u2013 das sind wir, die Gemeinde Christi.<\/p>\n<p>Doch dieses Aufbl\u00fchen geschieht nicht einfach so. Damit Fr\u00fcchte nach oben wachsen k\u00f6nnen, m\u00fcssen die Wurzeln tief nach unten reichen. Das ist ein g\u00f6ttliches Prinzip.<\/p>\n<p>Ein Baum ohne Wurzeln kann keine Frucht bringen. Frag dich selbst: Hast du tiefe geistliche Wurzeln, die dich dazu bef\u00e4higen, Frucht zu bringen, die dem Herrn gef\u00e4llt?<\/p>\n<p>Deine Wertsch\u00e4tzung f\u00fcr das Heil spiegelt wider, wie tief deine Wurzeln reichen. Und nur tiefe Wurzeln erm\u00f6glichen es dir, geistliche Fr\u00fcchte hervorzubringen.<\/p>\n<p>Ein Blatt braucht keine tiefen Wurzeln \u2013 es bringt ja auch keine Frucht hervor.<\/p>\n<p>Wenn du nicht bereit bist, im Heil zu wachsen, wenn dir dein geistliches Leben gleichg\u00fcltig ist, dann wirst du auch keine Frucht f\u00fcr deinen Gott bringen k\u00f6nnen.<\/p>\n<p>In dem Gleichnis vom S\u00e4mann erkl\u00e4rt Jesus, warum nur der vierte Samen Frucht bringen konnte. Er sagt, dass er Frucht brachte durch <strong>Ausdauer<\/strong>.<\/p>\n<p>\ud83d\udcd6 <strong>Lukas 8,15<\/strong><\/p>\n<blockquote><p><em>\u201eDas aber auf dem guten Land sind die, die das Wort, das sie geh\u00f6rt haben, in einem feinen und guten Herzen behalten und Frucht bringen in Geduld.\u201c<\/em><\/p><\/blockquote>\n<p>Was bedeutet \u201ein Geduld\u201c?<\/p>\n<p>Das bedeutet, dass sie die ersten drei H\u00fcrden \u00fcberwunden haben:<br \/>\n\u2013 Sie lie\u00dfen nicht zu, dass der Feind das ges\u00e4te Wort stiehlt.<br \/>\n\u2013 Sie hielten durch in Pr\u00fcfungen und Bedr\u00e4ngnissen.<br \/>\n\u2013 Sie lie\u00dfen sich nicht von den Sorgen dieser Welt oder dem Reichtum und Vergn\u00fcgungen ablenken.<br \/>\nDas sind die Dinge, in denen sie geduldig waren.<\/p>\n<p>Das ist ein Mensch, der das Heil ernst nimmt.<\/p>\n<p>Jetzt die Frage an uns: Tragen <strong>wir<\/strong> solche Frucht?<\/p>\n<p>Erinnere dich: Frucht kommt nicht durch blo\u00dfes W\u00fcnschen oder Abwarten. Sie kommt durch <strong>tiefe Wurzeln<\/strong>, die in der Lage sind, die Quellen des Lebens zu erreichen.<\/p>\n<p>Deshalb sagt die Bibel:<\/p>\n<p>\ud83d\udcd6 <strong>Psalm 1,1\u20133<\/strong><\/p>\n<blockquote><p><em>\u201eWohl dem, der nicht wandelt im Rat der Gottlosen, noch tritt auf den Weg der S\u00fcnder, noch sitzt, wo die Sp\u00f6tter sitzen,<br \/>\nsondern hat Lust am Gesetz des HERRN und sinnt \u00fcber seinem Gesetz Tag und Nacht.<br \/>\nDer ist wie ein Baum, gepflanzt an den Wasserb\u00e4chen, der seine Frucht bringt zu seiner Zeit,<br \/>\nund seine Bl\u00e4tter verwelken nicht. Und was er macht, das ger\u00e4t wohl.\u201c<\/em><\/p><\/blockquote>\n<p>Fang heute an, dich um deine Wurzeln zu k\u00fcmmern \u2013 bis sie wirklich die Wasserstr\u00f6me Gottes erreichen.<\/p>\n<p>Werde nicht lau im Gebet, im Fasten, im Gottesdienst, in der Evangelisation oder im Bibelstudium.<\/p>\n<p>\ud83d\udcd6 <strong>2. K\u00f6nige 19,30<\/strong><\/p>\n<blockquote><p><em>\u201eUnd was vom Haus Juda entkommen und \u00fcbrig geblieben ist, wird wieder Wurzeln nach unten schlagen und Fr\u00fcchte nach oben tragen.\u201c<\/em><\/p><\/blockquote>\n<p>Der Herr segne dich reichlich.<\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='SCHL\u00c4GT DEINE WURZELN TIEF, DAMIT DU FRUCHT TRAGEN KANNST.' data-link='https:\/\/wingulamashahidi.org\/de\/2024\/08\/25\/schlaegt-deine-wurzeln-tief-damit-du-frucht-tragen-kannst\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ich gr\u00fc\u00dfe dich im Namen unseres Herrn Jesus Christus. Willkommen \u2013 lass uns gemeinsam die gute Botschaft f\u00fcr das Leben unserer Seelen entdecken. Gotte<\/p>\n","protected":false},"author":1237,"featured_media":59859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-59858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/08\/images-2024-08-25T214300.261.jpeg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/08\/images-2024-08-25T214300.261.jpeg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"CvIAGy9g3A\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2024\/08\/25\/schlaegt-deine-wurzeln-tief-damit-du-frucht-tragen-kannst\/\">SCHL\u00c4GT DEINE WURZELN TIEF, DAMIT DU FRUCHT TRAGEN KANNST.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2024\/08\/25\/schlaegt-deine-wurzeln-tief-damit-du-frucht-tragen-kannst\/embed\/#?secret=CvIAGy9g3A\" width=\"500\" height=\"350\" title=\"&#8222;SCHL\u00c4GT DEINE WURZELN TIEF, DAMIT DU FRUCHT TRAGEN KANNST.&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"CvIAGy9g3A\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1237"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=59858"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59858\/revisions"}],"predecessor-version":[{"id":59860,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/59858\/revisions\/59860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/59859"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=59858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=59858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=59858"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=59858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}