{"id":60265,"date":"2020-05-29T12:57:01","date_gmt":"2020-05-29T09:57:01","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=60265"},"modified":"2025-10-23T22:42:43","modified_gmt":"2025-10-23T19:42:43","slug":"die-angenehme-zeit-ist-jetzt","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/05\/29\/die-angenehme-zeit-ist-jetzt\/","title":{"rendered":"DIE ANGENEHME ZEIT IST JETZT"},"content":{"rendered":"<blockquote><p><em>\u201eDenn er spricht: Ich habe dich zur angenehmen Zeit erh\u00f6rt und habe dir am Tage des Heils geholfen. Siehe, jetzt ist die angenehme Zeit; siehe, jetzt ist der Tag des Heils.\u201c<\/em><br \/>\n\u2014 <strong>2. Korinther 6,2<\/strong><\/p><\/blockquote>\n<p>Die Bibel sagt:<\/p>\n<blockquote><p><em>\u201eAlles hat seine bestimmte Stunde, und jedes Vorhaben unter dem Himmel hat seine Zeit.\u201c<\/em><br \/>\n\u2014 Prediger 3,1<\/p><\/blockquote>\n<p>Das bedeutet, dass selbst ein Baum seine bestimmte Zeit hat, Fr\u00fcchte zu tragen \u2014 nicht jede Zeit ist Erntezeit.<br \/>\nMan kann ihn gie\u00dfen und d\u00fcngen, aber wenn nicht die rechte Zeit gekommen ist, wird er keine Frucht bringen.<br \/>\nWarum? Weil alles zu seiner von Gott bestimmten Zeit geschieht.<\/p>\n<p>Ebenso haben sich auch im Geist die Zeiten und Zeitabschnitte ver\u00e4ndert, als unser Herr Jesus Christus in den Himmel aufstieg, um uns eine St\u00e4tte zu bereiten.<br \/>\nVorher war die T\u00fcr f\u00fcr Menschen, Frucht zu bringen, die Gott gef\u00e4llt, noch nicht ge\u00f6ffnet.<br \/>\nDas Vorrecht, Gott tief zu erkennen und mit Seinem Geist erf\u00fcllt zu werden, war nur wenigen Propheten vorbehalten, die Gott aus Gnade erw\u00e4hlte.<\/p>\n<hr \/>\n<h3>IN DEN TAGEN MOSES<\/h3>\n<p>In den Tagen Moses empfingen nur bestimmte \u00c4lteste einen Anteil an Gottes Geist:<\/p>\n<blockquote><p><em>\u201eDa nahm der HERR von dem Geist, der auf Mose war, und legte ihn auf die siebzig \u00c4ltesten; und es geschah, als der Geist auf ihnen ruhte, da weissagten sie&#8230; Und Mose sprach zu Josua: O dass doch das ganze Volk des HERRN Propheten w\u00e4re, dass der HERR seinen Geist auf sie legte!\u201c<\/em><br \/>\n\u2014 4. Mose 11,24\u201329<\/p><\/blockquote>\n<p>Siehst du das?<br \/>\nMose sehnte sich nach einer Zeit, in der alle Kinder Gottes den Heiligen Geist empfangen w\u00fcrden \u2013 nicht nur einige wenige Auserw\u00e4hlte.<\/p>\n<hr \/>\n<h3>DIE ZEIT DER GNADEN IST GEKOMMEN<\/h3>\n<p>Diese Zeit, nach der Mose sich sehnte, ist gekommen, als der Herr Jesus Christus in den Himmel auffuhr.<br \/>\nDie Prophezeiung Joels begann sich zu erf\u00fcllen:<\/p>\n<blockquote><p><em>\u201eUnd danach wird es geschehen, dass ich meinen Geist ausgie\u00dfe \u00fcber alles Fleisch; und eure S\u00f6hne und T\u00f6chter werden weissagen, eure Alten werden Tr\u00e4ume haben, eure jungen M\u00e4nner werden Gesichte sehen.\u201c<\/em><br \/>\n\u2014 Joel 2,28\u201329<\/p><\/blockquote>\n<p>Dies ist die angenehme Zeit, die Zeit der Gnade \u2014 die Zeit, in der Gott Seinen Geist \u00fcber <em>alles Fleisch<\/em> ausgie\u00dft, ohne Unterschied.<\/p>\n<p>Darum schrieb der Apostel Paulus:<\/p>\n<blockquote><p><em>\u201eWir ermahnen euch aber auch, dass ihr die Gnade Gottes nicht vergeblich empfangt\u2026 Siehe, jetzt ist die angenehme Zeit; siehe, jetzt ist der Tag des Heils.\u201c<\/em><br \/>\n\u2014 2. Korinther 6,1\u20132<\/p><\/blockquote>\n<p>Geliebte, dies ist die Zeit der Gnade.<br \/>\nDie Heiligen und Propheten der alten Zeit sehnten sich danach, diesen Tag zu sehen \u2014 den Tag, in dem wir heute leben \u2014, doch sie starben, ohne ihn zu erleben.<br \/>\nSie begehrten, die Gabe des Heiligen Geistes zu empfangen, aber es war nicht ihre bestimmte Zeit.<\/p>\n<p>Jetzt aber, durch Christus, ist diese Verhei\u00dfung erf\u00fcllt worden.<br \/>\nDer gleiche Geist, der auf Mose ruhte, wird nun \u00fcber alle ausgegossen, die an Jesus Christus glauben \u2014 Gro\u00dfe und Kleine gleicherma\u00dfen.<\/p>\n<hr \/>\n<h3>VERPASS DEN HEILIGEN GEIST NICHT<\/h3>\n<p>Lasst uns dieses Vorrecht nicht gering sch\u00e4tzen.<br \/>\nMan kann vieles im Leben verlieren, aber nicht den Heiligen Geist, denn Er ist das Siegel Gottes \u00fcber deinem Leben.<\/p>\n<blockquote><p><em>\u201eBetr\u00fcbt nicht den Heiligen Geist Gottes, mit dem ihr versiegelt worden seid auf den Tag der Erl\u00f6sung hin.\u201c<\/em><br \/>\n\u2014 Epheser 4,30<\/p><\/blockquote>\n<p>Hast du den Heiligen Geist empfangen?<br \/>\nWenn nicht, wisse: Er wird frei gegeben an alle, die wahrhaftig Bu\u00dfe tun und sich zu Gott wenden.<\/p>\n<p>Bu\u00dfe ist nicht nur ein Wort, sondern eine Tat.<br \/>\nWenn du gestohlen hast, h\u00f6re auf zu stehlen und gib zur\u00fcck, was du genommen hast.<br \/>\nWenn du deinen K\u00f6rper verkauft hast, h\u00f6re sofort auf und breche alle alten Verbindungen ab.<br \/>\nWenn du Unzucht, Bestechung oder irgendeine Form von S\u00fcnde praktiziert hast \u2014 verlasse sie vollst\u00e4ndig und komm zu Jesus um Gnade.<\/p>\n<p>Wenn Gott sieht, dass deine Bu\u00dfe echt ist, wird Sein Heiliger Geist dir nahen.<br \/>\nDu wirst eine neue Kraft in dir sp\u00fcren \u2014 als w\u00e4rst du m\u00fcde gewesen und pl\u00f6tzlich innerlich erneuert.<\/p>\n<hr \/>\n<h3>LASST EUCH TAUFEN UND EMPFANGT DEN GEIST<\/h3>\n<p>Um dieses Werk der Gnade zu vollenden, lasse dich bald taufen \u2014 in viel Wasser und im Namen des Herrn Jesus Christus, wie es in der Schrift geschrieben steht:<\/p>\n<blockquote><p><em>\u201ePetrus sprach zu ihnen: Tut Bu\u00dfe, und jeder von euch lasse sich taufen auf den Namen Jesu Christi zur Vergebung eurer S\u00fcnden; so werdet ihr die Gabe des Heiligen Geistes empfangen. Denn euch gilt die Verhei\u00dfung und euren Kindern und allen, die fern sind, so viele der Herr, unser Gott, herzurufen wird.\u201c<\/em><br \/>\n\u2014 Apostelgeschichte 2,37\u201339<\/p><\/blockquote>\n<hr \/>\n<h3>JETZT IST DIE ANGENEHME ZEIT \u2014 DER TAG DES HEILS<\/h3>\n<p>Darum, lieber Bruder, liebe Schwester, z\u00f6gere nicht.<br \/>\nDies ist die Zeit, die K\u00f6nige und Propheten zu sehen begehrten.<br \/>\nDies ist deine Zeit \u2014 deine angenehme Zeit vor Gott.<\/p>\n<p>Empfange heute den Heiligen Geist.<br \/>\nWandle in Gerechtigkeit und sei versiegelt f\u00fcr den Tag der Erl\u00f6sung.<\/p>\n<p>Kontaktiere uns \u00fcber WhatsApp unter +255 789 001 312, um neue Botschaften direkt zu erhalten.<br \/>\nTeile diese Botschaft mit anderen, damit auch sie diese Gnade empfangen.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DIE ANGENEHME ZEIT IST JETZT' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/05\/29\/die-angenehme-zeit-ist-jetzt\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u201eDenn er spricht: Ich habe dich zur angenehmen Zeit erh\u00f6rt und habe dir am Tage des Heils geholfen. Siehe, jetzt ist die angenehme Zeit; siehe, jetzt is<\/p>\n","protected":false},"author":1097,"featured_media":60266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-60265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/100651768_767865870414575_1421944988874309632_n.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/05\/100651768_767865870414575_1421944988874309632_n.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"FqjtYTuuwC\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/29\/die-angenehme-zeit-ist-jetzt\/\">DIE ANGENEHME ZEIT IST JETZT<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/05\/29\/die-angenehme-zeit-ist-jetzt\/embed\/#?secret=FqjtYTuuwC\" width=\"500\" height=\"350\" title=\"&#8222;DIE ANGENEHME ZEIT IST JETZT&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"FqjtYTuuwC\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=60265"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60265\/revisions"}],"predecessor-version":[{"id":60267,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60265\/revisions\/60267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/60266"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=60265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=60265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=60265"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=60265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}