{"id":60827,"date":"2021-03-28T00:58:35","date_gmt":"2021-03-27T21:58:35","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=60827"},"modified":"2025-11-06T23:11:28","modified_gmt":"2025-11-06T20:11:28","slug":"lehren-aus-dem-buch-titus","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/","title":{"rendered":"LEHREN AUS DEM BUCH TITUS"},"content":{"rendered":"<p>Das g\u00f6ttliche Ordnungsprinzip f\u00fcr Gemeindeleitung und christliches Leben verstehen<\/p>\n<p>Der Brief an Titus ist ein pastoraler Brief, den der Apostel Paulus an seinen geistlichen Sohn Titus schrieb, einen seiner treuen Mitarbeiter im Glauben. Titus war ein Nichtjude, der durch den Dienst von Paulus zum Glauben an Christus gef\u00fchrt wurde (Galater 2,3).<\/p>\n<p>Zur Zeit des Schreibens hatte Paulus Titus auf der Insel Kreta zur\u00fcckgelassen \u2013 einer Mittelmeerinsel s\u00fcdlich von Griechenland \u2013 mit der Aufgabe, die dort neu gegr\u00fcndeten Gemeinden zu ordnen und zu st\u00e4rken.<\/p>\n<blockquote><p>\u201eDer Grund, warum ich dich in Kreta zur\u00fccklie\u00df, war, dass du das, was noch fehlt, in Ordnung bringen und in jeder Stadt \u00c4lteste einsetzen solltest, wie ich es dir aufgetragen habe.\u201c<br \/>\n\u2014 <em>Titus 1,5 (NIV)<\/em><\/p><\/blockquote>\n<p>Paulus\u2019 Brief konzentriert sich auf zwei Hauptthemen:<\/p>\n<hr \/>\n<h3>1. Die Qualifikationen f\u00fcr geistliche Leiter<\/h3>\n<p>Paulus betont die gro\u00dfe Bedeutung gottesf\u00fcrchtiger Leitung, besonders bei der Einsetzung von \u00c4ltesten (griechisch <em>presbuteros<\/em>, auch als Bisch\u00f6fe oder Aufseher bezeichnet).<\/p>\n<p>Die Leitung der Gemeinde darf nicht auf Beliebtheit oder pers\u00f6nlichem Ehrgeiz, sondern muss auf geistlicher Reife und moralischer Integrit\u00e4t beruhen.<\/p>\n<h4>Wichtige Anforderungen (Titus 1,6\u20139):<\/h4>\n<ul>\n<li>Ein untadeliges Leben \u2013 nicht vollkommen, aber ohne berechtigten Vorwurf.<\/li>\n<li>Treue zu einem Ehepartner \u2013 Ausdruck moralischer Reinheit und Hingabe.<\/li>\n<li>Glaubende Kinder \u2013 das Familienleben zeigt, ob ein Mann f\u00fchren kann.<\/li>\n<li>Nicht herrschs\u00fcchtig oder j\u00e4hzornig.<\/li>\n<li>Kein Trinker, Gewaltt\u00e4tiger oder Liebhaber unehrlichen Gewinns.<\/li>\n<li>Gastfreundlich, besonnen und beherrscht.<\/li>\n<li>Fest in der Lehre stehend \u2013 f\u00e4hig, die Wahrheit zu lehren und zu verteidigen.<\/li>\n<\/ul>\n<blockquote><p>\u201eEr muss am zuverl\u00e4ssigen Wort festhalten, wie es gelehrt worden ist, damit er durch die gesunde Lehre ermahnen und die Widersprechenden \u00fcberf\u00fchren kann.\u201c<br \/>\n\u2014 <em>Titus 1,9 (NIV)<\/em><\/p><\/blockquote>\n<p>Paulus warnt Titus auch vor falschen Lehrern, insbesondere vor denen \u201eaus der Beschneidung\u201c, die ganze H\u00e4user durch falsche Lehren verf\u00fchrten, um eigene Vorteile zu erlangen (Titus 1,10\u201311). Diese Warnung erinnert an Paulus\u2019 Kampf gegen Gesetzlichkeit und falsche Evangelien (vgl. Galater 1,6\u20139).<\/p>\n<hr \/>\n<h3>2. Anweisungen f\u00fcr ein gottesf\u00fcrchtiges Leben<\/h3>\n<p>In Titus 2 gibt Paulus praktische Anweisungen f\u00fcr verschiedene Gruppen innerhalb der Gemeinde. Dies zeigt, dass der christliche Glaube alle Lebensbereiche ver\u00e4ndert \u2013 Familie, Arbeit, Charakter und Beziehungen.<\/p>\n<h4>A. \u00c4ltere M\u00e4nner und Frauen<\/h4>\n<p>(Titus 2,2\u20133)<\/p>\n<ul>\n<li>Die \u00e4lteren M\u00e4nner sollen besonnen, w\u00fcrdevoll, gesund im Glauben, in der Liebe und in der Standhaftigkeit sein.<\/li>\n<li>\u00c4ltere Frauen sollen ehrf\u00fcrchtig leben, nicht verleumden oder dem Trunk ergeben sein, sondern Gutes lehren.<\/li>\n<\/ul>\n<blockquote><p>\u201eEbenso lehre die \u00e4lteren Frauen, sich in ihrem Wandel ehrbar zu verhalten \u2026 damit sie das Gute lehren.\u201c<br \/>\n\u2014 <em>Titus 2,3 (NIV)<\/em><\/p><\/blockquote>\n<h4>B. J\u00fcngere Frauen und M\u00e4nner<\/h4>\n<p>(Titus 2,4\u20138)<\/p>\n<ul>\n<li>Junge Frauen sollen ihre Familien lieben, keusch, freundlich und ihren M\u00e4nnern untergeordnet sein.<\/li>\n<li>Junge M\u00e4nner sollen besonnen und vorbildlich im guten Werk sein, gesund in der Lehre, w\u00fcrdevoll und ernsthaft.<\/li>\n<\/ul>\n<blockquote><p>\u201eErmahne die jungen M\u00e4nner, besonnen zu sein. Sei du selbst in allem ein Vorbild guter Werke, in der Lehre unverf\u00e4lscht, w\u00fcrdevoll.\u201c<br \/>\n\u2014 <em>Titus 2,6\u20137 (NIV)<\/em><\/p><\/blockquote>\n<hr \/>\n<h3>3. Ein Leben der Gnade<\/h3>\n<p>Paulus erinnert die Gl\u00e4ubigen daran, dass das christliche Leben nicht durch eigene Leistung, sondern allein durch die Gnade Gottes m\u00f6glich ist.<\/p>\n<blockquote><p>\u201eDenn die Gnade Gottes ist erschienen, die allen Menschen Heil bringt. Sie erzieht uns dazu, die Gottlosigkeit und weltlichen Begierden zu verleugnen und besonnen, gerecht und gottesf\u00fcrchtig in der jetzigen Welt zu leben.\u201c<br \/>\n\u2014 <em>Titus 2,11\u201312 (NIV)<\/em><\/p><\/blockquote>\n<p>Die Gnade lehrt uns also, heilig zu leben, w\u00e4hrend wir auf die selige Hoffnung, die Wiederkunft Jesu Christi, warten (Titus 2,13).<\/p>\n<blockquote><p>\u201e\u2026 w\u00e4hrend wir auf die selige Hoffnung warten, auf das Erscheinen der Herrlichkeit des gro\u00dfen Gottes und unseres Retters Jesus Christus.\u201c<br \/>\n\u2014 <em>Titus 2,13 (NIV)<\/em><\/p><\/blockquote>\n<hr \/>\n<h3>4. Christliches Zeugnis in der Welt<\/h3>\n<p>In Titus 3 betont Paulus die Bedeutung guten Verhaltens gegen\u00fcber der Gesellschaft \u2013 Gehorsam gegen\u00fcber Autorit\u00e4ten, Sanftmut und Barmherzigkeit gegen\u00fcber allen Menschen.<\/p>\n<blockquote><p>\u201eErinnere sie daran, sich den Obrigkeiten und Gewalten unterzuordnen, gehorsam zu sein und zu jedem guten Werk bereit.\u201c<br \/>\n\u2014 <em>Titus 3,1 (NIV)<\/em><\/p><\/blockquote>\n<p>Wir werden daran erinnert, dass wir selbst einst verloren waren, aber durch Gottes Gnade und Erbarmen erneuert wurden \u2013 nicht durch Werke, sondern durch das Erbarmen Jesu Christi.<\/p>\n<blockquote><p>\u201eEr hat uns gerettet \u2013 nicht aufgrund von Werken der Gerechtigkeit, die wir getan h\u00e4tten, sondern aufgrund seiner Barmherzigkeit \u2013 durch das Bad der Wiedergeburt und Erneuerung im Heiligen Geist.\u201c<br \/>\n\u2014 <em>Titus 3,5 (NIV)<\/em><\/p><\/blockquote>\n<hr \/>\n<h3>SCHLUSSGEDANKE<\/h3>\n<p>Das Buch Titus zeigt uns, dass wahre Lehre und wahres Leben untrennbar miteinander verbunden sind. Ein gesunder Glaube f\u00fchrt zu einem heiligen Lebensstil, der Gottes Wahrheit widerspiegelt.<\/p>\n<p>M\u00f6gen wir, wie Titus, treue Diener sein, die Gottes Ordnung bewahren, gute Werke tun und durch unser Leben das Evangelium ehren.<\/p>\n<p>Shalom.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='LEHREN AUS DEM BUCH TITUS' data-link='https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Das g\u00f6ttliche Ordnungsprinzip f\u00fcr Gemeindeleitung und christliches Leben verstehen Der Brief an Titus ist ein pastoraler Brief, den der Apostel Paulus an seinen geistlichen Sohn Titus schrieb, einen seiner treuen Mitarbeiter im Glauben. Titus war ein Nichtjude, der durch den Dienst von Paulus zum Glauben an Christus gef\u00fchrt wurde (Galater 2,3). Zur Zeit des Schreibens [&hellip;]<\/p>\n","protected":false},"author":1097,"featured_media":60828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-60827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"PF7U6uwGhj\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/\">LEHREN AUS DEM BUCH TITUS<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/embed\/#?secret=PF7U6uwGhj\" width=\"500\" height=\"350\" title=\"&#8222;LEHREN AUS DEM BUCH TITUS&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"PF7U6uwGhj\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LEHREN AUS DEM BUCH TITUS &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LEHREN AUS DEM BUCH TITUS &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Das g\u00f6ttliche Ordnungsprinzip f\u00fcr Gemeindeleitung und christliches Leben verstehen Der Brief an Titus ist ein pastoraler Brief, den der Apostel Paulus an seinen geistlichen Sohn Titus schrieb, einen seiner treuen Mitarbeiter im Glauben. Titus war ein Nichtjude, der durch den Dienst von Paulus zum Glauben an Christus gef\u00fchrt wurde (Galater 2,3). Zur Zeit des Schreibens [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-27T21:58:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T20:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"214\" \/>\n\t<meta property=\"og:image:height\" content=\"236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rogath Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rogath Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/\"},\"author\":{\"name\":\"Rogath Henry\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\"},\"headline\":\"LEHREN AUS DEM BUCH TITUS\",\"datePublished\":\"2021-03-27T21:58:35+00:00\",\"dateModified\":\"2025-11-06T20:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/\"},\"wordCount\":747,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/paul_epistle.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/\",\"name\":\"LEHREN AUS DEM BUCH TITUS &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/paul_epistle.jpg\",\"datePublished\":\"2021-03-27T21:58:35+00:00\",\"dateModified\":\"2025-11-06T20:11:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/paul_epistle.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/paul_epistle.jpg\",\"width\":214,\"height\":236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2021\\\/03\\\/28\\\/lehren-aus-dem-buch-titus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEHREN AUS DEM BUCH TITUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\",\"name\":\"Rogath Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"caption\":\"Rogath Henry\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LEHREN AUS DEM BUCH TITUS &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/","og_locale":"de_DE","og_type":"article","og_title":"LEHREN AUS DEM BUCH TITUS &#8211; Site title","og_description":"Das g\u00f6ttliche Ordnungsprinzip f\u00fcr Gemeindeleitung und christliches Leben verstehen Der Brief an Titus ist ein pastoraler Brief, den der Apostel Paulus an seinen geistlichen Sohn Titus schrieb, einen seiner treuen Mitarbeiter im Glauben. Titus war ein Nichtjude, der durch den Dienst von Paulus zum Glauben an Christus gef\u00fchrt wurde (Galater 2,3). Zur Zeit des Schreibens [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2021-03-27T21:58:35+00:00","article_modified_time":"2025-11-06T20:11:28+00:00","og_image":[{"width":214,"height":236,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","type":"image\/jpeg"}],"author":"Rogath Henry","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rogath Henry","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/"},"author":{"name":"Rogath Henry","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d"},"headline":"LEHREN AUS DEM BUCH TITUS","datePublished":"2021-03-27T21:58:35+00:00","dateModified":"2025-11-06T20:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/"},"wordCount":747,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/","url":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/","name":"LEHREN AUS DEM BUCH TITUS &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","datePublished":"2021-03-27T21:58:35+00:00","dateModified":"2025-11-06T20:11:28+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/03\/paul_epistle.jpg","width":214,"height":236},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2021\/03\/28\/lehren-aus-dem-buch-titus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/was-haben-die-unreinen-tiere-in-petrus-vision-dargestellt\/"},{"@type":"ListItem","position":2,"name":"LEHREN AUS DEM BUCH TITUS"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d","name":"Rogath Henry","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","caption":"Rogath Henry"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=60827"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60827\/revisions"}],"predecessor-version":[{"id":60829,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/60827\/revisions\/60829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/60828"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=60827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=60827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=60827"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=60827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}