{"id":63054,"date":"2023-09-24T19:06:13","date_gmt":"2023-09-24T16:06:13","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=63054"},"modified":"2025-12-02T19:37:39","modified_gmt":"2025-12-02T16:37:39","slug":"die-vorteile-des-fastens-gemeinsam-mit-deinen-tieren","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2023\/09\/24\/die-vorteile-des-fastens-gemeinsam-mit-deinen-tieren\/","title":{"rendered":"DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<p><strong>DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN<\/strong><\/p>\n<p>(Spezielle Lehren \u00fcber Fasten und Gebet)<\/p>\n<p>Gepriesen sei der Name unseres Herrn und Erl\u00f6sers Jesus Christus! Kommt, lasst uns gemeinsam die Bibel studieren \u2013 das Wort unseres Gottes ist eine Leuchte f\u00fcr unsere F\u00fc\u00dfe und ein Licht auf unserem Weg (Psalm 119,105).<\/p>\n<p>Die Bibel zeigt uns an vielen Stellen die <strong>Vorteile des Fastens<\/strong> \u2013 also sich zeitweise vom Essen und Trinken zur\u00fcckzuhalten. Wer fastet, \u00f6ffnet T\u00fcren, die sich durch normales Gebet allein nicht \u00f6ffnen w\u00fcrden.<\/p>\n<blockquote>\n<p><strong>Matth\u00e4us 17,20: <\/strong><\/p>\n<p>\u201eJesus sagte zu ihnen: \u201aWegen eures Kleinglaubens. Wahrlich, ich sage euch: Wenn ihr Glauben habt wie ein Senfkorn, k\u00f6nnt ihr zu diesem Berg sagen: \u201eBewege dich von hier nach dort!\u201c, und er wird sich bewegen. F\u00fcr euch wird nichts unm\u00f6glich sein.<br \/>Aber dies geschieht nur durch Gebet und Fasten.\u2018\u201c<\/p>\n<\/blockquote>\n<p>Doch <strong>wei\u00dft du, welche Vorteile es hat, zusammen mit deinen Tieren zu fasten? Oder mit deinem Gesch\u00e4ft oder deinem Beruf?<\/strong> Nicht nur Menschen sollen fasten, sondern auch Tiere. Du fragst dich vielleicht: Wie kann das sein? Werfen wir einen Blick in die Bibel, zur Zeit des Propheten Jona, als er in Ninive predigte.<\/p>\n<p>Die Bibel berichtet, dass der K\u00f6nig von Ninive ausrief, dass <strong>alle Menschen und alle Tiere der Stadt fasten sollen<\/strong> \u2013 niemand sollte essen oder trinken (achte darauf: nicht nur Menschen, sondern auch die gez\u00e4hmten Tiere).<\/p>\n<blockquote>\n<p><strong>Jona 3,6\u201310:<\/strong><br \/>\u201eAls die Nachricht den K\u00f6nig von Ninive erreichte, stand er von seinem Thron auf, legte seinen Mantel ab, h\u00fcllte sich in Sack und setzte sich auf Asche.<br \/>Dann lie\u00df er ausrufen und verk\u00fcnden: \u201aKein Mensch soll essen oder trinken, auch keine Rinderherden, keine Schafherden; alles soll fasten.<br \/>Und sie sollen Sackkleider tragen, Menschen wie Tiere, und laut zu Gott rufen. Sie sollen umkehren, jeder von seinem b\u00f6sen Weg und der Gewalt in seinen H\u00e4nden.<br \/>Vielleicht wird Gott umkehren und sich von seinem Zorn abwenden, sodass wir nicht zugrunde gehen.\u2018<br \/>Gott sah ihre Werke, dass sie sich von ihrem b\u00f6sen Weg abgewandt hatten, und verschonte sie.\u201c<\/p>\n<\/blockquote>\n<p>Siehst du, was der K\u00f6nig von Ninive getan hat? Und das Ergebnis: Gott erw\u00e4hnte sp\u00e4ter ausdr\u00fccklich, dass <strong>auch die Tiere Gnade verdienten<\/strong>, weil sie fasteten. H\u00e4tten die Tiere nicht mitgefastet, h\u00e4tten vielleicht nur die Menschen Gnade erfahren, aber die Tiere w\u00e4ren gestorben. Die Wirtschaft der Stadt h\u00e4tte gelitten, selbst nach der Vergebung.<\/p>\n<blockquote>\n<p><strong>Jona 4,10\u201311:<\/strong><br \/>\u201eDa sprach der Herr: \u201aHast du Mitleid mit dem Rizinusstrauch, der nur \u00fcber Nacht gewachsen ist und schnell wieder verwelkt? Sollte ich nicht Mitleid haben mit Ninive, der gro\u00dfen Stadt, in der mehr als 120.000 Menschen leben, die nicht zwischen rechts und links unterscheiden k\u00f6nnen \u2013 und dazu noch sehr viele Tiere?\u2018\u201c<\/p>\n<\/blockquote>\n<p>Achte auf die letzten Worte Gottes: \u201e\u2026und dazu noch sehr viele Tiere?\u201c<\/p>\n<p>Auch Tiere k\u00f6nnen also Teil unseres Stroms von <strong>Segen oder Fluch<\/strong> sein. Der K\u00f6nig von Ninive erkannte dies \u2013 er wusste, dass S\u00fcnde nicht nur die Menschen, sondern auch ihre gez\u00e4hmten Tiere betrifft. Deshalb m\u00fcssen auch sie durch Bu\u00dfe und Fasten gereinigt werden. Die Tiere wurden sogar in Sackkleider geh\u00fcllt!<\/p>\n<p>Es ist wichtig, dies zu verstehen: Wenn du fastest, faste auch <strong>mit deinen Tieren<\/strong>. Es muss nicht st\u00e4ndig sein, aber es ist gut, dies zur Gewohnheit zu machen.<\/p>\n<p>Fasten bedeutet auch, dein Feld und dein Gesch\u00e4ft einzubeziehen: Keine Bew\u00e4sserung, kein D\u00fcngen, keine F\u00fctterung der Tiere, keine Arbeit im Gesch\u00e4ft an diesem Tag. Tue dies im Glauben, und du wirst gro\u00dfe Ergebnisse sehen!<\/p>\n<p>Viele Menschen sehen keine Ergebnisse in ihrer Arbeit, weil sie vergessen, ihr Gesch\u00e4ft oder ihre Tiere ins Fasten einzubeziehen. Sie fasten nur selbst, ohne zu verstehen, dass Fasten nicht nur den K\u00f6rper betrifft, sondern auch Gesch\u00e4fte und Tiere miteinbezieht.<\/p>\n<p>Der Herr segne dich.<\/p>\n<p><strong>Maranatha<\/strong><\/p>\n<p>Bitte teile diese Botschaft auch mit anderen.<\/p>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN' data-link='https:\/\/wingulamashahidi.org\/de\/2023\/09\/24\/die-vorteile-des-fastens-gemeinsam-mit-deinen-tieren\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN (Spezielle Lehren \u00fcber Fasten und Gebet) Gepriesen sei der Name unseres Herrn und Erl\u00f6sers Jesus <\/p>\n","protected":false},"author":1204,"featured_media":63055,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-63054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2023\/09\/Palaces-at-Nimrid.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2023\/09\/Palaces-at-Nimrid.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"AqxaEV98hx\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2023\/09\/24\/die-vorteile-des-fastens-gemeinsam-mit-deinen-tieren\/\">DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2023\/09\/24\/die-vorteile-des-fastens-gemeinsam-mit-deinen-tieren\/embed\/#?secret=AqxaEV98hx\" width=\"500\" height=\"350\" title=\"&#8222;DIE VORTEILE DES FASTENS GEMEINSAM MIT DEINEN TIEREN&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"AqxaEV98hx\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1204"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=63054"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63054\/revisions"}],"predecessor-version":[{"id":63056,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63054\/revisions\/63056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/63055"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=63054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=63054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=63054"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=63054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}