{"id":63704,"date":"2024-07-11T14:32:15","date_gmt":"2024-07-11T11:32:15","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=63704"},"modified":"2025-12-09T00:00:41","modified_gmt":"2025-12-08T21:00:41","slug":"lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/","title":{"rendered":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden"},"content":{"rendered":"\n\n\n<p>Heute leben viele Menschen in Angst wegen ihrer Familiengeschichte und Herkunft. Manche f\u00fchlen, dass ihr jetziges Leben oder Verhalten von ihrer famili\u00e4ren Vergangenheit, ihrer Abstammung oder ihren Vorfahren gepr\u00e4gt wurde \u2013 und sie wissen nicht, was sie dagegen tun sollen.<\/p>\n<p>Aber die Wahrheit ist: Niemand von uns hat eine Familienlinie, die frei von Problemen ist. Angefangen bei unserem Herrn Jesus Christus selbst, wurde die Bibel geschrieben und uns gegeben, um uns den Weg zu zeigen \u2013 damit wir standhaft und mutig die M\u00e4chte des B\u00f6sen \u00fcberwinden k\u00f6nnen, ohne Angst.<\/p>\n<p>Das Matth\u00e4usevangelium beginnt mit der Darstellung von Jesu Stammbaum. Es gab einen Grund, warum seine Familiengeschichte zuerst erw\u00e4hnt wird \u2013 Gott wollte uns etwas Wichtiges lehren. Viele Menschen k\u00f6nnten beim Lesen dieser Liste denken, Gott wolle uns zeigen, dass Jesus aus einer angesehenen, ehrbaren Linie stammt. Doch das ist nicht der Fall. Die Wahrheit ist: Viele der genannten Personen hatten keinen guten Ruf.<\/p>\n<p>Ich m\u00f6chte, dass wir sehen, wie schwierig und chaotisch diese Familienlinie war \u2013 so sehr, dass Jesus, wenn Gott nach Reinheit beurteilt h\u00e4tte, gar nicht als Retter der Welt h\u00e4tte kommen d\u00fcrfen. Sein Stammbaum bestand nicht nur aus guten Menschen; es waren \u201eHuren\u201c, \u201eEhebrecher\u201c und sogar \u201eHeiden\u201c darunter.<\/p>\n<p>Zum Beispiel war Rahab eine echte Prostituierte. Dann gibt es Ruth, eine Fremde, die nach dem Gesetz der Juden streng verboten war zu heiraten (Esra 9,2), weil sie als unrein galt. Dennoch ist sie in der Abstammung enthalten. Wenn das nicht genug w\u00e4re, gab es Tamar, die Ehebruch beging, indem sie ihren Schwiegervater t\u00e4uschte, um Perez zu geb\u00e4ren. Dann ist da noch Batseba, die Frau eines Diebes und Ehebrechers \u2013 K\u00f6nig David \u2013, die nicht einmal eine seiner rechtm\u00e4\u00dfigen Ehefrauen war, und doch wurde sie ausgew\u00e4hlt, die Linie fortzuf\u00fchren, aus der Christus hervorging. Die sogenannten \u201eReinen\u201c wurden \u00fcbergangen.<\/p>\n<p>Lass uns lesen:<\/p>\n<blockquote>\n<p><strong>Matth\u00e4us 1,1-17 (Lutherbibel 2017)<\/strong><br \/>1 Buch des Ursprungs Jesu Christi, des Sohnes Davids, des Sohnes Abrahams.<br \/>2 Abraham zeugte Isaak, Isaak zeugte Jakob, Jakob zeugte Juda und seine Br\u00fcder,<br \/>3 Juda zeugte Perez und Serach von der Tamar, Perez zeugte Hezron, Hezron zeugte Ram,<br \/>4 Ram zeugte Amminadab, Amminadab zeugte Nahschon, Nahschon zeugte Salmon,<br \/>5 Salmon zeugte Boas von der Rahab, Boas zeugte Obed von der Ruth, Obed zeugte Isai,<br \/>6 Isai zeugte David, den K\u00f6nig. David zeugte Salomo von der Frau des Uria,<br \/>7 Salomo zeugte Rehabeam, Rehabeam zeugte Abija, Abija zeugte Asa,<br \/>8 Asa zeugte Joschafat, Joschafat zeugte Joram, Joram zeugte Usija,<br \/>9 Usija zeugte Jotam, Jotam zeugte Ahas, Ahas zeugte Hiskia,<br \/>10 Hiskia zeugte Manasse, Manasse zeugte Amon, Amon zeugte Josia,<br \/>11 Josia zeugte Jekonja und seine Br\u00fcder zur Zeit der Wegf\u00fchrung nach Babylon.<br \/>12 Nach der Wegf\u00fchrung nach Babylon zeugte Jekonja Schealtiel, Schealtiel zeugte Serubbabel,<br \/>13 Serubbabel zeugte Abihud, Abihud zeugte Eljakim, Eljakim zeugte Asor,<br \/>14 Asor zeugte Zadok, Zadok zeugte Achim, Achim zeugte Eliud,<br \/>15 Eliud zeugte Eleasar, Eleasar zeugte Mattan, Mattan zeugte Jakob,<br \/>16 Jakob zeugte Josef, den Mann Marias, von der Jesus geboren ist, der Christus genannt wird.<br \/>17 Also sind es von Abraham bis David vierzehn Geschlechter, von David bis zur Wegf\u00fchrung nach Babylon vierzehn Geschlechter und von der Wegf\u00fchrung nach Babylon bis zum Christus vierzehn Geschlechter.<\/p>\n<\/blockquote>\n<p>Die Familie unseres Herrn Jesus Christus war also voller Unvollkommenheiten. Man k\u00f6nnte sagen, sie war nicht \u201erein\u201c im Vergleich zu anderen j\u00fcdischen Familienlinien. Doch Er ist derjenige, der Gott am meisten gefiel, obwohl Er aus einer verunreinigten Herkunft kam. Er ist der Retter, der gekommen ist, um Menschen zu befreien, jeden Fluch zu brechen und Segen in die Welt zu bringen.<\/p>\n<p>Was lehrt uns das?<\/p>\n<p>Hab keine Angst. Es mag wahr sein, dass deine Familiengeschichte voller S\u00fcnde, Prostituierter, Trinker, vererbter Krankheiten, Armut und Schw\u00e4che ist. Vielleicht verstehst du nicht, was vor sich geht, und deine Linie scheint verflucht zu sein. Aber lass mich dir sagen: H\u00f6r auf, dir wegen deiner Abstammung Sorgen zu machen, denn niemand kam je mit einem \u201ereinen\u201c Erbe in diese Welt. Schau nur auf Christus \u2013 Er hat am Kreuz alles f\u00fcr dich vollbracht. Glaube an das Werk, das Er vollendet hat.<\/p>\n<p>Wenn du gerettet bist, gibt es keinen Fluch mehr in dir, egal wie verdorben deine Familie war, egal welche Geister oder Fl\u00fcche weitergegeben wurden. Das ist vorbei! Es hat keine Macht mehr \u00fcber dich, also gib ihm keine Erlaubnis \u2013 glaube an Jesus, der dich erl\u00f6st hat.<\/p>\n<p>Sei nicht jemand, der heruml\u00e4uft und versucht, Familienfl\u00fcche zu brechen. Wie viele Fl\u00fcche willst du brechen? Wie viele Vorfahren gab es vor dir? Du m\u00fcsstest bis Adam zur\u00fcckgehen, um alle Fl\u00fcche zu brechen. Stattdessen brich sie ein f\u00fcr alle Mal geistlich, indem du an Jesus glaubst, der dich befreit hat.<\/p>\n<p>Familienprobleme gibt es bei jedem \u2013 auch bei manchen Dienern Gottes \u2013 nur auf unterschiedliche Weise. Aber wer Christus vertraut hat, ist frei von allen Fl\u00fcchen. Frag sie, wie das Leben ist, und sie werden es dir sagen.<\/p>\n<p>Lieber Bruder, liebe Schwester, wenn du gerettet bist, sind die alten Dinge vorbei. Sie sind neu geworden. Was du jetzt tun musst, ist, Christus immer mehr zu erkennen, damit du Frieden hast. Grabe nicht weiter in der Vergangenheit. Lerne aus der Familie Jesu.<\/p>\n<p>Gott segne dich.<\/p>\n<p>Teile diese gute Nachricht mit anderen, indem du diese Botschaft weitergibst.<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n\n\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden' data-link='https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Heute leben viele Menschen in Angst wegen ihrer Familiengeschichte und Herkunft. Manche f\u00fchlen, dass ihr jetziges Leben oder Verhalten von ihrer famili\u00e4ren Vergangenheit, ihrer Abstammung oder ihren Vorfahren gepr\u00e4gt wurde \u2013 und sie wissen nicht, was sie dagegen tun sollen. Aber die Wahrheit ist: Niemand von uns hat eine Familienlinie, die frei von Problemen ist. [&hellip;]<\/p>\n","protected":false},"author":1198,"featured_media":63705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-63704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pQqxDWKaF6\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/\">Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/embed\/#?secret=pQqxDWKaF6\" width=\"500\" height=\"350\" title=\"&#8222;Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"pQqxDWKaF6\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Heute leben viele Menschen in Angst wegen ihrer Familiengeschichte und Herkunft. Manche f\u00fchlen, dass ihr jetziges Leben oder Verhalten von ihrer famili\u00e4ren Vergangenheit, ihrer Abstammung oder ihren Vorfahren gepr\u00e4gt wurde \u2013 und sie wissen nicht, was sie dagegen tun sollen. Aber die Wahrheit ist: Niemand von uns hat eine Familienlinie, die frei von Problemen ist. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T11:32:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T21:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rehema Jonathan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rehema Jonathan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/\"},\"author\":{\"name\":\"Rehema Jonathan\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\"},\"headline\":\"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden\",\"datePublished\":\"2024-07-11T11:32:15+00:00\",\"dateModified\":\"2025-12-08T21:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/\"},\"wordCount\":889,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/\",\"name\":\"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg\",\"datePublished\":\"2024-07-11T11:32:15+00:00\",\"dateModified\":\"2025-12-08T21:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2024\\\/07\\\/11\\\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/a8faab023f5889d406195cde9cf8346c\",\"name\":\"Rehema Jonathan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g\",\"caption\":\"Rehema Jonathan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/","og_locale":"de_DE","og_type":"article","og_title":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title","og_description":"Heute leben viele Menschen in Angst wegen ihrer Familiengeschichte und Herkunft. Manche f\u00fchlen, dass ihr jetziges Leben oder Verhalten von ihrer famili\u00e4ren Vergangenheit, ihrer Abstammung oder ihren Vorfahren gepr\u00e4gt wurde \u2013 und sie wissen nicht, was sie dagegen tun sollen. Aber die Wahrheit ist: Niemand von uns hat eine Familienlinie, die frei von Problemen ist. [&hellip;]","og_url":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2024-07-11T11:32:15+00:00","article_modified_time":"2025-12-08T21:00:41+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","type":"image\/jpeg"}],"author":"Rehema Jonathan","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rehema Jonathan","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/"},"author":{"name":"Rehema Jonathan","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c"},"headline":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden","datePublished":"2024-07-11T11:32:15+00:00","dateModified":"2025-12-08T21:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/"},"wordCount":889,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/","url":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/","name":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","datePublished":"2024-07-11T11:32:15+00:00","dateModified":"2025-12-08T21:00:41+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2024\/07\/787988251b526aead9cddb3dfca92096266e59cbe0f897e6466171f9ab84b690._SX1080_FMjpg_.jpg","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2024\/07\/11\/lerne-eine-lektion-aus-der-familienlinie-von-jesus-finde-frieden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"Lerne eine Lektion aus der Familienlinie von Jesus \u2013 Finde Frieden"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/a8faab023f5889d406195cde9cf8346c","name":"Rehema Jonathan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d32888c36f3a8a3df7af14aed343affef876988da593b7618ccea3c1eb788a8?s=96&d=mm&r=g","caption":"Rehema Jonathan"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1198"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=63704"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63704\/revisions"}],"predecessor-version":[{"id":63706,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/63704\/revisions\/63706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/63705"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=63704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=63704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=63704"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=63704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}