{"id":64136,"date":"2023-08-30T09:14:38","date_gmt":"2023-08-30T06:14:38","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=64136"},"modified":"2025-12-14T21:08:45","modified_gmt":"2025-12-14T18:08:45","slug":"das-gesetz-des-fragens-und-empfangens","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2023\/08\/30\/das-gesetz-des-fragens-und-empfangens\/","title":{"rendered":"DAS GESETZ DES FRAGENS UND EMPFANGENS"},"content":{"rendered":"<blockquote><p>Gepriesen sei der Name unseres Herrn und Erl\u00f6sers Jesus Christus. Willkommen zu unserem heutigen Bibelstudium; Gottes Wort, das \u201eeine Leuchte f\u00fcr unsere F\u00fc\u00dfe und ein Licht auf unserem Weg\u201c ist (Psalm 119,105).<\/p><\/blockquote>\n<p>Es ist wichtig, dass wir die verschiedenen Regeln kennen, wie wir beten sollten, damit unsere Gebete akzeptabel sind, erh\u00f6rt werden und Fr\u00fcchte tragen. In unseren vergangenen Bibelstudien (Lehren) haben wir einige dieser Regeln gelernt, und heute, so Gott will, werden wir eine weitere wichtige Regel betrachten.<\/p>\n<p><strong>Das Wort Gottes sagt:<\/strong><\/p>\n<blockquote><p>\u202dJakobus 4,2-3 (LUT)\u202c:<br \/>\n[2] \u201eIhr begehrt und habt nicht; ihr mordet und neidet und k\u00f6nnt nicht erlangen; ihr streitet und k\u00e4mpft. Ihr habt nicht, weil ihr nicht bittet.<br \/>\n[3] Ihr bittet und empfangt nicht, weil ihr mit b\u00f6ser Absicht bittet, um es in euren Lusten zu vergeuden.\u201c<\/p><\/blockquote>\n<p>Die Bibel stellt klar, dass der Grund, warum wir in unseren Gebeten nicht das empfangen, worum wir bitten, darin liegt, dass wir \u201efalsch bitten\u201c. Wir beten mit falschen Motiven und bitten daher falsch!<\/p>\n<p>Falsch bitten bedeutet hier nicht, dass wir die falschen Worte w\u00e4hlen oder uns nicht stark und \u00fcberzeugend ausdr\u00fccken. In diesem biblischen Kontext weist die Bibel darauf hin, dass wir oft um Dinge bitten, die Gott nicht gefallen. Wir stimmen unsere Gebete (Bitten) nicht mit dem Willen Gottes ab. Zum Beispiel: Gott zu bitten, dass Er dir jemanden \u201eabschaltet\u201c oder stoppt, der dich verachtet, ist falsch! Solche Gebete werden selten von Gott erh\u00f6rt.<\/p>\n<p><strong>Daher gilt beim Beten Folgendes:<\/strong><\/p>\n<p><strong>1.) Habe ein gutes Motiv<\/strong><br \/>\nEin gutes Motiv bedeutet, einen guten Zweck beim Beten zu haben. Wenn du z.B. Gott um Erfolg auf deinem geistlichen Weg oder in deinem Leben bittest, muss deine Einstellung im Gebet rein sein. Dass du von den Schwierigkeiten befreit wirst, die du erlebst, und dass du das bekommst, was du brauchst, um anderen zu helfen. Nicht mit der Absicht, andere zu sch\u00e4digen. Wenn dein Motiv materiellen Besitz oder Geld ist, um anderen zu imponieren, werden deine Gebete wahrscheinlich nicht erh\u00f6rt.<\/p>\n<p><strong>2.) Bitte um deine Bed\u00fcrfnisse, nicht um Geld!<\/strong><br \/>\nViele von uns beten um egoistische W\u00fcnsche. Wir bitten Gott um Geld, weil wir denken, alles drehe sich ums Geld. Wir glauben, ein gutes Leben sei nur mit Geld m\u00f6glich. Doch das ist falsch. Wir vergessen oft die wichtigsten Dinge: die Grundbed\u00fcrfnisse wie Nahrung, Unterkunft, Kleidung, Gesundheit usw. Diese kann Gott uns geben. Gott kann uns erhalten, auch ohne dass Geld vorhanden ist.<\/p>\n<p>Wenn du Nahrung brauchst, bete. Bitte Gott nicht um Geld, um Nahrung zu kaufen, sondern bitte Ihn um das Essen selbst. Er wird dir das Essen auf Seine Weise bringen. Er k\u00f6nnte dir eine M\u00f6glichkeit er\u00f6ffnen, Geld zu bekommen, oder Hilfe durch einen anderen Menschen senden. Unser himmlischer Vater hat viele Wege, uns zu versorgen, selbst wenn kein Geld vorhanden ist.<\/p>\n<p>Ebenso, wenn du Kleidung, Unterkunft, ein Gesch\u00e4ft oder Gesundheit brauchst, bitte den Vater, sie bereitzustellen. Bitte Ihn nicht sofort um Geld, um Kleidung zu kaufen, ein Haus zu bauen oder ein Gesch\u00e4ft zu starten. Nenne einfach dein Bed\u00fcrfnis, und Gott wird es erf\u00fcllen. Er k\u00f6nnte dir Geldwege er\u00f6ffnen oder Hilfe durch einen Mitmenschen senden. Vielleicht hat Gott einen Platz f\u00fcr dich vorgesehen, um zu arbeiten, ohne dass Geld n\u00f6tig ist. Bitte also Gott, dir ein Gesch\u00e4ft zu er\u00f6ffnen, statt sofort um Geld zu bitten.<\/p>\n<p>Wenn du ein Werkzeug oder ein Transportmittel brauchst, sage Gott, was du brauchst. Bitte Ihn nicht um Geld, um es zu kaufen. Bitte Ihn, dir das Werkzeug, das Motorrad, die Maschine, das Auto usw. zu geben. Er wird liefern, wie Er es f\u00fcr richtig h\u00e4lt. Ebenso, wenn du reisen willst, bitte nicht um Geld f\u00fcr die Fahrt. Bitte Gott, dich an den gew\u00fcnschten Ort zu bringen. Er wei\u00df, wie Er dich dorthin bringt, sei es durch jemanden, der dich kostenlos begleitet, oder auf andere Weise, die Er kennt.<\/p>\n<p>Wenn du krank wirst, bitte nicht um Geld f\u00fcr Medikamente. Bitte um Heilung. Gott wei\u00df, wie Er deinen Schmerz oder die Krankheit beseitigt und deine Gesundheit wiederherstellt. Wende diese Regel auf alle Bereiche deines Lebens an. Vermeide es, \u201eGeld\u201c in der Gegenwart Gottes zu erw\u00e4hnen! Bitte einfach im Glauben um das, was du brauchst, nicht um Geld.<\/p>\n<blockquote><p><strong>Warum bleiben die meisten Geld-zentrierten Gebete unerh\u00f6rt?<\/strong><br \/>\nWeil der Geist des Geldes Menschen zu weltlichen Begierden f\u00fchrt, und viele daher vom Glauben abfallen, wie es in 1. Timotheus 6,10 steht:<br \/>\n\u201eDenn die Liebe zum Geld ist eine Wurzel alles \u00dcbels; nach ihr hat einige getrachtet, und sie sind vom Glauben abgeirrt und haben sich selbst viele Schmerzen verursacht.\u201c<\/p><\/blockquote>\n<p>Geld ist eine Falle, die Menschen in Versuchung f\u00fchrt. Deshalb sind viele Reiche arrogant. Doch diejenigen, die durch Gottes Segen reich werden, sind dem\u00fctig, freundlich und gro\u00dfz\u00fcgig. Zum Beispiel: Wer ein Fahrrad selbst kauft, ist oft stolzer als der, dem ein Fahrrad geschenkt wird. Wer ein Haus selbst baut, wird eher stolz sein als der, dem ein Haus geschenkt wird. Gottes Wille f\u00fcr uns Christen ist jedoch ein stilles Leben voller Demut und Freundlichkeit, nicht Stolz. Gott gibt uns nie Dinge, die uns arrogant machen w\u00fcrden.<\/p>\n<p>Ein sehr kleiner Prozentsatz der Reichen hat seinen Reichtum als Segen Gottes erhalten. Gott hat ihnen Geld anvertraut, weil Er wei\u00df, dass sie nie arrogant werden oder das, was Er ihnen gegeben hat, misshandeln werden, egal wie reich sie werden. Viele von uns erhalten nicht den Geldsegen, den sie wollen, weil Gott unsere Motive kennt. Wenn du einen reichen Menschen siehst, der arrogant ist, wei\u00dft du: Sein Reichtum stammt nicht von Gott.<\/p>\n<p>Die Bibel lehrt Christen, weder Geld zu lieben noch ihr Vertrauen darauf zu setzen. Wir sollen uns auf Gott verlassen, unseren Versorger (Jehova Jireh). Ob Geld vorhanden ist oder nicht, wir werden leben, essen, bekleidet sein und besitzen, was wir brauchen. Als Wiedergeborene k\u00f6nnen wir auch ohne Geld ein gutes Leben f\u00fchren, besser als viele, die materiellen Besitz haben.<\/p>\n<blockquote><p><strong>Prediger 5,10 (LUT):<\/strong><br \/>\n\u201eWer Geld liebt, wird nicht satt; wer Reichtum liebt, hat nicht genug. Auch dies ist eitel.\u201c<\/p><\/blockquote>\n<p>M\u00f6ge der Herr uns helfen.<\/p>\n<p><strong>Maranatha!<\/strong><\/p>\n<p>Bitte teile diese gute Botschaft mit anderen.<\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='DAS GESETZ DES FRAGENS UND EMPFANGENS' data-link='https:\/\/wingulamashahidi.org\/de\/2023\/08\/30\/das-gesetz-des-fragens-und-empfangens\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Gepriesen sei der Name unseres Herrn und Erl\u00f6sers Jesus Christus. Willkommen zu unserem heutigen Bibelstudium; Gottes Wort, das \u201eeine Leuchte f\u00fcr unser<\/p>\n","protected":false},"author":1216,"featured_media":64137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-64136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2023\/08\/prayer-silhouette-man-praying-hands-religion-png-favpng-x00zbeQah7bzwFY2MBs6Y9HWj.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2023\/08\/prayer-silhouette-man-praying-hands-religion-png-favpng-x00zbeQah7bzwFY2MBs6Y9HWj.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"qjoJtxOW86\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2023\/08\/30\/das-gesetz-des-fragens-und-empfangens\/\">DAS GESETZ DES FRAGENS UND EMPFANGENS<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2023\/08\/30\/das-gesetz-des-fragens-und-empfangens\/embed\/#?secret=qjoJtxOW86\" width=\"500\" height=\"350\" title=\"&#8222;DAS GESETZ DES FRAGENS UND EMPFANGENS&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"qjoJtxOW86\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1216"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=64136"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64136\/revisions"}],"predecessor-version":[{"id":64138,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64136\/revisions\/64138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/64137"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=64136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=64136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=64136"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=64136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}