{"id":64635,"date":"2021-07-19T12:01:10","date_gmt":"2021-07-19T09:01:10","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=64635"},"modified":"2025-12-19T11:59:52","modified_gmt":"2025-12-19T08:59:52","slug":"am-tag-meiner-angst-werde-ich-auf-dich-vertrauen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2021\/07\/19\/am-tag-meiner-angst-werde-ich-auf-dich-vertrauen\/","title":{"rendered":"\u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<hr \/>\n<p><strong>\u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c<\/strong><\/p>\n<p>David sagte:<\/p>\n<blockquote>\n<p><strong>Psalm 56,3-4 (LUT)<\/strong><br \/>\u201eWenn ich mich f\u00fcrchte, setze ich mein Vertrauen auf dich. Auf Gott, dessen Wort ich lobe, vertraue ich; auf Gott vertraue ich, ich f\u00fcrchte mich nicht. Was k\u00f6nnen Menschen mir tun?\u201c<\/p>\n<\/blockquote>\n<p>Dieser Psalm zeigt auf eindr\u00fcckliche Weise, wie tiefes Vertrauen in Gott die einzige wirksame Antwort auf Angst ist. Selbst in lebensbedrohlichen Situationen w\u00e4hlt David den Glauben \u00fcber die Furcht. Er erinnert uns daran, dass unser Halt nicht in menschlicher Macht liegt, sondern in Gottes Treue und seinen Verhei\u00dfungen.<\/p>\n<h3>Die Realit\u00e4t der Angst im Leben eines Christen<\/h3>\n<p>Solange wir auf dieser Erde leben, werden wir Pr\u00fcfungen und Angstmomente erleben \u2013 ganz gleich, wie geistlich reif oder \u201evollkommen\u201c wir sind. Die Bibel macht deutlich, dass selbst die Frommsten Zeiten des Leidens erfahren (Johannes 16,33; 2. Timotheus 3,12). Diese \u201eTage der Angst\u201c pr\u00fcfen unseren Glauben und machen deutlich, wie notwendig ein best\u00e4ndiges Vertrauen in Gott ist.<\/p>\n<p>David beschreibt sie treffend als \u201edie Tage meiner Angst\u201c \u2013 Momente gro\u00dfer geistlicher und emotionaler Belastung.<\/p>\n<h3>Verschiedene Formen von \u201eTagen der Angst\u201c<\/h3>\n<p><strong>Trauer<\/strong><br \/>Der pl\u00f6tzliche Verlust geliebter Menschen ersch\u00fcttert selbst den st\u00e4rksten Glauben. Hiob ist das klassische Beispiel (Hiob 1,13-19): Er verlor alle seine Kinder in einer einzigen Katastrophe und blieb dennoch Gott treu.<\/p>\n<p><strong>Verfolgung und Gefahr<\/strong><br \/>David selbst wurde von K\u00f6nig Saul unabl\u00e4ssig verfolgt \u2013 ein Bild f\u00fcr die Pr\u00fcfungen von Gl\u00e4ubigen unter Verfolgung. In der Bibel finden wir immer wieder Beispiele f\u00fcr Menschen, die \u201eauf der Flucht\u201c f\u00fcr ihren Glauben leben mussten (Hebr\u00e4er 11,37-38).<\/p>\n<p><strong>Schwere Krankheit<\/strong><br \/>Pl\u00f6tzliche, schw\u00e4chende Krankheiten k\u00f6nnen Hoffnungslosigkeit hervorrufen. Epaphroditus\u2019 Beinahe-Tod w\u00e4hrend seines Dienstes f\u00fcr das Evangelium (Philipper 2,25-27) zeigt, dass auch treue Diener Gottes ernsthafte Pr\u00fcfungen erleben.<\/p>\n<p><strong>Verrat<\/strong><br \/>Verrat durch enge Vertraute kann tiefe Wunden schlagen \u2013 wie Jesus es durch Judas erfahren hat (Matth\u00e4us 26,14-16). Solcher Verrat stellt unser Vertrauen auf die Probe.<\/p>\n<p><strong>Verlust von Besitz<\/strong><br \/>Wie Hiob erleben wir Angst, wenn wir materiellen Wohlstand und Sicherheit verlieren. Doch die Bibel ermutigt uns, auch in solchen Situationen Gott treu zu bleiben (Hiob 1,21).<\/p>\n<h3>Wie wir auf den Tag der Angst reagieren k\u00f6nnen<\/h3>\n<p>Wenn du dich in einer solchen Situation befindest, verzweifle nicht und wende dich nicht von Gott ab. Folge Davids Beispiel: \u201eWenn ich mich f\u00fcrchte, werde ich auf dich vertrauen.\u201c Dieses Vertrauen ist ein Akt des Glaubens, der Gottes Herrschaft und F\u00fcrsorge anerkennt, selbst in scheinbar ausweglosen Umst\u00e4nden.<\/p>\n<p>Hiob zeigt uns ein starkes Vorbild: Obwohl seine Frau ihn aufforderte, Gott zu verfluchen und zu sterben, blieb er standhaft (Hiob 2,9-10). Seine Haltung ist ein Zeugnis von Ausdauer und Hoffnung.<\/p>\n<hr \/>\n<h3>Trost und Hoffnung aus der Bibel<\/h3>\n<blockquote>\n<p><strong>Jeremia 29,11<\/strong><br \/>\u201eDenn ich wei\u00df wohl, was ich f\u00fcr Gedanken \u00fcber euch habe, spricht der HERR: Gedanken des Friedens und nicht des Leides, dass ich euch gebe Zukunft und Hoffnung.\u201c<\/p>\n<\/blockquote>\n<p>Dieses Versprechen erinnert uns daran, dass Gottes Pl\u00e4ne letztlich zu unserem Guten sind, auch wenn wir den Weg noch nicht sehen.<\/p>\n<blockquote>\n<p><strong>Jakobus 5,11<\/strong><br \/>\u201eSeht, wir halten f\u00fcr selig, die standhaft geblieben sind. Ihr habt von der Standhaftigkeit Hiobs geh\u00f6rt und den Zweck des Herrn gesehen, wie der Herr barmherzig und gn\u00e4dig ist.\u201c<\/p>\n<\/blockquote>\n<p>Gottes Barmherzigkeit tr\u00e4gt die, die in Pr\u00fcfungen standhaft bleiben.<\/p>\n<h3>Der Gott, der wiederherstellt<\/h3>\n<p>Hiob erlebte, wie Gott ihm das Doppelte dessen zur\u00fcckgab, was er verloren hatte, und segnete ihn mit einer neuen Familie (Hiob 42,10-17). Die Hoffnung auf Auferstehung zeigt uns die endg\u00fcltige Wiederherstellung.<\/p>\n<p>David hingegen, obwohl von Saul verfolgt, verlor nie sein Vertrauen in Gott. Letztlich bewahrte und erhob Gott ihn (1. Samuel 24; 2. Samuel 7).<\/p>\n<p>Aus diesen Passagen lernen wir:<\/p>\n<p><strong>Gottes Souver\u00e4nit\u00e4t:<\/strong> Er hat die Kontrolle, selbst wenn alles chaotisch erscheint.<\/p>\n<p><strong>Glaube statt Angst:<\/strong> Vertrauen in Gott ist eine geistliche Disziplin und Ausdruck seiner Gnade.<\/p>\n<p><strong>Gottes Mitgef\u00fchl und Wiederherstellung:<\/strong> Leid ist vor\u00fcbergehend; Gottes Barmherzigkeit bleibt ewig.<\/p>\n<p><strong>Hoffnung auf Auferstehung:<\/strong> Unsere endg\u00fcltige Heilung und Wiedervereinigung finden wir in Christus.<\/p>\n<blockquote>\n<p><strong>Jesaja 53,4<\/strong> best\u00e4tigt dies:<br \/>\u201eGewiss, er hat unsere Leiden getragen und unsere Schmerzen auf sich genommen \u2026\u201c<\/p>\n<\/blockquote>\n<p>Jesus trug unsere \u00c4ngste und Sorgen, damit wir Frieden haben k\u00f6nnen.<\/p>\n<p>M\u00f6ge der Herr dich segnen und deinen Glauben in den Tagen deiner Angst st\u00e4rken.<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c' data-link='https:\/\/wingulamashahidi.org\/de\/2021\/07\/19\/am-tag-meiner-angst-werde-ich-auf-dich-vertrauen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c David sagte: Psalm 56,3-4 (LUT)\u201eWenn ich mich f\u00fcrchte, setze ich mein Vertrauen auf dich. Auf <\/p>\n","protected":false},"author":1204,"featured_media":64636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-64635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/07\/88a62bdec09dc25f9893fcd07d587fbd.png","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2021\/07\/88a62bdec09dc25f9893fcd07d587fbd.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"8VY5A02hE0\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2021\/07\/19\/am-tag-meiner-angst-werde-ich-auf-dich-vertrauen\/\">\u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2021\/07\/19\/am-tag-meiner-angst-werde-ich-auf-dich-vertrauen\/embed\/#?secret=8VY5A02hE0\" width=\"500\" height=\"350\" title=\"&#8222;\u201eAm Tag meiner Angst werde ich auf dich vertrauen\u201c&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"8VY5A02hE0\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1204"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=64635"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64635\/revisions"}],"predecessor-version":[{"id":64637,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/64635\/revisions\/64637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/64636"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=64635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=64635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=64635"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=64635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}