{"id":65421,"date":"2019-09-02T13:15:56","date_gmt":"2019-09-02T10:15:56","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=65421"},"modified":"2025-12-29T19:31:07","modified_gmt":"2025-12-29T16:31:07","slug":"bevorzugt-gott-maenner-gegenueber-frauen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/","title":{"rendered":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<hr \/>\n<p><strong>Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?<\/strong><\/p>\n<p><strong>Antwort:<\/strong> Diese Frage wird oft gestellt, besonders beim Lesen von Versen wie:<\/p>\n<blockquote>\n<p><strong>1. Timotheus 2,13 (LUT):<\/strong><br \/>\u201eDenn Adam wurde zuerst gebildet, danach Eva.\u201c<\/p>\n<\/blockquote>\n<p>Dieser Vers wird h\u00e4ufig so verstanden, dass Adam gegen\u00fcber Eva Priorit\u00e4t habe. Es ist jedoch entscheidend zu erkennen, dass Gott ein Gott von Ordnung und Zweck ist. W\u00e4ren alle Menschen identisch geschaffen, w\u00fcrden sie gleichzeitig existieren und in allen Bereichen dieselbe Autorit\u00e4t haben, w\u00e4re das Leben ohne Struktur und Sinn. Die von Gott festgelegten Rollen und Ordnungen bedeuten nicht, dass der eine dem anderen \u00fcberlegen ist, sondern spiegeln Sein g\u00f6ttliches Design und Sein Ziel wider.<\/p>\n<p>Theologische Gelehrte betonen, dass Gottes Ordnung Teil Seines Sch\u00f6pfungsplans ist, der Harmonie und nicht eine Hierarchie aufgrund von Wert darstellt. Zum Beispiel wurden Tiere und Pflanzen vor Adam erschaffen (1. Mose 1). Bedeutet das, dass Tiere Vorrang vor Menschen haben? Offensichtlich nicht. Die Reihenfolge bezieht sich auf Gottes spezifischen Sch\u00f6pfungsplan und die vorgesehenen Rollen, nicht auf den Wert.<\/p>\n<p>Der Apostel Paulus spricht die Verwirrung an, die entsteht, wenn Geschlechterrollen verschwimmen, besonders in Bezug auf Leiterschaft in der Kirche und im Familienleben. Er fragt die Gl\u00e4ubigen: <strong>\u201eLehrt euch die Natur selbst nicht?\u201c<\/strong> (1. Korinther 11,14), und deutet damit an, dass die nat\u00fcrlichen Unterschiede zwischen M\u00e4nnern und Frauen Gottes geplante Ordnung offenbaren.<\/p>\n<p>Betrachten wir die einzigartige Rolle der Frau in der Geburt und F\u00fcrsorge von Kindern. Egal, wie hingebungsvoll ein Vater ist, er kann ein Kind nicht im Mutterleib tragen oder ern\u00e4hren. Diese lebensspendende Aufgabe ist einzigartig f\u00fcr Frauen (1. Mose 3,16). Das theologische Konzept des Komplementarismus erkennt an, dass M\u00e4nner und Frauen im Wert gleich sind, aber unterschiedliche Rollen, Gaben und Verantwortlichkeiten haben.<\/p>\n<p>\u00c4hnlich sind M\u00e4nner typischerweise f\u00fcr physische Aufgaben wie Schutz und Versorgung ausgestattet (1. Korinther 11,3). Viele Aufgaben k\u00f6nnen zwar geteilt werden, aber auf eine strikte 50\/50-Aufteilung in allen Rollen zu bestehen, ignoriert Gottes Plan und f\u00fchrt zu Verwirrung.<\/p>\n<p>In der Schrift gibt Paulus klare Anweisungen zur Leiterschaft in der Kirche:<\/p>\n<blockquote>\n<p><strong>1. Korinther 14,34 (LUT):<\/strong><br \/>\u201eDie Frauen sollen in den Gemeinden schweigen. Es ist ihnen nicht gestattet zu reden, sondern sie sollen sich unterordnen, wie auch das Gesetz sagt.\u201c<\/p>\n<\/blockquote>\n<p>\u00a0<\/p>\n<blockquote>\n<p><strong>1. Timotheus 2,12 (LUT):<\/strong><br \/>\u201eEiner Frau erlaube ich nicht zu lehren oder \u00fcber einen Mann zu herrschen, sondern sie soll still sein.\u201c<\/p>\n<\/blockquote>\n<p>Diese Verse werden oft im theologischen Rahmen verstanden, dass Frauen unterschiedliche Rollen in der Kirche haben, besonders in Bezug auf Lehre und Autorit\u00e4t \u00fcber M\u00e4nner. Manche sehen diese Passagen als kulturell bedingt, w\u00e4hrend andere, vor allem in evangelikalen und konservativen Traditionen, sie als zeitlose Prinzipien ansehen, die in Gottes Sch\u00f6pfungsordnung verwurzelt sind.<\/p>\n<p>Einige Frauen, die sich durch diese Anweisungen benachteiligt f\u00fchlen, entscheiden sich, auf eine Weise zu lehren oder zu f\u00fchren, die der Schrift widerspricht, in der irrt\u00fcmlichen Annahme, sie w\u00fcrden die Kirche aufbauen. Doch die Schrift warnt davor, Gottes Ordnung zu missachten:<\/p>\n<blockquote>\n<p><strong>1. Korinther 14,37-38 (LUT):<\/strong><br \/>\u201eWenn jemand meint, ein Prophet oder geistlich zu sein, so erkenne er an, dass das, was ich euch schreibe, des Herrn Gebot ist. Wer dies aber nicht erkennt, ist nicht anerkannt.\u201c<\/p>\n<\/blockquote>\n<p>Dies unterstreicht die Bedeutung, sich dem offenbarten Willen Gottes in der Schrift zu unterwerfen und nicht den menschlichen Vorlieben zu folgen.<\/p>\n<p><strong>Fazit:<\/strong> Die Bibel lehrt keine m\u00e4nnliche Dominanz, sondern von Gott eingesetzte Ordnung (1. Korinther 11,3). M\u00e4nner und Frauen sind gleichwertig in W\u00fcrde und Wert, geschaffen nach dem Bilde Gottes (1. Mose 1,27), aber sie erf\u00fcllen unterschiedliche Rollen gem\u00e4\u00df Gottes souver\u00e4nem Plan.<\/p>\n<p><strong>Segensw\u00fcnsche.<\/strong><\/p>\n<p>\u00a0<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?' data-link='https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? Antwort: Diese Frage wird oft gestellt, besonders beim Lesen von Versen wie: 1. Timotheus 2,13 (LUT):\u201eDenn A<\/p>\n","protected":false},"author":1204,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-65421","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"episode_featured_image":false,"episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"IUjsfWMhJV\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/\">Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/embed\/#?secret=IUjsfWMhJV\" width=\"500\" height=\"350\" title=\"&#8222;Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"IUjsfWMhJV\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? Antwort: Diese Frage wird oft gestellt, besonders beim Lesen von Versen wie: 1. Timotheus 2,13 (LUT):\u201eDenn A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-02T10:15:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T16:31:07+00:00\" \/>\n<meta name=\"author\" content=\"Dorcas Kulwa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dorcas Kulwa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/\"},\"author\":{\"name\":\"Dorcas Kulwa\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/9ddc4906c165be766d4f357c2d4493a6\"},\"headline\":\"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?\",\"datePublished\":\"2019-09-02T10:15:56+00:00\",\"dateModified\":\"2025-12-29T16:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/\"},\"wordCount\":591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/\",\"name\":\"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"datePublished\":\"2019-09-02T10:15:56+00:00\",\"dateModified\":\"2025-12-29T16:31:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/09\\\/02\\\/bevorzugt-gott-maenner-gegenueber-frauen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/9ddc4906c165be766d4f357c2d4493a6\",\"name\":\"Dorcas Kulwa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g\",\"caption\":\"Dorcas Kulwa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/","og_locale":"de_DE","og_type":"article","og_title":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title","og_description":"\u00a0 Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? Antwort: Diese Frage wird oft gestellt, besonders beim Lesen von Versen wie: 1. Timotheus 2,13 (LUT):\u201eDenn A","og_url":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2019-09-02T10:15:56+00:00","article_modified_time":"2025-12-29T16:31:07+00:00","author":"Dorcas Kulwa","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Dorcas Kulwa","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/"},"author":{"name":"Dorcas Kulwa","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/9ddc4906c165be766d4f357c2d4493a6"},"headline":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?","datePublished":"2019-09-02T10:15:56+00:00","dateModified":"2025-12-29T16:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/"},"wordCount":591,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/","url":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/","name":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen? &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"datePublished":"2019-09-02T10:15:56+00:00","dateModified":"2025-12-29T16:31:07+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/09\/02\/bevorzugt-gott-maenner-gegenueber-frauen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"Bevorzugt Gott M\u00e4nner gegen\u00fcber Frauen?"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/9ddc4906c165be766d4f357c2d4493a6","name":"Dorcas Kulwa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7be44bbf42d15fb02bc186267c53ff7e69a7a29b45e43d13fecc775d5727ccb5?s=96&d=mm&r=g","caption":"Dorcas Kulwa"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/65421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1204"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=65421"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/65421\/revisions"}],"predecessor-version":[{"id":65422,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/65421\/revisions\/65422"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=65421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=65421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=65421"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=65421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}