{"id":68768,"date":"2019-12-15T02:17:37","date_gmt":"2019-12-14T23:17:37","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=68768"},"modified":"2026-03-23T16:37:52","modified_gmt":"2026-03-23T13:37:52","slug":"welche-folgen-hat-es-das-evangelium-nicht-zu-predigen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/","title":{"rendered":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?"},"content":{"rendered":"<h1>\u00a0<\/h1>\n<p>Schalom. Der Name unseres Herrn Jesus Christus sei gepriesen.<br \/>Sei willkommen, Diener Gottes\u2014lasst uns gemeinsam die Bibel studieren. Heute werden wir einige wichtige Dinge \u00fcber unsere Verantwortung lernen, das Evangelium zu verk\u00fcnden.<\/p>\n<p>Das Wort <em>Evangelium<\/em> bedeutet \u201eGute Nachricht\u201c. Jede gute Botschaft, die du jemandem \u00fcberbringst, kann als gute Nachricht bezeichnet werden. Es gibt viele Arten von \u201eEvangelien\u201c in der Welt, aber es gibt nur ein Evangelium der Erl\u00f6sung, das auch \u201eEvangelium des Kreuzes\u201c genannt wird.<\/p>\n<p>Das Evangelium des Kreuzes handelt von Jesus Christus, dem Sohn Gottes, der gesandt wurde, um die S\u00fcnde der Welt hinwegzunehmen. Es betrifft die Erl\u00f6sung der Menschheit, die in der S\u00fcnde verloren war. Und denke daran\u2014die ganze Menschheit war in der S\u00fcnde verloren; deshalb betrifft dieses Evangelium jeden von uns.<\/p>\n<p>Nachdem der Herr Jesus gegangen war, wurde es notwendig, dass das Evangelium in der ganzen Welt und allen Gesch\u00f6pfen gepredigt wird. Jeder Mensch muss dieses Evangelium der Erl\u00f6sung h\u00f6ren und aus freiem Willen zwischen LEBEN und TOD w\u00e4hlen. Aus diesem Grund befahl der Herr seinen Aposteln:<\/p>\n<h3>Markus 13,9\u201310<\/h3>\n<blockquote>\n<p>\u201eIhr aber seht auf euch selbst! Denn sie werden euch den Gerichten \u00fcberantworten, und in den Synagogen werdet ihr geschlagen werden; und ihr werdet um meinetwillen vor Statthalter und K\u00f6nige gestellt werden, ihnen zum Zeugnis. Und allen V\u00f6lkern muss zuvor das Evangelium verk\u00fcndigt werden.\u201c<\/p>\n<\/blockquote>\n<p>Er sagt, es muss gepredigt werden! Das bedeutet, es ist eine Pflicht. Das Evangelium muss \u00fcberallhin gelangen\u2014im Leben oder im Tod. Selbst wenn es das Leben kostet, muss es die Menschen erreichen.<\/p>\n<p>Dies ist die Verantwortung aller, die Christus empfangen haben. Wir m\u00fcssen das Evangelium predigen. Gott benutzt immer Menschen, um das Evangelium zu verk\u00fcnden. Er hat den Menschen erw\u00e4hlt, f\u00fcr Ihn zu stehen und Ihn zu vertreten. Er benutzt weder Tiere noch Engel noch irgendein anderes Gesch\u00f6pf\u2014Er hat den Menschen erw\u00e4hlt!<\/p>\n<hr \/>\n<h2>Die Gefahr, das Evangelium nicht zu predigen<\/h2>\n<p>Es gibt eine gro\u00dfe Gefahr darin, das Evangelium nicht zu predigen. Es ist ein ernstes Risiko, die Gabe, die Gott dir gegeben hat, nicht zu nutzen, um anderen zu predigen.<\/p>\n<p>Der Herr hat dich gerettet, damit du auch anderen hilfst. Er hat uns nicht nur zu unserer eigenen Freude gerettet. Die meisten von uns haben Jesus nicht durch ein pers\u00f6nliches Erscheinen empfangen. Wir haben das Evangelium irgendwo durch einen Diener Gottes geh\u00f6rt\u2014und durch diese Predigt wurden wir gerettet.<\/p>\n<p>Deshalb ist es ein Fehler f\u00fcr jeden, der sich Christ nennt, das Evangelium nicht zu predigen.<\/p>\n<hr \/>\n<h2>Das Evangelium ist ansteckend<\/h2>\n<p>Dies ist Gottes Ordnung\u2014wir m\u00fcssen es von jemandem h\u00f6ren. Und genauso m\u00fcssen wir es anderen predigen, die es von uns h\u00f6ren werden. Es ist wie eine Kette: Einer bringt den anderen im Glauben hervor, und dieser wieder einen anderen, und so weiter.<\/p>\n<p>Aber wenn du gerettet bist und dich weigerst, \u201eandere hervorzubringen\u201c, besteht eine gro\u00dfe Gefahr.<\/p>\n<p>Kehren wir zur Bibel zur\u00fcck und lesen wir \u00fcber den Propheten Hesekiel. Er war ein wahrer Prophet Gottes und geh\u00f6rte zu den Gefangenen, die nach Babylon gef\u00fchrt wurden. Dort erschien ihm Gott in einer Vision\u2014auf seinem Thron sitzend, umgeben von Seraphim und Cherubim. Er h\u00f6rte die Stimme Gottes selbst.<\/p>\n<p>Gott sandte ihn, um den Kindern Israels von ihren S\u00fcnden, ihrer Rebellion und den Folgen ihrer Unbu\u00dffertigkeit zu berichten.<\/p>\n<p>Doch nachdem er die Vision empfangen hatte, schwieg er. Nicht weil er Gott verachtete\u2014nein! Er f\u00fcrchtete sich zu sprechen. Sein Herz war betr\u00fcbt und voller Zorn wegen des B\u00f6sen seines Volkes, aber er z\u00f6gerte sieben Tage lang zu reden.<\/p>\n<p>Nach sieben Tagen kam das Wort des Herrn erneut zu ihm und warnte ihn ernsthaft, weil er die Botschaft nicht weitergegeben hatte.<\/p>\n<h3>Hesekiel 3,15\u201319<\/h3>\n<blockquote>\n<p>\u201eDa kam ich zu den Weggef\u00fchrten nach Tel-Abib, die am Fluss Kebar wohnten, und ich setzte mich dorthin, wo sie sa\u00dfen, und blieb sieben Tage lang bet\u00e4ubt unter ihnen. Und nach sieben Tagen geschah das Wort des Herrn zu mir: Du Menschenkind, ich habe dich zum W\u00e4chter f\u00fcr das Haus Israel gesetzt; darum sollst du das Wort aus meinem Mund h\u00f6ren und sie von mir warnen. Wenn ich zu dem Gottlosen sage: Du musst sterben! und du warnst ihn nicht \u2026 so wird der Gottlose in seiner Schuld sterben; aber sein Blut werde ich von deiner Hand fordern. Wenn du aber den Gottlosen warnst \u2026 so wird er in seiner Schuld sterben; du aber hast deine Seele gerettet.\u201c<\/p>\n<\/blockquote>\n<p>Siehst du das?<\/p>\n<p>Als Hesekiel h\u00f6rte, dass das Blut des S\u00fcnders von seiner Hand gefordert w\u00fcrde, wenn er ihn nicht warnte, verstand er, dass es keinen Raum f\u00fcr Verz\u00f6gerung gab. Von da an \u00fcberbrachte er alles treu, was ihm gezeigt wurde.<\/p>\n<p>Er wusste, dass er zur Rechenschaft gezogen werden w\u00fcrde.<\/p>\n<hr \/>\n<h2>Eine pers\u00f6nliche Warnung<\/h2>\n<p>Bruder, wenn der Herr dir Visionen zeigt, um Menschen vor ihren S\u00fcnden zu warnen, und du es ihnen nicht sagst\u2014lerne von Hesekiel. Wenn du das Wort kennst und es nicht weitergibst, besteht Gefahr.<\/p>\n<p>Es ist besser, sie zu warnen und sie selbst entscheiden zu lassen, als zu schweigen. Wenn jemand in seiner S\u00fcnde stirbt, ohne gewarnt worden zu sein\u2014wie wirst du bestehen?<\/p>\n<p>Wenn du wei\u00dft, dass Ehebrecher und Unz\u00fcchtige in die H\u00f6lle kommen werden, wenn sie nicht umkehren\u2014und du selbst nicht in dieser S\u00fcnde lebst\u2014warum warnst du sie nicht? Sage es ihnen, damit sie gerettet werden. Sie zu ver\u00e4ndern ist nicht deine Aufgabe. Deine Aufgabe ist es, zu predigen.<\/p>\n<p>Aber wenn du selbst in derselben S\u00fcnde lebst, dann predige nicht\u2014du brauchst zuerst Rettung. Ein Blinder kann keinen Blinden f\u00fchren. So sagt es die Bibel.<\/p>\n<hr \/>\n<h2>Handle heute<\/h2>\n<p>Wenn du fr\u00fcher gepredigt hast\u2014beginne heute wieder.<br \/>Wenn du Angst hattest, \u00fcber die letzten Tage zu sprechen\u2014fang jetzt an.<\/p>\n<p>Hesekiel f\u00fcrchtete sich mehr als du, aber als er h\u00f6rte, dass ihr Blut von seiner Hand gefordert w\u00fcrde, \u00e4nderte er sich sofort. Tue dasselbe. Der Herr wird dir helfen.<\/p>\n<p>Es gibt gro\u00dfe Gefahr darin, das Evangelium nicht zu predigen.<\/p>\n<hr \/>\n<h2>Wenn du noch nicht gerettet bist<\/h2>\n<p>Wenn du nicht gerettet bist, tue heute Bu\u00dfe. Die T\u00fcr der Gnade ist noch offen\u2014aber sie wird nicht f\u00fcr immer offen bleiben.<\/p>\n<p>Du hast gelesen, was mit dem geschieht, der in der S\u00fcnde stirbt.<\/p>\n<blockquote>\n<p>\u201eWenn du aber den Gottlosen warnst \u2026 so wird er in seiner Schuld sterben; du aber hast deine Seele gerettet.\u201c \u2014 Hesekiel 3,19<\/p>\n<\/blockquote>\n<p>Heute hast du das Evangelium geh\u00f6rt. Wenn du dich weigerst umzukehren, wirst du in deinen S\u00fcnden sterben. Und die Folge davon ist der Feuersee.<\/p>\n<p>Wo immer du bist, bitte den Herrn um Vergebung. Tue Bu\u00dfe \u00fcber Unzucht, Trunkenheit, L\u00fcgen, Bestechung, Verleumdung, Diebstahl und beleidigende Worte. Suche die richtige Taufe, wenn du noch nicht getauft bist. Der Heilige Geist wird dich reinigen und vollkommen machen.<\/p>\n<blockquote>\n<p>\u201eDie Zeit ist erf\u00fcllt, und das Reich Gottes ist nahe. Tut Bu\u00dfe und glaubt an das Evangelium.\u201c \u2014 Markus 1,15<\/p>\n<\/blockquote>\n<p>M\u00f6ge der Herr dich segnen.<br \/>Schalom.<\/p>\n\n\n\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?' data-link='https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 Schalom. Der Name unseres Herrn Jesus Christus sei gepriesen.Sei willkommen, Diener Gottes\u2014lasst uns gemeinsam die Bibel studieren. Heute werden wir e<\/p>\n","protected":false},"author":1097,"featured_media":68016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-68768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"988mMpdNcy\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/\">WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/embed\/#?secret=988mMpdNcy\" width=\"500\" height=\"350\" title=\"&#8222;WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"988mMpdNcy\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Schalom. Der Name unseres Herrn Jesus Christus sei gepriesen.Sei willkommen, Diener Gottes\u2014lasst uns gemeinsam die Bibel studieren. Heute werden wir e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-14T23:17:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T13:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rogath Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rogath Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/\"},\"author\":{\"name\":\"Rogath Henry\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\"},\"headline\":\"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?\",\"datePublished\":\"2019-12-14T23:17:37+00:00\",\"dateModified\":\"2026-03-23T13:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/\"},\"wordCount\":1200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/78935552_729597444201983_4475698733836664832_n-1.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/\",\"name\":\"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/78935552_729597444201983_4475698733836664832_n-1.jpg\",\"datePublished\":\"2019-12-14T23:17:37+00:00\",\"dateModified\":\"2026-03-23T13:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/78935552_729597444201983_4475698733836664832_n-1.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/78935552_729597444201983_4475698733836664832_n-1.jpg\",\"width\":450,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2019\\\/12\\\/15\\\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/bffb4332e3db6c10bd3150f055a8e97d\",\"name\":\"Rogath Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g\",\"caption\":\"Rogath Henry\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/","og_locale":"de_DE","og_type":"article","og_title":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title","og_description":"\u00a0 Schalom. Der Name unseres Herrn Jesus Christus sei gepriesen.Sei willkommen, Diener Gottes\u2014lasst uns gemeinsam die Bibel studieren. Heute werden wir e","og_url":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2019-12-14T23:17:37+00:00","article_modified_time":"2026-03-23T13:37:52+00:00","og_image":[{"width":450,"height":338,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","type":"image\/jpeg"}],"author":"Rogath Henry","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Rogath Henry","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/"},"author":{"name":"Rogath Henry","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d"},"headline":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?","datePublished":"2019-12-14T23:17:37+00:00","dateModified":"2026-03-23T13:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/"},"wordCount":1200,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/","url":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/","name":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN? &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","datePublished":"2019-12-14T23:17:37+00:00","dateModified":"2026-03-23T13:37:52+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2019\/12\/78935552_729597444201983_4475698733836664832_n-1.jpg","width":450,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2019\/12\/15\/welche-folgen-hat-es-das-evangelium-nicht-zu-predigen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"WELCHE FOLGEN HAT ES, DAS EVANGELIUM NICHT ZU PREDIGEN?"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/bffb4332e3db6c10bd3150f055a8e97d","name":"Rogath Henry","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a138435f31e1aafb50aad914fdb3dfd31f54959b3b0bd49558fd329c747a65da?s=96&d=mm&r=g","caption":"Rogath Henry"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/68768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=68768"}],"version-history":[{"count":1,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/68768\/revisions"}],"predecessor-version":[{"id":68769,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/68768\/revisions\/68769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/68016"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=68768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=68768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=68768"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=68768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}