{"id":69016,"date":"2020-11-27T21:02:50","date_gmt":"2020-11-27T18:02:50","guid":{"rendered":"https:\/\/wingulamashahidi.org\/?p=69016"},"modified":"2026-03-24T20:20:24","modified_gmt":"2026-03-24T17:20:24","slug":"bibelbuecher-teil-10-das-buch-der-psalmen","status":"publish","type":"post","link":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/","title":{"rendered":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN"},"content":{"rendered":"<ul>\n<li><a href=\"https:\/\/wingulamashahidi.org\/en\/\">Startseite<\/a>\u00a0\u00a0 \/ \u00a0<a href=\"https:\/\/wingulamashahidi.org\/en\/category\/home-en\/\">Home<\/a>\u00a0\u00a0 \/<\/li>\n<li>BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN<\/li>\n<\/ul>\n<h3><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/\">BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN<\/a><\/h3>\n<p><em>Gepriesen sei der Name unseres Herrn und Retters Jesus Christus!<\/em><br \/>\nWillkommen erneut, w\u00e4hrend wir weiterhin \u00fcber die Heilige Schrift nachdenken. Wir haben bereits mehrere B\u00fccher der Bibel begonnen bei Genesis behandelt. Wenn Sie die vorherigen Teile noch nicht gelesen haben und dies nachholen m\u00f6chten, k\u00f6nnen Sie hier anfangen &gt;&gt; BIBELB\u00dcCHER: TEIL 1.<\/p>\n<p>Heute, durch die Gnade des Herrn, wenden wir uns dem n\u00e4chsten Buch in unserer Reihe zu: <strong>Das Buch der Psalmen<\/strong>.<\/p>\n<hr \/>\n<h3>1. <strong>\u00dcberblick \u00fcber die Psalmen<\/strong><\/h3>\n<p>Das Buch der Psalmen ist nicht nur das l\u00e4ngste Buch der Bibel, sondern steht auch im Zentrum der Heiligen Schrift. W\u00e4hrend K\u00f6nig David, der Sohn Isais, den Gro\u00dfteil der Psalmen verfasste, war er nicht der einzige Autor. Weitere Mitwirkende waren unter anderem Salomo, Mose, Asaf, die S\u00f6hne Korahs, Ethan, Heman und nach Tradition sogar K\u00f6nig Hiskia.<\/p>\n<p>Das Wort <em>\u201ePsalm\u201c<\/em> bedeutet w\u00f6rtlich <em>\u201eheilige Lieder, die mit Saiteninstrumenten gesungen werden\u201c<\/em>, wie Harfe, Leier oder Laute. Diese Lieder wurden nicht zum blo\u00dfen Zeitvertreib komponiert, sondern hatten einen tiefen geistlichen Zweck: <em>Anbetung, Lobpreis, Dank, Gebet und Verherrlichung des Herrn.<\/em><\/p>\n<hr \/>\n<h3>2. <strong>Die Rolle der Musik und Davids Salbung<\/strong><\/h3>\n<p>David hatte von Jugend an eine besondere Begabung im Spiel von Instrumenten, besonders der Harfe. Dieses Talent war nicht nur nat\u00fcrlich, sondern eine g\u00f6ttliche Gabe, die im geistlichen Kampf und in der Anbetung eingesetzt wurde.<\/p>\n<blockquote><p>In <strong>1. Samuel 16,14\u201323<\/strong> sehen wir, dass K\u00f6nig Saul von einem b\u00f6sen Geist geplagt wurde, und es war Davids gesalbte Musik, die ihm Erleichterung brachte. Vers 23 (Luther 2017) sagt:<br \/>\n<em>&#8222;Und sobald der Geist des HERRN \u00fcber Saul kam, nahm David die Harfe und spielte mit seiner Hand; und Saul wurde erfrischt und es geschah ihm wohl, und der b\u00f6se Geist wich von ihm.&#8220;<\/em><\/p><\/blockquote>\n<p>David setzte dieses Geschenk sein Leben lang ein und komponierte Psalmen in allen Lebenslagen \u2013 im Krieg, in Frieden, in Sieg, Verzweiflung, Bu\u00dfe und in tiefer pers\u00f6nlicher Gemeinschaft mit Gott.<\/p>\n<hr \/>\n<h3>3. <strong>Ursprung und Kontext der Psalmen<\/strong><\/h3>\n<p>Die Psalmen wurden nicht willk\u00fcrlich geschrieben. Jeder entstand aus einem realen geistlichen oder historischen Ereignis. Zum Beispiel wurde <strong>Psalm 105<\/strong> verfasst, um die Freudenfeier \u00fcber die \u00dcberf\u00fchrung der Bundeslade aus dem Haus Obed-Edoms in die Stadt Davids zu beschreiben.<\/p>\n<p>In <strong>1. Chronik 15,25\u201328<\/strong> lesen wir von dieser gro\u00dfen Prozession, erf\u00fcllt von Gesang, Tanz und Instrumentalspiel. David war so \u00fcberw\u00e4ltigt von Freude, dass er vor dem HERRN mit aller Kraft tanzte. Sp\u00e4ter, in <strong>1. Chronik 16<\/strong>, setzte David Asaf und seine Br\u00fcder als Leiter der Anbetung ein, und <strong>Verse 8\u201322<\/strong> spiegeln direkt die Inhalte von Psalm 105 wider.<\/p>\n<p>Dies zeigt, dass die Psalmen keine abstrakten Texte sind, sondern tief verwurzelt in erlebten Erfahrungen \u2013 <em>g\u00f6ttliche Begegnungen, wunderbare Befreiungen, prophetische Offenbarungen und Handeln der Treue Gottes.<\/em><\/p>\n<hr \/>\n<h3>4. <strong>Die Psalmen als Prophetie<\/strong><\/h3>\n<p>Neben Anbetung und Gebet sind die Psalmen prophetisch. Sie enthalten einige der klarsten alttestamentlichen Vorhersagen \u00fcber den Messias, Jesus Christus. Zum Beispiel:<\/p>\n<ul>\n<li><strong>Psalm 22,2<\/strong> \u2013 <em>\u201eMein Gott, mein Gott, warum hast du mich verlassen?\u201c<\/em> \u2013 Dies waren Jesu genaue Worte am Kreuz (<em>vgl. Markus 15,34<\/em>).<\/li>\n<li><strong>Psalm 41,10<\/strong> \u2013 <em>\u201eAuch mein Freund, dem ich vertraute, der mein Brot a\u00df, hat seine Ferse gegen mich erhoben.\u201c<\/em> \u2013 Dies k\u00fcndigt Judas\u2019 Verrat an (<em>vgl. Johannes 13,18<\/em>).<\/li>\n<li><strong>Psalm 22,19<\/strong> \u2013 <em>\u201eSie teilen meine Kleider unter sich und werfen das Los um mein Gewand.\u201c<\/em> \u2013 Erf\u00fcllt w\u00e4hrend der Kreuzigung (<em>vgl. Matth\u00e4us 27,35<\/em>).<\/li>\n<li><strong>Psalm 16,10<\/strong> \u2013 <em>\u201eDenn du wirst meine Seele nicht dem Totenreich \u00fcberlassen, noch zulassen, dass dein Heiliger die Verwesung sieht.\u201c<\/em> \u2013 Petrus zitiert dies in <em>Apostelgeschichte 2,27\u201331<\/em> als direkte Prophezeiung der Auferstehung Christi.<\/li>\n<\/ul>\n<blockquote><p>Jesus selbst best\u00e4tigte die prophetische Autorit\u00e4t der Psalmen. Nach seiner Auferstehung sagte er:<br \/>\n<em>&#8222;Dies sind die Worte, die ich zu euch geredet habe, als ich noch bei euch war: Es muss alles erf\u00fcllt werden, was im Gesetz Mose, in den Propheten und Psalmen \u00fcber mich geschrieben steht.&#8220;<\/em> (<em>Lukas 24,44, Luther 2017<\/em>)<\/p><\/blockquote>\n<hr \/>\n<h3>5. <strong>Themen und Lektionen aus den Psalmen<\/strong><\/h3>\n<p>Das Buch der Psalmen ist nicht nur poetisch, sondern auch tief theologisches Lehrmaterial. Es lehrt:<\/p>\n<ul>\n<li><strong>Bu\u00dfe und Vergebung<\/strong> \u2013 <em>Psalm 51<\/em> ist ein Vorbildgebet der Beichte nach S\u00fcnde und zeigt, wie man Gott in Zerknirschung und Demut begegnet.<\/li>\n<li><strong>Lobpreis und Dank<\/strong> \u2013 Die Psalmen rufen uns auf, Gott nicht nur mit Worten, sondern mit Instrumenten und Feier zu preisen (<em>Psalm 33,2\u20133; Psalm 150<\/em>).<\/li>\n<li><strong>Vertrauen auf Gott<\/strong> \u2013 Psalmen wie <em>Psalm 23<\/em> und <em>Psalm 27<\/em> vermitteln mutigen Glauben und Frieden angesichts von Gefahr und Furcht.<\/li>\n<li><strong>Intimit\u00e4t mit Gott<\/strong> \u2013 Die Psalmen geben Worte f\u00fcr die tiefe pers\u00f6nliche Beziehung zu Gott \u2013 Sehnsucht, Freude, Kummer und Genuss in Seiner Gegenwart.<\/li>\n<\/ul>\n<hr \/>\n<h3>6. <strong>Warum die Psalmen heute studieren?<\/strong><\/h3>\n<p>Die Psalmen sind zeitlos. Sie helfen Gl\u00e4ubigen, jede Emotion vor Gott auszudr\u00fccken \u2013 Trauer, Freude, Angst oder Triumph. Sie pr\u00e4gen unsere Anbetung, unser Gebet und unser Verst\u00e4ndnis von Gottes Verhei\u00dfungen. Die Psalmen lehren uns, dass Anbetung nicht nur Musik ist, sondern die Reaktion des Herzens auf Gottes Gr\u00f6\u00dfe und G\u00fcte.<\/p>\n<hr \/>\n<h3>Abschlie\u00dfende Gedanken<\/h3>\n<p>Das Buch der Psalmen nimmt einen einzigartigen Platz in der Bibel ein. Es ist sowohl alt als auch immer neu, poetisch und prophetisch, pers\u00f6nlich und universell. Es ist ein g\u00f6ttliches Geschenk f\u00fcr die Reise der Seele \u2013 von Verzweiflung zu Freude, von Furcht zu Glauben, von Trauer zu Lobpreis.<\/p>\n<p><strong>M\u00f6ge der Herr Sie reichlich segnen, w\u00e4hrend Sie \u00fcber Sein Wort in den Psalmen nachsinnen.<\/strong><br \/>\n<em>Maranatha!<\/em><\/p>\n<hr \/>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN' data-link='https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\">Print this post<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Startseite\u00a0\u00a0 \/ \u00a0Home\u00a0\u00a0 \/ BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN Gepriesen sei der Name unseres <\/p>\n","protected":false},"author":1241,"featured_media":69017,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[16908],"tags":[],"series":[],"class_list":["post-69016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"episode_featured_image":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","episode_player_image":"https:\/\/wingulamashahidi.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/wingulamashahidi.org\/de\/feed\/podcast\/wingu-la-mashahidi","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ys3R4oESBv\"><a href=\"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/\">BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/embed\/#?secret=ys3R4oESBv\" width=\"500\" height=\"350\" title=\"&#8222;BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN&#8220; &#8211; Wingu la Mashahidi\" data-secret=\"ys3R4oESBv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/wingulamashahidi.org\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title\" \/>\n<meta property=\"og:description\" content=\"Startseite\u00a0\u00a0 \/ \u00a0Home\u00a0\u00a0 \/ BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN Gepriesen sei der Name unseres\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wingu la Mashahidi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-27T18:02:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T17:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"235\" \/>\n\t<meta property=\"og:image:height\" content=\"214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salome Kalaita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:site\" content=\"@wingukuu07\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salome Kalaita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/\"},\"author\":{\"name\":\"Salome Kalaita\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/e432669ac0946df6a02875ec48f8240a\"},\"headline\":\"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN\",\"datePublished\":\"2020-11-27T18:02:50+00:00\",\"dateModified\":\"2026-03-24T17:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/\"},\"wordCount\":891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/download-25.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/\",\"name\":\"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/download-25.jpg\",\"datePublished\":\"2020-11-27T18:02:50+00:00\",\"dateModified\":\"2026-03-24T17:20:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/download-25.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/download-25.jpg\",\"width\":235,\"height\":214},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/2020\\\/11\\\/27\\\/bibelbuecher-teil-10-das-buch-der-psalmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"name\":\"Wingu la Mashahidi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#organization\",\"name\":\"Die Wolke der Zeugen\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"contentUrl\":\"https:\\\/\\\/wingulamashahidi.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/15420967_113066522521748_8712116330127403860_n.jpg\",\"width\":308,\"height\":308,\"caption\":\"Die Wolke der Zeugen\"},\"image\":{\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/Wingu-La-Mashahidi-215927442275090\\\/\",\"https:\\\/\\\/x.com\\\/wingukuu07\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wingulamashahidi.org\\\/de\\\/#\\\/schema\\\/person\\\/e432669ac0946df6a02875ec48f8240a\",\"name\":\"Salome Kalaita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g\",\"caption\":\"Salome Kalaita\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/","og_locale":"de_DE","og_type":"article","og_title":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title","og_description":"Startseite\u00a0\u00a0 \/ \u00a0Home\u00a0\u00a0 \/ BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN Gepriesen sei der Name unseres","og_url":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/","og_site_name":"Wingu la Mashahidi","article_publisher":"https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","article_published_time":"2020-11-27T18:02:50+00:00","article_modified_time":"2026-03-24T17:20:24+00:00","og_image":[{"width":235,"height":214,"url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","type":"image\/jpeg"}],"author":"Salome Kalaita","twitter_card":"summary_large_image","twitter_creator":"@wingukuu07","twitter_site":"@wingukuu07","twitter_misc":{"Verfasst von":"Salome Kalaita","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#article","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/"},"author":{"name":"Salome Kalaita","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/e432669ac0946df6a02875ec48f8240a"},"headline":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN","datePublished":"2020-11-27T18:02:50+00:00","dateModified":"2026-03-24T17:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/"},"wordCount":891,"commentCount":0,"publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/","url":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/","name":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN &#8211; Site title","isPartOf":{"@id":"https:\/\/wingulamashahidi.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#primaryimage"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#primaryimage"},"thumbnailUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","datePublished":"2020-11-27T18:02:50+00:00","dateModified":"2026-03-24T17:20:24+00:00","breadcrumb":{"@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#primaryimage","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2020\/11\/download-25.jpg","width":235,"height":214},{"@type":"BreadcrumbList","@id":"https:\/\/wingulamashahidi.org\/de\/2020\/11\/27\/bibelbuecher-teil-10-das-buch-der-psalmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wingulamashahidi.org\/de\/"},{"@type":"ListItem","position":2,"name":"BIBELB\u00dcCHER: TEIL 10 \u2013 DAS BUCH DER PSALMEN"}]},{"@type":"WebSite","@id":"https:\/\/wingulamashahidi.org\/de\/#website","url":"https:\/\/wingulamashahidi.org\/de\/","name":"Wingu la Mashahidi","description":"","publisher":{"@id":"https:\/\/wingulamashahidi.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wingulamashahidi.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wingulamashahidi.org\/de\/#organization","name":"Die Wolke der Zeugen","url":"https:\/\/wingulamashahidi.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","contentUrl":"https:\/\/wingulamashahidi.org\/wp-content\/uploads\/2018\/08\/15420967_113066522521748_8712116330127403860_n.jpg","width":308,"height":308,"caption":"Die Wolke der Zeugen"},"image":{"@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/Wingu-La-Mashahidi-215927442275090\/","https:\/\/x.com\/wingukuu07"]},{"@type":"Person","@id":"https:\/\/wingulamashahidi.org\/de\/#\/schema\/person\/e432669ac0946df6a02875ec48f8240a","name":"Salome Kalaita","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12e8a83863519f7d035074a8158b1b5a443438152ae15c81bb0cdea29955b24a?s=96&d=mm&r=g","caption":"Salome Kalaita"}}]}},"_links":{"self":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/69016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/users\/1241"}],"replies":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/comments?post=69016"}],"version-history":[{"count":2,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/69016\/revisions"}],"predecessor-version":[{"id":69019,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/posts\/69016\/revisions\/69019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media\/69017"}],"wp:attachment":[{"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/media?parent=69016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/categories?post=69016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/tags?post=69016"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/wingulamashahidi.org\/de\/wp-json\/wp\/v2\/series?post=69016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}